{"id":14334,"date":"2023-06-16T10:25:20","date_gmt":"2023-06-16T08:25:20","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=14334"},"modified":"2023-06-16T10:25:23","modified_gmt":"2023-06-16T08:25:23","slug":"gobernar-para-todos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos","title":{"rendered":"Gobernar para todos"},"content":{"rendered":"\n<p>Los cargos electos de ayuntamientos y juntas vecinales que tomar\u00e1n posesi\u00f3n de sus cargos ma\u00f1ana s\u00e1bado deben de gobernar para todos. Gobernar para todos es no poner por delante los intereses personales, que a veces los hay, y si hay que ponerlos que al menos sean leg\u00edtimos. Gobernar para todos es tratar a todos los n\u00facleos de poblaci\u00f3n, cuando como es habitual hay m\u00e1s de uno, sin discriminaci\u00f3n alguna. Y gobernar para todos es tomar decisiones con las que nadie pueda sentirse perjudicado debido a su ideolog\u00eda pol\u00edtica. Siempre hay que gobernar para todos, pero con m\u00e1s motivo cuando se trata de n\u00facleos de escasa poblaci\u00f3n, que a veces son los m\u00e1s divididos o donde m\u00e1s se notan las divisiones y los enfrentamientos.\u00a0 En estas elecciones, quiz\u00e1s m\u00e1s que en otras, se han puesto de manifiesto enfrentamientos vecinales en los que el objetivo ha estado marcado en un colectivo como es el de los agricultores y ganaderos. Con un censo cada vez m\u00e1s peque\u00f1o de gente que vive del campo, en muchos pueblos hay corrientes organizadas para quitarle las tierras a qui\u00e9n las trabaja, para quitarle los pastos a qui\u00e9n los aprovecha con sus reba\u00f1os, y todo para d\u00e1rselo al mejor postor que llegue de fuera, sin miramiento alguno. En otros casos, el destino de lo que se le quita al agricultor y ganadero de siempre es d\u00e1rselo a los fondos de inversi\u00f3n para que pongan placas fotovoltaicas, es d\u00e1rselo a qui\u00e9n m\u00e1s pague como si en la vida todo se pudiera comprar y vender, como si ya no quedase nadie en la vida p\u00fablica dispuesto a defender principios y valores por encima del dinero. Los concejales y alcaldes tendr\u00e1n motivos para considerarse importantes cuando les llamen a todas horas para elegir a los diputados provinciales, pero vivir\u00e1n la experiencia de que nadie se va a acordar ni ocupar de ellos al d\u00eda siguiente de emitir el voto, y por supuesto, a los de las juntas vecinales, ni les van a poner cara. Los partidos pol\u00edticos no prestan la atenci\u00f3n debida a quienes ejercen cargos locales con mucho sacrificio y casi siempre sin sueldo.<\/p>\n<p><em>*Art\u00edculo de opini\u00f3n de Jos\u00e9 Antonio Turrado publicado en La Nueva Cr\u00f3nica del viernes 16 de junio de 2023.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cargos electos de ayuntamientos y juntas vecinales que tomar\u00e1n posesi\u00f3n de sus cargos ma\u00f1ana s\u00e1bado deben de gobernar para todos. Gobernar para todos es no poner por delante los intereses personales, que a veces los hay, y si hay que ponerlos que al menos sean leg\u00edtimos. Gobernar para todos es tratar a todos los [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobernar para todos - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Los cargos electos de ayuntamientos y juntas vecinales que tomar\u00e1n posesi\u00f3n de sus cargos ma\u00f1ana s\u00e1bado deben de gobernar para todos. Gobernar para todos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobernar para todos - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Los cargos electos de ayuntamientos y juntas vecinales que tomar\u00e1n posesi\u00f3n de sus cargos ma\u00f1ana s\u00e1bado deben de gobernar para todos. Gobernar para todos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-16T08:25:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-16T08:25:23+00:00\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos\",\"name\":\"Gobernar para todos - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2023-06-16T08:25:20+00:00\",\"dateModified\":\"2023-06-16T08:25:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Los cargos electos de ayuntamientos y juntas vecinales que tomar\u00e1n posesi\u00f3n de sus cargos ma\u00f1ana s\u00e1bado deben de gobernar para todos. Gobernar para todos\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobernar para todos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobernar para todos - ASAJA Le\u00f3n","description":"Los cargos electos de ayuntamientos y juntas vecinales que tomar\u00e1n posesi\u00f3n de sus cargos ma\u00f1ana s\u00e1bado deben de gobernar para todos. Gobernar para todos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos","og_locale":"es_ES","og_type":"article","og_title":"Gobernar para todos - ASAJA Le\u00f3n","og_description":"Los cargos electos de ayuntamientos y juntas vecinales que tomar\u00e1n posesi\u00f3n de sus cargos ma\u00f1ana s\u00e1bado deben de gobernar para todos. Gobernar para todos","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2023-06-16T08:25:20+00:00","article_modified_time":"2023-06-16T08:25:23+00:00","author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos","name":"Gobernar para todos - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2023-06-16T08:25:20+00:00","dateModified":"2023-06-16T08:25:23+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Los cargos electos de ayuntamientos y juntas vecinales que tomar\u00e1n posesi\u00f3n de sus cargos ma\u00f1ana s\u00e1bado deben de gobernar para todos. Gobernar para todos","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/gobernar-para-todos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Gobernar para todos"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14334"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=14334"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14334\/revisions"}],"predecessor-version":[{"id":14335,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14334\/revisions\/14335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=14334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=14334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=14334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}