{"id":1435,"date":"2015-04-24T00:00:00","date_gmt":"2015-04-23T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2015\/04\/24\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales\/"},"modified":"2017-11-15T09:38:40","modified_gmt":"2017-11-15T08:38:40","slug":"el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales","title":{"rendered":"El Gobierno ha publicado la reducci&#243;n de los m&#243;dulos fiscales"},"content":{"rendered":"<h2>En el Bolet&#237;n Oficial del Estado del 24 de abril se publica una Orden del ministerio de Hacienda por la que se reduce para el periodo impositivo de 2014 los &#237;ndices de rendimiento neto aplicables en el m&#233;todo de estimaci&#243;n objetiva  del Impuesto sobre la Renta de las Personas F&#237;sicas, para las actividades agr&#237;colas y ganaderas afectadas por diversas circunstancias excepcionales.<\/h2>\n<p style=\"text-align: center;\">\n<strong>El Gobierno ha publicado la reducci&#243;n de los m&#243;dulos fiscales<\/strong><\/p>\n<p>\n<strong>E<\/strong>n el Bolet&#237;n Oficial del Estado del 24 de abril se publica una Orden del ministerio de Hacienda por la que se reduce para el periodo impositivo de 2014 los &#237;ndices de rendimiento neto aplicables en el m&#233;todo de estimaci&#243;n objetiva&#160; del Impuesto sobre la Renta de las Personas F&#237;sicas, para las actividades agr&#237;colas y ganaderas afectadas por diversas circunstancias excepcionales.<\/p>\n<p>\nRespecto a la provincia de Le&#243;n, destaca el de las patatas, que se fija en el 0,19,&#160; el del vacuno de leche que baja a 0,26 y el de las alubias que se reduce hasta el 0,18. Tambi&#233;n hay bajada con car&#225;cter general en los productos hort&#237;colas y en los servicios de integraci&#243;n de porcino y avicultura.<\/p>\n<p>\nEn los cultivos de cereales, oleaginosas y leguminosas hay reducciones en distintos municipios de la provincia.<\/p>\n<p>\n<img decoding=\"async\" alt=\"\" src=\"\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/Reduccion_mod_2015.jpg\" style=\"width: 800px; height: 600px;\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el Bolet&#237;n Oficial del Estado del 24 de abril se publica una Orden del ministerio de Hacienda por la que se reduce para el periodo impositivo de 2014 los &#237;ndices de rendimiento neto aplicables en el m&#233;todo de estimaci&#243;n objetiva  del Impuesto sobre la Renta de las Personas F&#237;sicas, para las actividades agr&#237;colas y ganaderas afectadas por diversas circunstancias excepcionales.<\/p>\n","protected":false},"author":3,"featured_media":6435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno ha publicado la reducci&#243;n de los m&#243;dulos fiscales - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"En el Bolet&#237;n Oficial del Estado del 24 de abril se publica una Orden del ministerio de Hacienda por la que se reduce para el periodo impositivo de 2014 los &#237;ndices de rendimiento neto aplicables en el m&#233;todo de estimaci&#243;n objetiva del Impuesto sobre la Renta de las Personas F&#237;sicas, para las actividades agr&#237;colas y ganaderas afectadas por diversas circunstancias excepcionales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno ha publicado la reducci&#243;n de los m&#243;dulos fiscales - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"En el Bolet&#237;n Oficial del Estado del 24 de abril se publica una Orden del ministerio de Hacienda por la que se reduce para el periodo impositivo de 2014 los &#237;ndices de rendimiento neto aplicables en el m&#233;todo de estimaci&#243;n objetiva del Impuesto sobre la Renta de las Personas F&#237;sicas, para las actividades agr&#237;colas y ganaderas afectadas por diversas circunstancias excepcionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-23T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T08:38:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/Reduccion_mod_2015.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"816\" \/>\n\t<meta property=\"og:image:height\" content=\"612\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales\",\"name\":\"El Gobierno ha publicado la reducci&#243;n de los m&#243;dulos fiscales - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/Reduccion_mod_2015.jpg\",\"datePublished\":\"2015-04-23T22:00:00+00:00\",\"dateModified\":\"2017-11-15T08:38:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"En el Bolet&#237;n Oficial del Estado del 24 de abril se publica una Orden del ministerio de Hacienda por la que se reduce para el periodo impositivo de 2014 los &#237;ndices de rendimiento neto aplicables en el m&#233;todo de estimaci&#243;n objetiva del Impuesto sobre la Renta de las Personas F&#237;sicas, para las actividades agr&#237;colas y ganaderas afectadas por diversas circunstancias excepcionales.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/Reduccion_mod_2015.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/Reduccion_mod_2015.jpg\",\"width\":816,\"height\":612},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno ha publicado la reducci&#243;n de los m&#243;dulos fiscales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno ha publicado la reducci&#243;n de los m&#243;dulos fiscales - ASAJA Le\u00f3n","description":"En el Bolet&#237;n Oficial del Estado del 24 de abril se publica una Orden del ministerio de Hacienda por la que se reduce para el periodo impositivo de 2014 los &#237;ndices de rendimiento neto aplicables en el m&#233;todo de estimaci&#243;n objetiva del Impuesto sobre la Renta de las Personas F&#237;sicas, para las actividades agr&#237;colas y ganaderas afectadas por diversas circunstancias excepcionales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno ha publicado la reducci&#243;n de los m&#243;dulos fiscales - ASAJA Le\u00f3n","og_description":"En el Bolet&#237;n Oficial del Estado del 24 de abril se publica una Orden del ministerio de Hacienda por la que se reduce para el periodo impositivo de 2014 los &#237;ndices de rendimiento neto aplicables en el m&#233;todo de estimaci&#243;n objetiva del Impuesto sobre la Renta de las Personas F&#237;sicas, para las actividades agr&#237;colas y ganaderas afectadas por diversas circunstancias excepcionales.","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2015-04-23T22:00:00+00:00","article_modified_time":"2017-11-15T08:38:40+00:00","og_image":[{"width":816,"height":612,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/Reduccion_mod_2015.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales","name":"El Gobierno ha publicado la reducci&#243;n de los m&#243;dulos fiscales - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/Reduccion_mod_2015.jpg","datePublished":"2015-04-23T22:00:00+00:00","dateModified":"2017-11-15T08:38:40+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"En el Bolet&#237;n Oficial del Estado del 24 de abril se publica una Orden del ministerio de Hacienda por la que se reduce para el periodo impositivo de 2014 los &#237;ndices de rendimiento neto aplicables en el m&#233;todo de estimaci&#243;n objetiva del Impuesto sobre la Renta de las Personas F&#237;sicas, para las actividades agr&#237;colas y ganaderas afectadas por diversas circunstancias excepcionales.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/Reduccion_mod_2015.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/Reduccion_mod_2015.jpg","width":816,"height":612},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/el-gobierno-ha-publicado-la-reduccin-de-los-mdulos-fiscales#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"El Gobierno ha publicado la reducci&#243;n de los m&#243;dulos fiscales"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1435"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=1435"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1435\/revisions"}],"predecessor-version":[{"id":6434,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1435\/revisions\/6434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/6435"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=1435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=1435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=1435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}