{"id":14358,"date":"2023-06-27T18:34:41","date_gmt":"2023-06-27T16:34:41","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=14358"},"modified":"2023-06-27T18:34:43","modified_gmt":"2023-06-27T16:34:43","slug":"nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio","title":{"rendered":"Nueva ayuda al gas\u00f3leo agr\u00edcola aprobada en Consejo de Ministros del 27 de junio"},"content":{"rendered":"\n<p>En concreto, el importe de la ayuda ascender\u00e1 a 10 c\u00e9ntimos por cada litro consumido durante tres meses y a 5 c\u00e9ntimos durante otros tres meses, que se calcular\u00e1 teniendo en cuenta la media mensual realizado durante 2023.<\/p>\n<p>Esta ayuda se conceder\u00e1 a los agricultores mediante los mecanismos y procedimientos asociados a la devoluci\u00f3n parcial del Impuesto sobre Hidrocarburos.<\/p>\n<p>La Administraci\u00f3n tributaria realizar\u00e1 el pago de la nueva ayuda a la compra de gas\u00f3leo de uso agrario mediante una transferencia bancaria a la cuenta a la que se ordene el pago derivada de la solicitud de devoluci\u00f3n por adquisiciones 2023.<\/p>\n<p>Interpretamos que para esta devoluci\u00f3n es indistinto que se haya consumido en el primero o en el segundo semestre del a\u00f1o, porque se calcula sobre consumos medios del a\u00f1o 2023, salvo mejor criterio.<\/p>\n<p>ASAJA. Le\u00f3n, 27 de junio de 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En concreto, el importe de la ayuda ascender\u00e1 a 10 c\u00e9ntimos por cada litro consumido durante tres meses y a 5 c\u00e9ntimos durante otros tres meses, que se calcular\u00e1 teniendo en cuenta la media mensual realizado durante 2023. Esta ayuda se conceder\u00e1 a los agricultores mediante los mecanismos y procedimientos asociados a la devoluci\u00f3n parcial [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":14359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nueva ayuda al gas\u00f3leo agr\u00edcola aprobada en Consejo de Ministros del 27 de junio - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"En concreto, el importe de la ayuda ascender\u00e1 a 10 c\u00e9ntimos por cada litro consumido durante tres meses y a 5 c\u00e9ntimos durante otros tres meses, que se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva ayuda al gas\u00f3leo agr\u00edcola aprobada en Consejo de Ministros del 27 de junio - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"En concreto, el importe de la ayuda ascender\u00e1 a 10 c\u00e9ntimos por cada litro consumido durante tres meses y a 5 c\u00e9ntimos durante otros tres meses, que se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-27T16:34:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-27T16:34:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/06\/estacion-de-servicio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"611\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio\",\"name\":\"Nueva ayuda al gas\u00f3leo agr\u00edcola aprobada en Consejo de Ministros del 27 de junio - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/06\/estacion-de-servicio.jpg\",\"datePublished\":\"2023-06-27T16:34:41+00:00\",\"dateModified\":\"2023-06-27T16:34:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"En concreto, el importe de la ayuda ascender\u00e1 a 10 c\u00e9ntimos por cada litro consumido durante tres meses y a 5 c\u00e9ntimos durante otros tres meses, que se\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/06\/estacion-de-servicio.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/06\/estacion-de-servicio.jpg\",\"width\":1280,\"height\":611},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva ayuda al gas\u00f3leo agr\u00edcola aprobada en Consejo de Ministros del 27 de junio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva ayuda al gas\u00f3leo agr\u00edcola aprobada en Consejo de Ministros del 27 de junio - ASAJA Le\u00f3n","description":"En concreto, el importe de la ayuda ascender\u00e1 a 10 c\u00e9ntimos por cada litro consumido durante tres meses y a 5 c\u00e9ntimos durante otros tres meses, que se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio","og_locale":"es_ES","og_type":"article","og_title":"Nueva ayuda al gas\u00f3leo agr\u00edcola aprobada en Consejo de Ministros del 27 de junio - ASAJA Le\u00f3n","og_description":"En concreto, el importe de la ayuda ascender\u00e1 a 10 c\u00e9ntimos por cada litro consumido durante tres meses y a 5 c\u00e9ntimos durante otros tres meses, que se","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2023-06-27T16:34:41+00:00","article_modified_time":"2023-06-27T16:34:43+00:00","og_image":[{"width":1280,"height":611,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/06\/estacion-de-servicio.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio","name":"Nueva ayuda al gas\u00f3leo agr\u00edcola aprobada en Consejo de Ministros del 27 de junio - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/06\/estacion-de-servicio.jpg","datePublished":"2023-06-27T16:34:41+00:00","dateModified":"2023-06-27T16:34:43+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"En concreto, el importe de la ayuda ascender\u00e1 a 10 c\u00e9ntimos por cada litro consumido durante tres meses y a 5 c\u00e9ntimos durante otros tres meses, que se","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/06\/estacion-de-servicio.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/06\/estacion-de-servicio.jpg","width":1280,"height":611},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/nueva-ayuda-al-gasoleo-agricola-aprobada-en-consejo-de-ministros-del-27-de-junio#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Nueva ayuda al gas\u00f3leo agr\u00edcola aprobada en Consejo de Ministros del 27 de junio"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14358"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=14358"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14358\/revisions"}],"predecessor-version":[{"id":14360,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14358\/revisions\/14360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/14359"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=14358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=14358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=14358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}