{"id":145,"date":"2017-04-05T00:00:00","date_gmt":"2017-04-04T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2017\/04\/05\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos\/"},"modified":"2017-11-14T18:22:49","modified_gmt":"2017-11-14T17:22:49","slug":"asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos","title":{"rendered":"ASAJA PIDE FLEXIBILIDAD EN LOS PLANES DE SIEMBRA ANTE LAS ANUNCIADAS RESTRICCIONES EN EL RIEGO DE CULTIVOS"},"content":{"rendered":"<h2>La organizaci&#243;n agraria ASAJA ha pedido hoy a la Junta que exonere a los agricultores y ganaderos del compromiso de cumplir con el plan de cultivos presentado en los expedientes de ayuda a la modernizaci&#243;n de explotaciones e incorporaci&#243;n de j&#243;venes, un compromiso que se asume al menos por cinco a&#241;os.<\/h2>\n<p style=\"text-align: center;\">\n<span style=\"color:#006400;\"><strong>ASAJA PIDE FLEXIBILIDAD EN LOS PLANES DE SIEMBRA ANTE LAS ANUNCIADAS RESTRICCIONES EN EL RIEGO DE CULTIVOS<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\nLa organizaci&#243;n agraria ASAJA ha pedido hoy a la Junta que exonere a los agricultores y ganaderos del compromiso de cumplir con el plan de cultivos presentado en los expedientes de ayuda a la modernizaci&#243;n de explotaciones e incorporaci&#243;n de j&#243;venes, un compromiso que se asume al menos por cinco a&#241;os. Las dificultades para cumplir con estos compromisos est&#225;n en las restricciones del agua de riego por el mal estado de los embalses, unas restricciones que ya est&#225;n comunicando tanto la Confederaci&#243;n Hidrogr&#225;fica del Duero como las propias comunidades de regantes. La provincia de Le&#243;n, con m&#225;s de 150.000 hect&#225;reas, es la que&#160; m&#225;s superficie regable tiene de toda la autonom&#237;a, y pr&#225;cticamente todas son con aguas superficiales, no de sondeos, por lo tanto afectadas en mayor o menor medida por las restricciones.<\/p>\n<p style=\"text-align: justify;\">\nLa organizaci&#243;n agraria ha pedido tambi&#233;n, para estos agricultores de regad&#237;o, que se aplique flexibilidad en las normas que se establecen para el cobro del denominado &#8220;pago verde&#8221; de la PAC, tanto en lo referente al n&#250;mero de cultivos, como a los porcentajes que han de representar cada uno de ellos.<\/p>\n<p style=\"text-align: justify;\">\nASAJA espera sensibilidad de la Junta para abordar un problema, el de la falta de agua de riego, que puede convertirse en una cat&#225;strofe para la econom&#237;a de miles de familias agricultoras, y que &#250;nicamente se solucionar&#225;, total o parcialmente, si se da una situaci&#243;n excepcional de lluvias en las pr&#243;ximas semanas. M&#225;s adelante, seg&#250;n c&#243;mo evolucionen los acontecimientos, ser&#225; el momento de solicitar otras medidas excepcionales a las distintas administraciones con competencias en pol&#237;tica agraria.<\/p>\n<p style=\"text-align: justify;\">\nLe&#243;n, 5 de abril de 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci&#243;n agraria ASAJA ha pedido hoy a la Junta que exonere a los agricultores y ganaderos del compromiso de cumplir con el plan de cultivos presentado en los expedientes de ayuda a la modernizaci&#243;n de explotaciones e incorporaci&#243;n de j&#243;venes, un compromiso que se asume al menos por cinco a&#241;os.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA PIDE FLEXIBILIDAD EN LOS PLANES DE SIEMBRA ANTE LAS ANUNCIADAS RESTRICCIONES EN EL RIEGO DE CULTIVOS - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La organizaci&#243;n agraria ASAJA ha pedido hoy a la Junta que exonere a los agricultores y ganaderos del compromiso de cumplir con el plan de cultivos presentado en los expedientes de ayuda a la modernizaci&#243;n de explotaciones e incorporaci&#243;n de j&#243;venes, un compromiso que se asume al menos por cinco a&#241;os.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA PIDE FLEXIBILIDAD EN LOS PLANES DE SIEMBRA ANTE LAS ANUNCIADAS RESTRICCIONES EN EL RIEGO DE CULTIVOS - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La organizaci&#243;n agraria ASAJA ha pedido hoy a la Junta que exonere a los agricultores y ganaderos del compromiso de cumplir con el plan de cultivos presentado en los expedientes de ayuda a la modernizaci&#243;n de explotaciones e incorporaci&#243;n de j&#243;venes, un compromiso que se asume al menos por cinco a&#241;os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-04T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T17:22:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos\",\"name\":\"ASAJA PIDE FLEXIBILIDAD EN LOS PLANES DE SIEMBRA ANTE LAS ANUNCIADAS RESTRICCIONES EN EL RIEGO DE CULTIVOS - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2017-04-04T22:00:00+00:00\",\"dateModified\":\"2017-11-14T17:22:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"La organizaci&#243;n agraria ASAJA ha pedido hoy a la Junta que exonere a los agricultores y ganaderos del compromiso de cumplir con el plan de cultivos presentado en los expedientes de ayuda a la modernizaci&#243;n de explotaciones e incorporaci&#243;n de j&#243;venes, un compromiso que se asume al menos por cinco a&#241;os.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA PIDE FLEXIBILIDAD EN LOS PLANES DE SIEMBRA ANTE LAS ANUNCIADAS RESTRICCIONES EN EL RIEGO DE CULTIVOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA PIDE FLEXIBILIDAD EN LOS PLANES DE SIEMBRA ANTE LAS ANUNCIADAS RESTRICCIONES EN EL RIEGO DE CULTIVOS - ASAJA Le\u00f3n","description":"La organizaci&#243;n agraria ASAJA ha pedido hoy a la Junta que exonere a los agricultores y ganaderos del compromiso de cumplir con el plan de cultivos presentado en los expedientes de ayuda a la modernizaci&#243;n de explotaciones e incorporaci&#243;n de j&#243;venes, un compromiso que se asume al menos por cinco a&#241;os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos","og_locale":"es_ES","og_type":"article","og_title":"ASAJA PIDE FLEXIBILIDAD EN LOS PLANES DE SIEMBRA ANTE LAS ANUNCIADAS RESTRICCIONES EN EL RIEGO DE CULTIVOS - ASAJA Le\u00f3n","og_description":"La organizaci&#243;n agraria ASAJA ha pedido hoy a la Junta que exonere a los agricultores y ganaderos del compromiso de cumplir con el plan de cultivos presentado en los expedientes de ayuda a la modernizaci&#243;n de explotaciones e incorporaci&#243;n de j&#243;venes, un compromiso que se asume al menos por cinco a&#241;os.","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2017-04-04T22:00:00+00:00","article_modified_time":"2017-11-14T17:22:49+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos","name":"ASAJA PIDE FLEXIBILIDAD EN LOS PLANES DE SIEMBRA ANTE LAS ANUNCIADAS RESTRICCIONES EN EL RIEGO DE CULTIVOS - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2017-04-04T22:00:00+00:00","dateModified":"2017-11-14T17:22:49+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"La organizaci&#243;n agraria ASAJA ha pedido hoy a la Junta que exonere a los agricultores y ganaderos del compromiso de cumplir con el plan de cultivos presentado en los expedientes de ayuda a la modernizaci&#243;n de explotaciones e incorporaci&#243;n de j&#243;venes, un compromiso que se asume al menos por cinco a&#241;os.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-flexibilidad-en-los-planes-de-siembra-ante-las-anunciadas-restricciones-en-el-riego-de-cultivos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ASAJA PIDE FLEXIBILIDAD EN LOS PLANES DE SIEMBRA ANTE LAS ANUNCIADAS RESTRICCIONES EN EL RIEGO DE CULTIVOS"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/145"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=145"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/145\/revisions"}],"predecessor-version":[{"id":3710,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/145\/revisions\/3710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}