{"id":14505,"date":"2023-08-11T10:10:54","date_gmt":"2023-08-11T08:10:54","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=14505"},"modified":"2023-08-25T09:07:42","modified_gmt":"2023-08-25T07:07:42","slug":"asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios","title":{"rendered":"ASAJA valora que la concentraci\u00f3n parcelaria de Los Oteros entre en su fase final, y espera que se hayan atendido las reclamaciones de los propietarios"},"content":{"rendered":"\n<p>La organizaci\u00f3n agraria ASAJA de Le\u00f3n ha recibido con satisfacci\u00f3n la publicaci\u00f3n en el BOCYL en el d\u00eda hoy del Anuncio de la Direcci\u00f3n General\u00a0 de Desarrollo Rural, por el que se somete a informaci\u00f3n p\u00fablica la <strong>aprobaci\u00f3n del acuerdo de reordenaci\u00f3n parcelaria de la zona de Los Oteros<\/strong>. Este paso permitir\u00e1 la entrega de las fincas de reemplazo en el plazo de un mes, coincidiendo con el inicio de la campa\u00f1a 2023\/2024, algo que ASAJA ha venido demandando insistentemente.<\/p>\n<p>ASAJA espera que la Junta haya atendido la mayor\u00eda de las alegaciones que distintos propietarios formularon al proyecto de concentraci\u00f3n parcelaria, y que a ser posible no haya ning\u00fan perjudicado, pues el objetivo de esta medida de reordenaci\u00f3n de la propiedad debe de ser\u00a0 que todos obtengan mejoras, en particular los propietarios que a su vez son cultivadores profesionales. Mejoras que llegan sobre todo por juntar la propiedad en una \u00fanica parcela incluso teniendo propiedades en varios municipios, y por la actuaci\u00f3n en la red de caminos que dan acceso a las fincas que permitir\u00e1 ahorrar tiempo y alargar la vida de la maquinaria.\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n<p>Con motivo de la entrega de las fincas de reemplazo, <strong>ASAJA pedir\u00e1 a la Junta, por diferentes v\u00edas, que blinde esta zona agr\u00edcola reconcentrada e impida la implantaci\u00f3n de macroparques fotovoltaicos.<\/strong> Los promotores de estas energ\u00edas ya est\u00e1n contactando con los propietarios para, ahora que las fincas son mayores, reconvertir el suelo agr\u00edcola en suelo industrial destin\u00e1ndolo a energ\u00edas fotovoltaicas y lo hace precisamente aqu\u00ed para aprovechar la proximidad al centro de evacuaci\u00f3n de Red El\u00e9ctrica en Luengos de los Oteros. La inversi\u00f3n que ha hecho la Junta de Castilla y Le\u00f3n\u00a0 en esta actuaci\u00f3n, con el fin de mejorar la competitividad de las explotaciones, no puede servir para lo contrario, para que se pierdan cientos de hect\u00e1reas de suelo agr\u00edcola a favor de otros usos.<\/p>\n<p>Por otra parte, ASAJA reitera la necesidad de <strong>modificar la unidad m\u00ednima de cultivo<\/strong>, que es la superficie que determina si una finca se puede segregar en una compraventa, herencia o donaci\u00f3n. ASAJA viene demandando medidas para que las fincas agr\u00edcolas no puedan dividirse, ya que las administraciones no pueden estar permanentemente haciendo reconcentraciones parcelarias para hacer fincas mayores que despu\u00e9s los propietarios troceen en las herencias a su antojo. La unidad m\u00ednima de cultivo est\u00e1 regulada por un Decreto de la JCYL de 1984, sin que se haya modificado desde entonces. En la zona de actuaci\u00f3n citada (Los Oteros), la unidad m\u00ednima de cultivo est\u00e1 en 6 hect\u00e1reas en secano y 2 en regad\u00edo.<\/p>\n<p>ASAJA. Le\u00f3n, 11 de agosto de 2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n agraria ASAJA de Le\u00f3n ha recibido con satisfacci\u00f3n la publicaci\u00f3n en el BOCYL en el d\u00eda hoy del Anuncio de la Direcci\u00f3n General\u00a0 de Desarrollo Rural, por el que se somete a informaci\u00f3n p\u00fablica la aprobaci\u00f3n del acuerdo de reordenaci\u00f3n parcelaria de la zona de Los Oteros. Este paso permitir\u00e1 la entrega de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":14507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA valora que la concentraci\u00f3n parcelaria de Los Oteros entre en su fase final, y espera que se hayan atendido las reclamaciones de los propietarios - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La organizaci\u00f3n agraria ASAJA de Le\u00f3n ha recibido con satisfacci\u00f3n la publicaci\u00f3n en el BOCYL en el d\u00eda hoy del Anuncio de la Direcci\u00f3n General\u00a0 de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA valora que la concentraci\u00f3n parcelaria de Los Oteros entre en su fase final, y espera que se hayan atendido las reclamaciones de los propietarios - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n agraria ASAJA de Le\u00f3n ha recibido con satisfacci\u00f3n la publicaci\u00f3n en el BOCYL en el d\u00eda hoy del Anuncio de la Direcci\u00f3n General\u00a0 de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-11T08:10:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T07:07:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"344\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios\",\"name\":\"ASAJA valora que la concentraci\u00f3n parcelaria de Los Oteros entre en su fase final, y espera que se hayan atendido las reclamaciones de los propietarios - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg\",\"datePublished\":\"2023-08-11T08:10:54+00:00\",\"dateModified\":\"2023-08-25T07:07:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"La organizaci\u00f3n agraria ASAJA de Le\u00f3n ha recibido con satisfacci\u00f3n la publicaci\u00f3n en el BOCYL en el d\u00eda hoy del Anuncio de la Direcci\u00f3n General\u00a0 de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg\",\"width\":612,\"height\":344,\"caption\":\"Tractor cultivating field at spring,aerial view\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA valora que la concentraci\u00f3n parcelaria de Los Oteros entre en su fase final, y espera que se hayan atendido las reclamaciones de los propietarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA valora que la concentraci\u00f3n parcelaria de Los Oteros entre en su fase final, y espera que se hayan atendido las reclamaciones de los propietarios - ASAJA Le\u00f3n","description":"La organizaci\u00f3n agraria ASAJA de Le\u00f3n ha recibido con satisfacci\u00f3n la publicaci\u00f3n en el BOCYL en el d\u00eda hoy del Anuncio de la Direcci\u00f3n General\u00a0 de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios","og_locale":"es_ES","og_type":"article","og_title":"ASAJA valora que la concentraci\u00f3n parcelaria de Los Oteros entre en su fase final, y espera que se hayan atendido las reclamaciones de los propietarios - ASAJA Le\u00f3n","og_description":"La organizaci\u00f3n agraria ASAJA de Le\u00f3n ha recibido con satisfacci\u00f3n la publicaci\u00f3n en el BOCYL en el d\u00eda hoy del Anuncio de la Direcci\u00f3n General\u00a0 de","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2023-08-11T08:10:54+00:00","article_modified_time":"2023-08-25T07:07:42+00:00","og_image":[{"width":612,"height":344,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios","name":"ASAJA valora que la concentraci\u00f3n parcelaria de Los Oteros entre en su fase final, y espera que se hayan atendido las reclamaciones de los propietarios - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg","datePublished":"2023-08-11T08:10:54+00:00","dateModified":"2023-08-25T07:07:42+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"La organizaci\u00f3n agraria ASAJA de Le\u00f3n ha recibido con satisfacci\u00f3n la publicaci\u00f3n en el BOCYL en el d\u00eda hoy del Anuncio de la Direcci\u00f3n General\u00a0 de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg","width":612,"height":344,"caption":"Tractor cultivating field at spring,aerial view"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-que-la-concentracion-parcelaria-de-los-oteros-entre-en-su-fase-final-y-espera-que-se-hayan-atendido-las-reclamaciones-de-los-propietarios#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ASAJA valora que la concentraci\u00f3n parcelaria de Los Oteros entre en su fase final, y espera que se hayan atendido las reclamaciones de los propietarios"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14505"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=14505"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14505\/revisions"}],"predecessor-version":[{"id":14508,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14505\/revisions\/14508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/14507"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=14505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=14505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=14505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}