{"id":1466,"date":"2014-08-19T00:00:00","date_gmt":"2014-08-18T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2014\/08\/19\/recortes-en-las-ayudas\/"},"modified":"2017-11-15T09:39:11","modified_gmt":"2017-11-15T08:39:11","slug":"recortes-en-las-ayudas","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas","title":{"rendered":"RECORTES EN LAS AYUDAS"},"content":{"rendered":"<h2><\/h2>\n<p align=\"center\" style=\"margin-left: 36pt\">\n<span style=\"color: #008000\"><strong>RECORTES EN LAS AYUDAS<\/strong><\/span><\/p>\n<p style=\"text-align: justify; margin-left: 36pt\">\nEl Diario Oficial del Uni&#243;n Europea del 13 de agosto public&#243; un <strong>Reglamento de Ejecuci&#243;n<\/strong> de la Comisi&#243;n por el que se fija para el a&#241;o civil 2014 un porcentaje de ajuste de los pagos directos dirigidos a los agricultores y ganaderos. Este ajuste supone un recorte del 1,30% en las ayudas solicitadas en 2014, quedando exentos de dicho recorte los 2.000 primeros euros de ayuda.&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RECORTES EN LAS AYUDAS El Diario Oficial del Uni&#243;n Europea del 13 de agosto public&#243; un Reglamento de Ejecuci&#243;n de la Comisi&#243;n por el que se fija para el a&#241;o civil 2014 un porcentaje de ajuste de los pagos directos dirigidos a los agricultores y ganaderos. Este ajuste supone un recorte del 1,30% en las [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RECORTES EN LAS AYUDAS - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"RECORTES EN LAS AYUDAS El Diario Oficial del Uni&#243;n Europea del 13 de agosto public&#243; un Reglamento de Ejecuci&#243;n de la Comisi&#243;n por el\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RECORTES EN LAS AYUDAS - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"RECORTES EN LAS AYUDAS El Diario Oficial del Uni&#243;n Europea del 13 de agosto public&#243; un Reglamento de Ejecuci&#243;n de la Comisi&#243;n por el\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-18T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T08:39:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas\",\"name\":\"RECORTES EN LAS AYUDAS - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2014-08-18T22:00:00+00:00\",\"dateModified\":\"2017-11-15T08:39:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"RECORTES EN LAS AYUDAS El Diario Oficial del Uni&#243;n Europea del 13 de agosto public&#243; un Reglamento de Ejecuci&#243;n de la Comisi&#243;n por el\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RECORTES EN LAS AYUDAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RECORTES EN LAS AYUDAS - ASAJA Le\u00f3n","description":"RECORTES EN LAS AYUDAS El Diario Oficial del Uni&#243;n Europea del 13 de agosto public&#243; un Reglamento de Ejecuci&#243;n de la Comisi&#243;n por el","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas","og_locale":"es_ES","og_type":"article","og_title":"RECORTES EN LAS AYUDAS - ASAJA Le\u00f3n","og_description":"RECORTES EN LAS AYUDAS El Diario Oficial del Uni&#243;n Europea del 13 de agosto public&#243; un Reglamento de Ejecuci&#243;n de la Comisi&#243;n por el","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2014-08-18T22:00:00+00:00","article_modified_time":"2017-11-15T08:39:11+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas","name":"RECORTES EN LAS AYUDAS - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2014-08-18T22:00:00+00:00","dateModified":"2017-11-15T08:39:11+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"RECORTES EN LAS AYUDAS El Diario Oficial del Uni&#243;n Europea del 13 de agosto public&#243; un Reglamento de Ejecuci&#243;n de la Comisi&#243;n por el","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/recortes-en-las-ayudas#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"RECORTES EN LAS AYUDAS"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1466"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=1466"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1466\/revisions"}],"predecessor-version":[{"id":1859,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1466\/revisions\/1859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=1466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=1466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=1466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}