{"id":14875,"date":"2023-11-20T14:01:00","date_gmt":"2023-11-20T13:01:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=14875"},"modified":"2023-11-20T14:01:02","modified_gmt":"2023-11-20T13:01:02","slug":"importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023","title":{"rendered":"Importes provisionales ayudas asociadas y eco reg\u00edmenes de la PAC 2023"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Con \u00a0base a nueva informaci\u00f3n, el 17 de noviembre el FEGA ha corregido las estimaciones de ayudas asociadas y de eco reg\u00edmenes \u00a0publicadas el 18 de septiembre 2023, y ha establecido nuevos importes para tener en cuenta en pr\u00f3ximos pagos, en particular el pago que se hace en el mes de diciembre. No obstante, estas cantidades no son todav\u00eda definitivas, pero las variaciones deber\u00edan de ser ya, en todo caso, poco significativas.<\/p>\n<p>Lo previsto es que a finales de diciembre quede pagado el 90% del importe de estas y otras ayudas de la PAC, y que el saldo final se haga antes del 30 de junio de 2024.<\/p>\n<p><strong>IMPORTES AYUDAS ASOCIADAS AGR\u00cdCOLAS Y GANADERAS<\/strong><\/p>\n<ul>\n<li>La ayuda a las <strong>legumbres<\/strong> queda en <strong>80 euros<\/strong> hect\u00e1rea ( es lo inicialmente previsto y m\u00e1s de lo estimado en septiembre).<\/li>\n<li>La ayuda a las<strong> leguminosas de consumo animal<\/strong> (vezas, guisantes, alfalfa\u2026) prevista en 60 euros por hect\u00e1rea, se queda en m\u00e1s, en <strong>63,8<\/strong> euros hect\u00e1rea.<\/li>\n<li>La ayuda a la <strong>remolacha azucarera<\/strong>, se queda en <strong>591,75<\/strong> euros hect\u00e1rea, igual que lo previsto y m\u00e1s que en la estimaci\u00f3n de septiembre.<\/li>\n<li>La ayuda a la <strong>vaca nodriza<\/strong>, prevista inicialmente en 90 euros por vaca, se queda en <strong>84,55<\/strong> y si es raza aut\u00f3ctona <strong>93 euros<\/strong> (m\u00e1s de lo previsto en la estimaci\u00f3n de septiembre).<\/li>\n<li>La ayuda asociada para la <strong>producci\u00f3n de leche<\/strong> de vaca, en el primer tramo de hasta 150 vacas, es de <strong>170,38 <\/strong>euros por animal, que se eleva a <strong>195,84<\/strong> si es zona de monta\u00f1a. En el tramo segundo, de 151 a 725 vacas, la ayuda se queda en <strong>85,19<\/strong> euros por animal. Es superior a lo previsto y a lo estimado en septiembre.<\/li>\n<li>La ayuda al <strong>ovino y caprino de carne<\/strong> se queda en <strong>15,61<\/strong> euros, superior a lo previsto y a lo estimado en septiembre.<\/li>\n<li>La ayuda asociada a<strong> ovino y caprino de leche<\/strong> se \u00a0queda en <strong>16,08<\/strong> euros, superior a lo previsto y a lo estimado en septiembre.<\/li>\n<li>La ayuda a ganaderos de ovino y caprino que no cobren derechos de la Pac y aprovechen rastrojeras queda en <strong>13,62<\/strong> euros, superior a lo previsto y a lo estimado en septiembre.<\/li>\n<\/ul>\n<p><strong>IMPORTE ECO REG\u00cdMENES DE LA PAC<\/strong><\/p>\n<ul>\n<li>Eco r\u00e9gimen de <strong>pastoreo extensivo, siega y espacios de biodiversidad en <u>pastos h\u00famedos<\/u><\/strong>: la ayuda prevista era de 62,16 euros por hect\u00e1rea y se queda en <strong>51,13<\/strong>. A partir de las 65 hect\u00e1reas se aplica degresividad y se pagan a <strong>43,51<\/strong> euros hect\u00e1rea.<\/li>\n<li>Eco r\u00e9gimen de <strong>pastoreo extensivo, siega y espacios de biodiversidad en <u>pastos secos<\/u>: <\/strong>la ayuda prevista era de 40,96 euros por hect\u00e1rea y se ha quedado en <strong>33,69<\/strong> Se aplica degresividad, por lo que a partir de 95 hect\u00e1reas la ayuda es de <strong>27,19<\/strong> euros hect\u00e1rea.<\/li>\n<li>Eco r\u00e9gimen de <strong>rotaci\u00f3n y siembra directa en secano<\/strong>: la ayuda prevista eran 47,67 euros por hect\u00e1rea y se mantiene igual, en <strong>47,67<\/strong>, por lo tanto se cobra el 100%. Con plurianualidad el importe es de <strong>72,67<\/strong> euros hect\u00e1rea (25 euros m\u00e1s). Se aplica degresividad a partir de las 70 hect\u00e1reas, quedando en <strong>36,90<\/strong> euros por hect\u00e1rea y <strong>61,90<\/strong> si hay plurianualidad.<\/li>\n<li>El eco r\u00e9gimen de <strong>rotaci\u00f3n y siembra directa en regad\u00edo<\/strong> pasa de 151,99 que se estimaba a <strong>139,52<\/strong> euros hect\u00e1rea. Se aplica degresividad a partir de 25 has, quedando en <strong>97,67<\/strong> euros hect\u00e1rea. Con el compromiso de plurianualidad de siembra directa la ayuda queda en 164,52 euros, y a partir de las 25 hect\u00e1reas en 122,66 euros hect\u00e1rea.<\/li>\n<li>Eco r\u00e9gimen de espacios de biodiversidad (no cosechado): estaba previsto 56,04 euros por hect\u00e1rea y se ha quedado en <strong>46,10<\/strong>. No se aplica degresividad, como estaba previsto.<\/li>\n<li>En el eco r\u00e9gimen de <strong>cubierta vegetal y cubiertas inertes en cultivos le\u00f1osos<\/strong>, en terrenos llanos, los importes se mantienen en lo previsto que eran 61,07 euros hect\u00e1rea y no hay degresividad, es decir, cobran eso todas las has. En terrenos de pendiente media se mantiene tambi\u00e9n lo previsto, de 113,95 euros hect\u00e1rea, y sin degresividad. En terrenos de pendiente de m\u00e1s del 10% o bancales, lo previsto eran <strong>165,17<\/strong> euros, y se mantiene en dicho importe, y se aplica degresividad, por lo que a partir de 15 has. el importe es de <strong>115,61<\/strong> euros hect\u00e1rea (a estas cantidades hay que sumar lo correspondiente a la plurianualidad, si es el caso).<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>ASAJA Le\u00f3n, 20 de noviembre de 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con \u00a0base a nueva informaci\u00f3n, el 17 de noviembre el FEGA ha corregido las estimaciones de ayudas asociadas y de eco reg\u00edmenes \u00a0publicadas el 18 de septiembre 2023, y ha establecido nuevos importes para tener en cuenta en pr\u00f3ximos pagos, en particular el pago que se hace en el mes de diciembre. No obstante, estas [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":14448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Importes provisionales ayudas asociadas y eco reg\u00edmenes de la PAC 2023 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Con \u00a0base a nueva informaci\u00f3n, el 17 de noviembre el FEGA ha corregido las estimaciones de ayudas asociadas y de eco reg\u00edmenes \u00a0publicadas el 18 de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Importes provisionales ayudas asociadas y eco reg\u00edmenes de la PAC 2023 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Con \u00a0base a nueva informaci\u00f3n, el 17 de noviembre el FEGA ha corregido las estimaciones de ayudas asociadas y de eco reg\u00edmenes \u00a0publicadas el 18 de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-20T13:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-20T13:01:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/cabras.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"886\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023\",\"name\":\"Importes provisionales ayudas asociadas y eco reg\u00edmenes de la PAC 2023 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/cabras.jpg\",\"datePublished\":\"2023-11-20T13:01:00+00:00\",\"dateModified\":\"2023-11-20T13:01:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Con \u00a0base a nueva informaci\u00f3n, el 17 de noviembre el FEGA ha corregido las estimaciones de ayudas asociadas y de eco reg\u00edmenes \u00a0publicadas el 18 de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/cabras.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/cabras.jpg\",\"width\":1280,\"height\":886},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Importes provisionales ayudas asociadas y eco reg\u00edmenes de la PAC 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Importes provisionales ayudas asociadas y eco reg\u00edmenes de la PAC 2023 - ASAJA Le\u00f3n","description":"Con \u00a0base a nueva informaci\u00f3n, el 17 de noviembre el FEGA ha corregido las estimaciones de ayudas asociadas y de eco reg\u00edmenes \u00a0publicadas el 18 de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023","og_locale":"es_ES","og_type":"article","og_title":"Importes provisionales ayudas asociadas y eco reg\u00edmenes de la PAC 2023 - ASAJA Le\u00f3n","og_description":"Con \u00a0base a nueva informaci\u00f3n, el 17 de noviembre el FEGA ha corregido las estimaciones de ayudas asociadas y de eco reg\u00edmenes \u00a0publicadas el 18 de","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2023-11-20T13:01:00+00:00","article_modified_time":"2023-11-20T13:01:02+00:00","og_image":[{"width":1280,"height":886,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/cabras.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023","name":"Importes provisionales ayudas asociadas y eco reg\u00edmenes de la PAC 2023 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/cabras.jpg","datePublished":"2023-11-20T13:01:00+00:00","dateModified":"2023-11-20T13:01:02+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Con \u00a0base a nueva informaci\u00f3n, el 17 de noviembre el FEGA ha corregido las estimaciones de ayudas asociadas y de eco reg\u00edmenes \u00a0publicadas el 18 de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/cabras.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/cabras.jpg","width":1280,"height":886},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/importes-provisionales-ayudas-asociadas-y-eco-regimenes-de-la-pac-2023#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Importes provisionales ayudas asociadas y eco reg\u00edmenes de la PAC 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14875"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=14875"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14875\/revisions"}],"predecessor-version":[{"id":14876,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/14875\/revisions\/14876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/14448"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=14875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=14875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=14875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}