{"id":15260,"date":"2024-04-05T16:17:24","date_gmt":"2024-04-05T14:17:24","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=15260"},"modified":"2024-04-12T10:57:21","modified_gmt":"2024-04-12T08:57:21","slug":"las-seis-noticias-agrarias-de-la-semana-05-04-2024","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 05\/04\/2024"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Concentraci\u00f3n Parcelaria Sector XII de la Margen Izquierda del Porma, Embalses leoneses, 45\u00ba Plan de Seguros Agrarios Combinados, an\u00e1lisis de tierras destinadas al cultivo, Control Lechero de Castilla y Le\u00f3n, seguro de remolacha<\/h2>\n\n\n\n<ol>\n<li>El Ayuntamiento de Gordoncillo ha publicado la aprobaci\u00f3n, por parte de la Consejer\u00eda de Agricultura, del Estudio T\u00e9cnico Previo de la Zona de Concentraci\u00f3n Parcelaria vinculada a la zona regable Sector XII de la Margen Izquierda del Porma. Se trata de una peque\u00f1a superficie de nuevos regad\u00edos a\u00f1adida a los nuevos regad\u00edos proyectados en\u00a0 Valderas.<\/li>\n<\/ol>\n<ol start=\"2\">\n<li>Los <strong>embalses leoneses<\/strong> de la cuenca del Duero se encontraban esta semana por encima del 85% de su capacidad, por lo tanto t\u00e9cnicamente se puede decir que se encontraban llenos, albergando 1.100 hect\u00f3metros c\u00fabicos de agua. Adem\u00e1s, el estado de los r\u00edos va a\u00a0 permitir que el primer consumo para riego\u00a0 se pueda hacer sin necesidad de llevar a cabo el desembalse. Esta situaci\u00f3n va a permitir ahorrar agua para la campa\u00f1a de 2025.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li>El Consejo de Ministros ha aprobado el convenio de colaboraci\u00f3n entre la Entidad Estatal de Seguros Agrarios (ENESA) y la Agrupaci\u00f3n Espa\u00f1ola de Entidades Aseguradoras de los Seguros Agrarios (Agroseguro) para la ejecuci\u00f3n del <strong>45\u00ba Plan de Seguros Agrarios Combinados<\/strong> y la liquidaci\u00f3n de planes anteriores, as\u00ed como para regular otros \u00e1mbitos de cooperaci\u00f3n. El acuerdo cuenta con un presupuesto para subvencionar la contrataci\u00f3n de p\u00f3lizas en el a\u00f1o 2024 de 284,5 millones de euros, dotaci\u00f3n que ya fue aprobada en Consejo de Ministros el pasado 27 de diciembre de 2023<\/li>\n<\/ol>\n<ol start=\"4\">\n<li>ASAJA critica que la Diputaci\u00f3n de Le\u00f3n\u00a0 haya dejado de presar el servicio\u00a0 de subvencionar a agricultores y ganaderos por el <strong>an\u00e1lisis de tierras destinadas al cultivo<\/strong>, sin dar explicaciones de los motivos, ni haber informado si volver\u00e1 a prestar este servicio en un futuro. La \u00faltima convocatoria de esta l\u00ednea de ayudas se public\u00f3 en el BOP del 24 de diciembre de 2022, extendiendo el servicio hasta el 21 de junio de 2023.<\/li>\n<\/ol>\n<ol start=\"5\">\n<li>Se han publicado los datos oficiales del <strong>Control Lechero de Castilla y Le\u00f3n <\/strong>referentes al a\u00f1o 2023. En leche de vaca, en la raza Frisona, y para animales de\u00a0 primer parto, la producci\u00f3n por lactaci\u00f3n fue de 12.993 kilos por animal, con una media de grasa del 3,86% y una media de prote\u00edna del 3,44%. En el caso de hembras en segunda o siguientes lactaciones, la producci\u00f3n ascendi\u00f3 a 14.598 kilos de leche. Se puede decir que estos rendimientos est\u00e1n muy estabilizados, con escasas mejoras respecto a ejercicios anteriores.<\/li>\n<\/ol>\n<ol start=\"6\">\n<li>El pr\u00f3ximo d\u00eda 10 de abril finaliza el plazo para la suscripci\u00f3n del <strong>seguro de remolacha<\/strong> que cubre todos los da\u00f1os, incluido el de no nascencia y helada. Ese mismo d\u00eda finaliza el plazo para hacer las modificaciones en el seguro de rendimiento, de cultivos de secano, en la Linea 309, una vez que dicho plazo fue ampliado, pues inicialmente finalizaba el 30 de marzo.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Concentraci\u00f3n Parcelaria Sector XII de la Margen Izquierda del Porma, Embalses leoneses, 45\u00ba Plan de Seguros Agrarios Combinados, an\u00e1lisis de tierras destinadas al cultivo, Control Lechero de Castilla y Le\u00f3n, seguro de remolacha El Ayuntamiento de Gordoncillo ha publicado la aprobaci\u00f3n, por parte de la Consejer\u00eda de Agricultura, del Estudio T\u00e9cnico Previo de la Zona [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":14462,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 05\/04\/2024 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Concentraci\u00f3n Parcelaria Sector XII de la Margen Izquierda del Porma, Embalses leoneses, 45\u00ba Plan de Seguros Agrarios Combinados, an\u00e1lisis de tierras\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 05\/04\/2024 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Concentraci\u00f3n Parcelaria Sector XII de la Margen Izquierda del Porma, Embalses leoneses, 45\u00ba Plan de Seguros Agrarios Combinados, an\u00e1lisis de tierras\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-05T14:17:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-12T08:57:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/Puente_Ingeniero_Carlos_Fernandez_Casado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024\",\"name\":\"Las seis noticias agrarias de la semana - 05\/04\/2024 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/Puente_Ingeniero_Carlos_Fernandez_Casado.jpg\",\"datePublished\":\"2024-04-05T14:17:24+00:00\",\"dateModified\":\"2024-04-12T08:57:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Concentraci\u00f3n Parcelaria Sector XII de la Margen Izquierda del Porma, Embalses leoneses, 45\u00ba Plan de Seguros Agrarios Combinados, an\u00e1lisis de tierras\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/Puente_Ingeniero_Carlos_Fernandez_Casado.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/Puente_Ingeniero_Carlos_Fernandez_Casado.jpg\",\"width\":2048,\"height\":1536,\"caption\":\"Foto conseguida de http:\/\/www.asturlinux.org\/galeria\/berrueta-blog\/IMG_3970 su autor es: http:\/\/www.asturlinux.org\/~berrueta\/ Comparto la foto en esta licencia porque el autor as\u00ed me lo ha permitido (y pedido) con un correo electr\u00f3nico. Es el puente Ingeniero Carlos Fern\u00e1ndez Casado que cruza el embalse de Barrios de Luna, en la AP-66 (antes A-66), que es la autopista que va de Le\u00f3n a Asturias, es un puente atirantado muy bonito.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 05\/04\/2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 05\/04\/2024 - ASAJA Le\u00f3n","description":"Concentraci\u00f3n Parcelaria Sector XII de la Margen Izquierda del Porma, Embalses leoneses, 45\u00ba Plan de Seguros Agrarios Combinados, an\u00e1lisis de tierras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 05\/04\/2024 - ASAJA Le\u00f3n","og_description":"Concentraci\u00f3n Parcelaria Sector XII de la Margen Izquierda del Porma, Embalses leoneses, 45\u00ba Plan de Seguros Agrarios Combinados, an\u00e1lisis de tierras","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2024-04-05T14:17:24+00:00","article_modified_time":"2024-04-12T08:57:21+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/Puente_Ingeniero_Carlos_Fernandez_Casado.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024","name":"Las seis noticias agrarias de la semana - 05\/04\/2024 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/Puente_Ingeniero_Carlos_Fernandez_Casado.jpg","datePublished":"2024-04-05T14:17:24+00:00","dateModified":"2024-04-12T08:57:21+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Concentraci\u00f3n Parcelaria Sector XII de la Margen Izquierda del Porma, Embalses leoneses, 45\u00ba Plan de Seguros Agrarios Combinados, an\u00e1lisis de tierras","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/Puente_Ingeniero_Carlos_Fernandez_Casado.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/07\/Puente_Ingeniero_Carlos_Fernandez_Casado.jpg","width":2048,"height":1536,"caption":"Foto conseguida de http:\/\/www.asturlinux.org\/galeria\/berrueta-blog\/IMG_3970 su autor es: http:\/\/www.asturlinux.org\/~berrueta\/ Comparto la foto en esta licencia porque el autor as\u00ed me lo ha permitido (y pedido) con un correo electr\u00f3nico. Es el puente Ingeniero Carlos Fern\u00e1ndez Casado que cruza el embalse de Barrios de Luna, en la AP-66 (antes A-66), que es la autopista que va de Le\u00f3n a Asturias, es un puente atirantado muy bonito."},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-05-04-2024#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 05\/04\/2024"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15260"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=15260"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15260\/revisions"}],"predecessor-version":[{"id":15261,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15260\/revisions\/15261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/14462"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=15260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=15260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=15260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}