{"id":15342,"date":"2024-05-02T09:30:41","date_gmt":"2024-05-02T07:30:41","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=15342"},"modified":"2024-05-17T10:19:35","modified_gmt":"2024-05-17T08:19:35","slug":"asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas","title":{"rendered":"ASAJA pide a Azucarera que planifique mejor sus campa\u00f1as para que la remolacha no est\u00e9 tanto tiempo en las fincas"},"content":{"rendered":"\n<p>Ante las expectativas de un incremento\u00a0 importante de las siembras de remolacha para esta campa\u00f1a 2024-2025, que podr\u00eda llegar en la provincia de Le\u00f3n a las 10.000 hect\u00e1reas, frente a las 7.000 de la pasada, la organizaci\u00f3n agraria ASAJA reclama una mejor planificaci\u00f3n para que la mayor\u00eda se molture en el a\u00f1o natural o en los primeros meses del siguiente, y que en ning\u00fan caso se convierta en habitual tener remolacha en las fincas sin recolectar en el mes de mayo, como est\u00e1 ocurriendo este a\u00f1o.<\/p>\n<p>Esta situaci\u00f3n de ciclos anormalmente largos en el cultivo ocasiona p\u00e9rdidas importantes que soportan los productores, y que nadie se las compensa. Y aunque es cierto que una gran parte de la remolacha se contrata bajo la modalidad de \u201ccontrato compartido\u201d donde los mayores riesgos los asume la industria azucarera, no es menos cierto que alargar hasta doce meses la permanencia de la ra\u00edz en las fincas dificulta sobremanera hacer una rotaci\u00f3n en la explotaci\u00f3n, pues retrasa la implantaci\u00f3n de los cultivos del a\u00f1o siguiente, y es incompatible con algunos de ellos, como los cereales de invierno, que se siembran en los meses de noviembre y diciembre.<\/p>\n<p>ASAJA considera un hecho muy positivo que el az\u00facar est\u00e9 en niveles muy altos en los mercados internacionales y que gracias a ello la industria azucarera haya mejorado las condiciones a los productores, y que estos hayan respondido incrementando la superficie de siembra. Pero ASAJA alerta de que este cultivo, si no es bien gestionado, va a ser menos rentable de lo que debiera y perjudicar\u00e1 el buen funcionamiento agron\u00f3mico de otros, y con ello su rentabilidad (como ma\u00edz, cereales, oleaginosas y legumbres).<\/p>\n<p>Para hacer campa\u00f1as m\u00e1s cortas, la industria azucarera tiene que mejorar la capacidad de molienda de sus f\u00e1bricas, que permanece invariable desde hace a\u00f1os debido a que, ante las dudas que planteaba el cultivo, las empresas no han hecho las inversiones que s\u00ed se han hecho en otras f\u00e1bricas de Europa.<\/p>\n<p>ASAJA. Le\u00f3n, 2 de mayo de 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante las expectativas de un incremento\u00a0 importante de las siembras de remolacha para esta campa\u00f1a 2024-2025, que podr\u00eda llegar en la provincia de Le\u00f3n a las 10.000 hect\u00e1reas, frente a las 7.000 de la pasada, la organizaci\u00f3n agraria ASAJA reclama una mejor planificaci\u00f3n para que la mayor\u00eda se molture en el a\u00f1o natural o en [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":9546,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA pide a Azucarera que planifique mejor sus campa\u00f1as para que la remolacha no est\u00e9 tanto tiempo en las fincas - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Ante las expectativas de un incremento\u00a0 importante de las siembras de remolacha para esta campa\u00f1a 2024-2025, que podr\u00eda llegar en la provincia de Le\u00f3n a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA pide a Azucarera que planifique mejor sus campa\u00f1as para que la remolacha no est\u00e9 tanto tiempo en las fincas - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Ante las expectativas de un incremento\u00a0 importante de las siembras de remolacha para esta campa\u00f1a 2024-2025, que podr\u00eda llegar en la provincia de Le\u00f3n a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T07:30:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-17T08:19:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/12\/planta_remolacha.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas\",\"name\":\"ASAJA pide a Azucarera que planifique mejor sus campa\u00f1as para que la remolacha no est\u00e9 tanto tiempo en las fincas - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/12\/planta_remolacha.jpg\",\"datePublished\":\"2024-05-02T07:30:41+00:00\",\"dateModified\":\"2024-05-17T08:19:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Ante las expectativas de un incremento\u00a0 importante de las siembras de remolacha para esta campa\u00f1a 2024-2025, que podr\u00eda llegar en la provincia de Le\u00f3n a\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/12\/planta_remolacha.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/12\/planta_remolacha.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA pide a Azucarera que planifique mejor sus campa\u00f1as para que la remolacha no est\u00e9 tanto tiempo en las fincas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA pide a Azucarera que planifique mejor sus campa\u00f1as para que la remolacha no est\u00e9 tanto tiempo en las fincas - ASAJA Le\u00f3n","description":"Ante las expectativas de un incremento\u00a0 importante de las siembras de remolacha para esta campa\u00f1a 2024-2025, que podr\u00eda llegar en la provincia de Le\u00f3n a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas","og_locale":"es_ES","og_type":"article","og_title":"ASAJA pide a Azucarera que planifique mejor sus campa\u00f1as para que la remolacha no est\u00e9 tanto tiempo en las fincas - ASAJA Le\u00f3n","og_description":"Ante las expectativas de un incremento\u00a0 importante de las siembras de remolacha para esta campa\u00f1a 2024-2025, que podr\u00eda llegar en la provincia de Le\u00f3n a","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2024-05-02T07:30:41+00:00","article_modified_time":"2024-05-17T08:19:35+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/12\/planta_remolacha.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas","name":"ASAJA pide a Azucarera que planifique mejor sus campa\u00f1as para que la remolacha no est\u00e9 tanto tiempo en las fincas - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/12\/planta_remolacha.jpg","datePublished":"2024-05-02T07:30:41+00:00","dateModified":"2024-05-17T08:19:35+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Ante las expectativas de un incremento\u00a0 importante de las siembras de remolacha para esta campa\u00f1a 2024-2025, que podr\u00eda llegar en la provincia de Le\u00f3n a","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/12\/planta_remolacha.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2018\/12\/planta_remolacha.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-pide-a-azucarera-que-planifique-mejor-sus-campanas-para-que-la-remolacha-no-este-tanto-tiempo-en-las-fincas#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ASAJA pide a Azucarera que planifique mejor sus campa\u00f1as para que la remolacha no est\u00e9 tanto tiempo en las fincas"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15342"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=15342"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15342\/revisions"}],"predecessor-version":[{"id":15343,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15342\/revisions\/15343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/9546"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=15342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=15342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=15342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}