{"id":15379,"date":"2024-05-24T09:13:19","date_gmt":"2024-05-24T07:13:19","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=15379"},"modified":"2024-05-24T09:13:23","modified_gmt":"2024-05-24T07:13:23","slug":"lectura-unica","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica","title":{"rendered":"Lectura \u00fanica"},"content":{"rendered":"\n<p>Yo, m\u00e1s o menos, conoc\u00eda lo que significaba eso del procedimiento de lectura \u00fanica a la hora de aprobar una ley en un parlamento, pero para no meter la pata en este art\u00edculo, he recurrido, como todo hijo de vecino, al buscador Google. Este me dice que es el que \u201cse aplica a iniciativas legislativas cuya naturaleza aconseja o cuya simplicidad permite su tramitaci\u00f3n directa por el Pleno, sin emplear las fases de comisi\u00f3n y ponencia\u201d. Bueno, pues en esto andan en las Cortes de Castilla y Le\u00f3n, a iniciativa de los grupos parlamentarios del PP y de Vox, respecto a una modificaci\u00f3n de la Ley de Sanidad Animal de Castilla y Le\u00f3n. La \u00fanica raz\u00f3n es dar cobertura legal, porque no la ten\u00eda,\u00a0 a un aspecto de la\u00a0 Orden de saneamiento ganadero, ya publicada, seg\u00fan el cual los ganaderos pueden contratar a veterinarios de parte para que le realicen las pruebas oficiales de saneamiento ganadero en la enfermedad de la tuberculosis bovina. Para que nos entendamos, esto es como si en vez de tener que ir con nuestro coche a la ITV, pudi\u00e9ramos sustituirlo por un certificado de idoneidad que nos expidiera un ingeniero colegiado contratado por nuestra cuenta. Sin entrar en el debate de lo que esto significa, ni sus consecuencias para una provincia como la de Le\u00f3n donde despu\u00e9s de mucho coste y sacrificio la ganader\u00eda se encentra oficialmente libre de esa enfermedad, tengo que decir que el asunto, ni por su naturaleza ni por su simplicidad, deber\u00eda de haberse cursado por el procedimiento de lectura \u00fanica. Claro que, quien ten\u00eda la obligaci\u00f3n de abrir el debate, que no es otro que el principal partido de la oposici\u00f3n, el PSOE, se ha visto arrastrado, contra sus propios principios e ideolog\u00eda, por la corriente populista de abrir la mano para que cada cual haga en su explotaci\u00f3n lo que le venga en gana respecto a estas cuestiones sanitarias. \u00bfY qu\u00e9 opinan los Colegios Veterinarios? Los Colegios no opinan nada, se han lavado las manos como Pilatos y que cada colegiado se gane la vida como mejor pueda. No vaya a ser que se enfaden en la Junta y\u2026.<\/p>\n<p><em>*Art\u00edculo de opini\u00f3n de Jos\u00e9 Antonio Turrado publicado en La Nueva Cr\u00f3nica del viernes 24 de mayo de 2024.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yo, m\u00e1s o menos, conoc\u00eda lo que significaba eso del procedimiento de lectura \u00fanica a la hora de aprobar una ley en un parlamento, pero para no meter la pata en este art\u00edculo, he recurrido, como todo hijo de vecino, al buscador Google. Este me dice que es el que \u201cse aplica a iniciativas legislativas [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":15380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lectura \u00fanica - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Yo, m\u00e1s o menos, conoc\u00eda lo que significaba eso del procedimiento de lectura \u00fanica a la hora de aprobar una ley en un parlamento, pero para no meter la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lectura \u00fanica - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Yo, m\u00e1s o menos, conoc\u00eda lo que significaba eso del procedimiento de lectura \u00fanica a la hora de aprobar una ley en un parlamento, pero para no meter la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-24T07:13:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-24T07:13:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/05\/lectura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica\",\"name\":\"Lectura \u00fanica - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/05\/lectura.jpg\",\"datePublished\":\"2024-05-24T07:13:19+00:00\",\"dateModified\":\"2024-05-24T07:13:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Yo, m\u00e1s o menos, conoc\u00eda lo que significaba eso del procedimiento de lectura \u00fanica a la hora de aprobar una ley en un parlamento, pero para no meter la\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/05\/lectura.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/05\/lectura.jpg\",\"width\":2500,\"height\":1563,\"caption\":\"Education e-learning class and e-book digital technology concept with computer notebook and opening book flipping on classroom desk in school library among old stacks of textbook archive collection\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lectura \u00fanica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lectura \u00fanica - ASAJA Le\u00f3n","description":"Yo, m\u00e1s o menos, conoc\u00eda lo que significaba eso del procedimiento de lectura \u00fanica a la hora de aprobar una ley en un parlamento, pero para no meter la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica","og_locale":"es_ES","og_type":"article","og_title":"Lectura \u00fanica - ASAJA Le\u00f3n","og_description":"Yo, m\u00e1s o menos, conoc\u00eda lo que significaba eso del procedimiento de lectura \u00fanica a la hora de aprobar una ley en un parlamento, pero para no meter la","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2024-05-24T07:13:19+00:00","article_modified_time":"2024-05-24T07:13:23+00:00","og_image":[{"width":2500,"height":1563,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/05\/lectura.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica","name":"Lectura \u00fanica - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/05\/lectura.jpg","datePublished":"2024-05-24T07:13:19+00:00","dateModified":"2024-05-24T07:13:23+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Yo, m\u00e1s o menos, conoc\u00eda lo que significaba eso del procedimiento de lectura \u00fanica a la hora de aprobar una ley en un parlamento, pero para no meter la","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/05\/lectura.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/05\/lectura.jpg","width":2500,"height":1563,"caption":"Education e-learning class and e-book digital technology concept with computer notebook and opening book flipping on classroom desk in school library among old stacks of textbook archive collection"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/lectura-unica#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Lectura \u00fanica"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15379"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=15379"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15379\/revisions"}],"predecessor-version":[{"id":15381,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15379\/revisions\/15381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/15380"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=15379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=15379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=15379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}