{"id":15416,"date":"2024-06-05T10:43:17","date_gmt":"2024-06-05T08:43:17","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=15416"},"modified":"2024-06-14T10:54:01","modified_gmt":"2024-06-14T08:54:01","slug":"asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas","title":{"rendered":"ASAJA se opone a que el proyecto regional \u00abLa Robla Green\u00bb expropie fincas r\u00fasticas"},"content":{"rendered":"\n<p>La organizaci\u00f3n agraria ASAJA, en coherencia con lo que viene manifestando en todos los proyectos energ\u00e9ticos, se opone al proyecto de energ\u00edas renovables que ha proyectado la empresa Desarrollo Renovables Abies, S.L., en la localidad de la Robla, conocido como \u201cLa Robla Green\u201d, por conllevar una ordenaci\u00f3n del territorio, para atender los intereses empresariales, &nbsp;que supone la expropiaci\u00f3n de 171 parcelas r\u00fasticas, que en su mayor\u00eda son prados de regad\u00edo.<\/p>\n\n\n\n<p>El proyecto ha iniciado el proceso de aprobaci\u00f3n por la Consejer\u00eda de&nbsp; Medio Ambiente, Vivienda y Ordenaci\u00f3n del Territorio, con la publicaci\u00f3n en el d\u00eda de hoy en el Bolet\u00edn Oficial de la Provincia. La organizaci\u00f3n presentar\u00e1 las alegaciones oportunas, en el plazo establecido, y los recursos al mismo cuando sea el momento de hacerlo.<\/p>\n\n\n\n<p>La organizaci\u00f3n agraria ASAJA no est\u00e1 en contra de las actuaciones en energ\u00edas renovables, del tipo que sean, y en este coso puede tener un componente de inter\u00e9s para los agricultores al sustentarse en el consumo de paja de ma\u00edz, lo que merece el apoyo, pero el promotor debe de buscar el entendimiento con los propietarios para adquirir los terrenos y no actuar por las bravas aplicando normas expropiatorias,&nbsp; y debe de buscar ubicaciones que causen el menor da\u00f1o posible al suelo agr\u00edcola. ASAJA no va a permitir, sin antes utilizar todos sus recursos para evitarlo, que cualquiera con una \u201cbuena cartera\u201d pueda comprarlo todo, hasta voluntades, para pasar por encima de los agricultores y ganaderos de la provincia.<\/p>\n\n\n\n<p>ASAJA. Le\u00f3n, 5 de junio de 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n agraria ASAJA, en coherencia con lo que viene manifestando en todos los proyectos energ\u00e9ticos, se opone al proyecto de energ\u00edas renovables que ha proyectado la empresa Desarrollo Renovables Abies, S.L., en la localidad de la Robla, conocido como \u201cLa Robla Green\u201d, por conllevar una ordenaci\u00f3n del territorio, para atender los intereses empresariales, &nbsp;que [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":15417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA se opone a que el proyecto regional &quot;La Robla Green&quot; expropie fincas r\u00fasticas - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La organizaci\u00f3n agraria ASAJA, en coherencia con lo que viene manifestando en todos los proyectos energ\u00e9ticos, se opone al proyecto de energ\u00edas renovables\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA se opone a que el proyecto regional &quot;La Robla Green&quot; expropie fincas r\u00fasticas - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n agraria ASAJA, en coherencia con lo que viene manifestando en todos los proyectos energ\u00e9ticos, se opone al proyecto de energ\u00edas renovables\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-05T08:43:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-14T08:54:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/06\/La-Robla-Green.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"662\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas\",\"name\":\"ASAJA se opone a que el proyecto regional \\\"La Robla Green\\\" expropie fincas r\u00fasticas - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/06\/La-Robla-Green.jpg\",\"datePublished\":\"2024-06-05T08:43:17+00:00\",\"dateModified\":\"2024-06-14T08:54:01+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"La organizaci\u00f3n agraria ASAJA, en coherencia con lo que viene manifestando en todos los proyectos energ\u00e9ticos, se opone al proyecto de energ\u00edas renovables\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/06\/La-Robla-Green.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/06\/La-Robla-Green.jpg\",\"width\":662,\"height\":333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA se opone a que el proyecto regional \u00abLa Robla Green\u00bb expropie fincas r\u00fasticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA se opone a que el proyecto regional \"La Robla Green\" expropie fincas r\u00fasticas - ASAJA Le\u00f3n","description":"La organizaci\u00f3n agraria ASAJA, en coherencia con lo que viene manifestando en todos los proyectos energ\u00e9ticos, se opone al proyecto de energ\u00edas renovables","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas","og_locale":"es_ES","og_type":"article","og_title":"ASAJA se opone a que el proyecto regional \"La Robla Green\" expropie fincas r\u00fasticas - ASAJA Le\u00f3n","og_description":"La organizaci\u00f3n agraria ASAJA, en coherencia con lo que viene manifestando en todos los proyectos energ\u00e9ticos, se opone al proyecto de energ\u00edas renovables","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2024-06-05T08:43:17+00:00","article_modified_time":"2024-06-14T08:54:01+00:00","og_image":[{"width":662,"height":333,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/06\/La-Robla-Green.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas","name":"ASAJA se opone a que el proyecto regional \"La Robla Green\" expropie fincas r\u00fasticas - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/06\/La-Robla-Green.jpg","datePublished":"2024-06-05T08:43:17+00:00","dateModified":"2024-06-14T08:54:01+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"La organizaci\u00f3n agraria ASAJA, en coherencia con lo que viene manifestando en todos los proyectos energ\u00e9ticos, se opone al proyecto de energ\u00edas renovables","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/06\/La-Robla-Green.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/06\/La-Robla-Green.jpg","width":662,"height":333},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-opone-a-que-el-proyecto-regional-la-robla-green-expropie-fincas-rusticas#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ASAJA se opone a que el proyecto regional \u00abLa Robla Green\u00bb expropie fincas r\u00fasticas"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15416"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=15416"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15416\/revisions"}],"predecessor-version":[{"id":15418,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15416\/revisions\/15418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/15417"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=15416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=15416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=15416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}