{"id":1561,"date":"2013-05-07T00:00:00","date_gmt":"2013-05-06T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2013\/05\/07\/jornada-de-campo-aimcra-2013\/"},"modified":"2017-11-15T09:41:11","modified_gmt":"2017-11-15T08:41:11","slug":"jornada-de-campo-aimcra-2013","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013","title":{"rendered":"JORNADA DE CAMPO AIMCRA 2013"},"content":{"rendered":"<h2><\/h2>\n<div align=\"center\"><font color=\"#003300\"><b>ACTIVIDAD: Jornada de Campo de Remolacha Azucarera; 4 de Junio. <\/b>(10.30 &#8211; 17.00)<\/font><\/div>\n<div align=\"justify\"><b><\/b><\/div>\n<div align=\"justify\">Esta Jornada de Campo, organizada por el Plan 2014 y AIMCRA, &#160;es equivalente a las que hemos celebrado en los &#250;ltimos a&#241;os en el mes de septiembre, y est&#225; dirigida a agricultores y t&#233;cnicos interesados en el cultivo de la remolacha y en el riego. El lugar de celebraci&#243;n est&#225; situado en el t&#233;rmino de Villamarciel (Valladolid), en dos parcelas pertenecientes a las comunidades de regantes de Geria-Villamarciel y del Canal de Tordesillas, ambas modernizadas. <\/div>\n<div align=\"justify\">Todos los asistentes tendr&#225;n ocasi&#243;n de hacer un recorrido guiado, con visita de varios campos demostrativos de remolacha (fecha de siembra, herbicidas, densidad de siembra, variedades tolerantes a nematodos,&#8230;) y otros relacionadas con el riego (riego inteligente, automatismos, programadores, riego por goteo, cobertura total enterrada, emisores de baja presi&#243;n, sondas de humedad&#8230;). <\/div>\n<div>El programa previsto es el siguiente:<\/div>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\" align=\"left\">\n<tbody>\n<tr>\n<td width=\"149\">\n<div align=\"center\">9:00<\/div>\n<\/td>\n<td width=\"387\">\n<div>Apertura a los expositores<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"149\">\n<div align=\"center\">10:30<\/div>\n<\/td>\n<td width=\"387\">\n<div>Apertura al p&#250;blico. Visitas y recorridos<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"149\">\n<div align=\"center\">10:30-13:00<\/div>\n<\/td>\n<td width=\"387\">\n<div>Visitas y recorridos a campos demostrativos, ensayos y stands<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"149\">\n<div align=\"center\">13:00-14:00<\/div>\n<\/td>\n<td width=\"387\">\n<div>Comunicaciones de la organizaci&#243;n y patrocinadores.<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"149\">\n<div align=\"center\">14:00-14:30<\/div>\n<\/td>\n<td width=\"387\">\n<div>Intervenciones institucionales y entrega de premios<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"149\">\n<div align=\"center\">14:30-16:30<\/div>\n<\/td>\n<td width=\"387\">\n<div>Almuerzo<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"149\">\n<div align=\"center\">16:30<\/div>\n<\/td>\n<td width=\"387\">\n<div>Fin de la Jornada<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div>&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160;&#160; <\/div>\n<div>&#160;<\/div>\n<div>&#160;<\/div>\n<div>&#160;<\/div>\n<div>&#160;<\/div>\n<div>&#160;<\/div>\n<div>&#160;<\/div>\n<div>&#160;<\/div>\n<div align=\"justify\">Como en ediciones anteriores, est&#225; previsto hacer un reconocimiento a aquellos agricultores que se han distinguido por sus resultados en la campa&#241;a 2012-13. <\/div>\n<p align=\"justify\">Adem&#225;s podremos disfrutar de una magn&#237;fica comida campestre, y existir&#225; un bar abierto durante el transcurso de la jornada, de forma que cada asistente pueda tomar algo cuando desee. La asistencia a esta actividad es gratuita, pero es necesario inscribirse a trav&#233;s de la p&#225;gina web <a href=\"http:\/\/www.aimcra.es\/\">www.aimcra.es<\/a> o llamando al tel&#233;fono 983204777 antes del pr&#243;ximo d&#237;a 28 de mayo<\/p>\n<p align=\"justify\">&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACTIVIDAD: Jornada de Campo de Remolacha Azucarera; 4 de Junio. (10.30 &#8211; 17.00) Esta Jornada de Campo, organizada por el Plan 2014 y AIMCRA, &#160;es equivalente a las que hemos celebrado en los &#250;ltimos a&#241;os en el mes de septiembre, y est&#225; dirigida a agricultores y t&#233;cnicos interesados en el cultivo de la remolacha y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>JORNADA DE CAMPO AIMCRA 2013 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"ACTIVIDAD: Jornada de Campo de Remolacha Azucarera; 4 de Junio. (10.30 - 17.00) Esta Jornada de Campo, organizada por el Plan 2014 y AIMCRA, &#160;es\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JORNADA DE CAMPO AIMCRA 2013 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"ACTIVIDAD: Jornada de Campo de Remolacha Azucarera; 4 de Junio. (10.30 - 17.00) Esta Jornada de Campo, organizada por el Plan 2014 y AIMCRA, &#160;es\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-06T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T08:41:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013\",\"name\":\"JORNADA DE CAMPO AIMCRA 2013 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2013-05-06T22:00:00+00:00\",\"dateModified\":\"2017-11-15T08:41:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"ACTIVIDAD: Jornada de Campo de Remolacha Azucarera; 4 de Junio. (10.30 - 17.00) Esta Jornada de Campo, organizada por el Plan 2014 y AIMCRA, &#160;es\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JORNADA DE CAMPO AIMCRA 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JORNADA DE CAMPO AIMCRA 2013 - ASAJA Le\u00f3n","description":"ACTIVIDAD: Jornada de Campo de Remolacha Azucarera; 4 de Junio. (10.30 - 17.00) Esta Jornada de Campo, organizada por el Plan 2014 y AIMCRA, &#160;es","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013","og_locale":"es_ES","og_type":"article","og_title":"JORNADA DE CAMPO AIMCRA 2013 - ASAJA Le\u00f3n","og_description":"ACTIVIDAD: Jornada de Campo de Remolacha Azucarera; 4 de Junio. (10.30 - 17.00) Esta Jornada de Campo, organizada por el Plan 2014 y AIMCRA, &#160;es","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2013-05-06T22:00:00+00:00","article_modified_time":"2017-11-15T08:41:11+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013","name":"JORNADA DE CAMPO AIMCRA 2013 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2013-05-06T22:00:00+00:00","dateModified":"2017-11-15T08:41:11+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"ACTIVIDAD: Jornada de Campo de Remolacha Azucarera; 4 de Junio. (10.30 - 17.00) Esta Jornada de Campo, organizada por el Plan 2014 y AIMCRA, &#160;es","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/jornada-de-campo-aimcra-2013#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"JORNADA DE CAMPO AIMCRA 2013"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1561"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=1561"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1561\/revisions"}],"predecessor-version":[{"id":1954,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/1561\/revisions\/1954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=1561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=1561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=1561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}