{"id":15648,"date":"2024-09-13T08:52:34","date_gmt":"2024-09-13T06:52:34","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=15648"},"modified":"2024-09-20T11:45:51","modified_gmt":"2024-09-20T09:45:51","slug":"las-seis-noticias-agrarias-de-la-semana-13-09-2024","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 13\/09\/2024"},"content":{"rendered":"\n<h2><strong>MicroBank, <\/strong><strong>\u201cexcelente colaboraci\u00f3n\u201d de los Gobiernos de Espa\u00f1a y Reino Unido, excelencia en la agricultura, enfermedad hemorr\u00e1gica epizo\u00f3tica, reglamento de veh\u00edculos hist\u00f3ricos, agricultura 4.0<\/strong><strong>\u00a0<\/strong><\/h2>\n<ol>\n<li>\n<h6>ASAJA ha firmado recientemente un convenio con <strong>MicroBank<\/strong>, con el objetivo de establecer una <strong>l\u00ednea de financiaci\u00f3n espec\u00edfica para los asociados. <\/strong>Este acuerdo est\u00e1 dirigido a fomentar el autoempleo e incentivar la actividad emprendedora, as\u00ed como que se financie el establecimiento, consolidaci\u00f3n o ampliaci\u00f3n <strong>de microempresas, negocios de aut\u00f3nomos y proyectos de autoempleo <\/strong>y contribuir al desarrollo del tejido productivo, la creaci\u00f3n y consolidaci\u00f3n de empleo y la contribuci\u00f3n al progreso social.<\/h6>\n<\/li>\n<li>\n<h6>El ministro de Agricultura, Pesca y Alimentaci\u00f3n, Luis Planas, ha destacado la <strong>\u201cexcelente colaboraci\u00f3n\u201d de los Gobiernos de Espa\u00f1a y Reino Unido<\/strong>, que ha permitido que este pa\u00eds se mantenga como uno de los principales mercados para los productos agroalimentarios espa\u00f1oles despu\u00e9s del \u201cBrexit\u201d, y ha destacado que esta coordinaci\u00f3n se va a ver reforzada con el nuevo Ejecutivo brit\u00e1nico. Planas se ha reunido, en Londres, con el secretario de Estado de Medio Ambiente, Alimentaci\u00f3n y Medio Rural, Steve Reed, con quien ha abordado distintos aspectos de esta colaboraci\u00f3n.<\/h6>\n<\/li>\n<li>\n<h6>El Ministerio de Agricultura ha otorgado el\u00a0 primer\u00a0 premio a la <strong><em>excelencia en la agricultura<\/em><\/strong> a la ganader\u00eda extensiva Oma\u00f1a Cea T.C., ubicada en Muria de Paredes (Le\u00f3n), que cuenta con su propia sala de despiece. Adem\u00e1s, posee una<a href=\"https:\/\/www.tuterneraencasa.com\/\">p\u00e1gina web<\/a>\u00a0a trav\u00e9s de la cual vende directamente tanto sus productos (carne de ternera y platos elaborados) como los de otros productores locales. Con estos premios, el ministerio muestra su compromiso con las pol\u00edticas que impulsan la igualdad de g\u00e9nero plena, favorecen el acceso de las j\u00f3venes a la actividad agraria y fomentan la diversificaci\u00f3n de la actividad econ\u00f3mica del medio rural, lo que contribuye a frenar el despoblamiento de estos entornos. El premio est\u00e1 dotado con 18.000 euros.<\/h6>\n<\/li>\n<li>\n<h6>La Consejer\u00eda de Agricultura y Ganader\u00eda de la\u00a0 Junta de Castilla y Le\u00f3n ha comunicado que publicar\u00e1 una ayuda a las explotaciones afectadas por la <strong>Enfermedad Hemorr\u00e1gica Epizo\u00f3tica<\/strong> en el a\u00f1o 2023, que no\u00a0 la percibieron en dicho a\u00f1o. A la vez, se ha comprometido a una nueva convocatoria de ayudas para las explotaciones afectadas durante 2024, y ser\u00e1n aquellas con patolog\u00edas comunicadas y confirmadas con los an\u00e1lisis oficiales pertinentes.<\/h6>\n<\/li>\n<li>\n<h6>El Consejo de Ministros del martes d\u00eda 10 de septiembre aprob\u00f3 un real decreto por el que se aprueba el <strong>reglamento de veh\u00edculos hist\u00f3ricos<\/strong>. La principal caracter\u00edstica para ser catalogados as\u00ed es haberse fabricado y matriculado hace m\u00e1s de treinta a\u00f1os. Se establece un procedimiento abreviado para la clasificaci\u00f3n de los mismos. Esta normativa incluye tambi\u00e9n a los tractores agr\u00edcolas.<\/h6>\n<\/li>\n<li>\n<h6>La organizaci\u00f3n agraria ASAJA est\u00e1 impartiendo curso sobre <strong>Agricultura 4.0<\/strong> en las localidades de Valencia de Don Juan, Santa Mar\u00eda del P\u00e1ramo y Sahag\u00fan, contando para ello con la direcci\u00f3n y profesorado del ITAGRA. Estos cursos son gratuitos para los alumnos al contar con financiaci\u00f3n de la Uni\u00f3n Europea y de la Junta de Castilla y Le\u00f3n.<\/h6>\n<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>MicroBank, \u201cexcelente colaboraci\u00f3n\u201d de los Gobiernos de Espa\u00f1a y Reino Unido, excelencia en la agricultura, enfermedad hemorr\u00e1gica epizo\u00f3tica, reglamento de veh\u00edculos hist\u00f3ricos, agricultura 4.0\u00a0 ASAJA ha firmado recientemente un convenio con MicroBank, con el objetivo de establecer una l\u00ednea de financiaci\u00f3n espec\u00edfica para los asociados. Este acuerdo est\u00e1 dirigido a fomentar el autoempleo e incentivar [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":12649,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 13\/09\/2024 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"MicroBank, \u201cexcelente colaboraci\u00f3n\u201d de los Gobiernos de Espa\u00f1a y Reino Unido, excelencia en la agricultura, enfermedad hemorr\u00e1gica epizo\u00f3tica, reglamento\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 13\/09\/2024 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"MicroBank, \u201cexcelente colaboraci\u00f3n\u201d de los Gobiernos de Espa\u00f1a y Reino Unido, excelencia en la agricultura, enfermedad hemorr\u00e1gica epizo\u00f3tica, reglamento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-13T06:52:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-20T09:45:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/09\/Barreiros-R-350-S-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"361\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024\",\"name\":\"Las seis noticias agrarias de la semana - 13\/09\/2024 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/09\/Barreiros-R-350-S-.jpg\",\"datePublished\":\"2024-09-13T06:52:34+00:00\",\"dateModified\":\"2024-09-20T09:45:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"MicroBank, \u201cexcelente colaboraci\u00f3n\u201d de los Gobiernos de Espa\u00f1a y Reino Unido, excelencia en la agricultura, enfermedad hemorr\u00e1gica epizo\u00f3tica, reglamento\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/09\/Barreiros-R-350-S-.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/09\/Barreiros-R-350-S-.jpg\",\"width\":600,\"height\":361},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 13\/09\/2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 13\/09\/2024 - ASAJA Le\u00f3n","description":"MicroBank, \u201cexcelente colaboraci\u00f3n\u201d de los Gobiernos de Espa\u00f1a y Reino Unido, excelencia en la agricultura, enfermedad hemorr\u00e1gica epizo\u00f3tica, reglamento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 13\/09\/2024 - ASAJA Le\u00f3n","og_description":"MicroBank, \u201cexcelente colaboraci\u00f3n\u201d de los Gobiernos de Espa\u00f1a y Reino Unido, excelencia en la agricultura, enfermedad hemorr\u00e1gica epizo\u00f3tica, reglamento","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2024-09-13T06:52:34+00:00","article_modified_time":"2024-09-20T09:45:51+00:00","og_image":[{"width":600,"height":361,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/09\/Barreiros-R-350-S-.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024","name":"Las seis noticias agrarias de la semana - 13\/09\/2024 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/09\/Barreiros-R-350-S-.jpg","datePublished":"2024-09-13T06:52:34+00:00","dateModified":"2024-09-20T09:45:51+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"MicroBank, \u201cexcelente colaboraci\u00f3n\u201d de los Gobiernos de Espa\u00f1a y Reino Unido, excelencia en la agricultura, enfermedad hemorr\u00e1gica epizo\u00f3tica, reglamento","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/09\/Barreiros-R-350-S-.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2021\/09\/Barreiros-R-350-S-.jpg","width":600,"height":361},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13-09-2024#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 13\/09\/2024"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15648"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=15648"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15648\/revisions"}],"predecessor-version":[{"id":15649,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15648\/revisions\/15649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/12649"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=15648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=15648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=15648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}