{"id":15650,"date":"2024-09-13T15:11:55","date_gmt":"2024-09-13T13:11:55","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=15650"},"modified":"2024-09-25T09:56:27","modified_gmt":"2024-09-25T07:56:27","slug":"asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria","title":{"rendered":"Asaja de Le\u00f3n celebr\u00f3 hoy la XXXVIII Asamblea General Ordinaria"},"content":{"rendered":"<p>La organizaci\u00f3n agraria ASAJA de Le\u00f3n celebr\u00f3 hoy en la localidad de Valencia de Don Juan su XXXVIII Asamblea General, acto que se hab\u00eda pospuesto ya que habitualmente este \u00f3rgano de gobierno se re\u00fane en el primer trimestre del a\u00f1o.<\/p>\n<p>Adem\u00e1s del informe de gesti\u00f3n, tanto en la actividad sindical y representativa\u00a0 como de servicios, y de la aprobaci\u00f3n del balance econ\u00f3mico y presupuesto para 2024, se abord\u00f3 la situaci\u00f3n general del campo en la provincia, donde destaca el bajo precio que perciben los\u00a0 cerealistas por su grano, se\u00f1alando, por su importancia cuantitativa, el cultivo del ma\u00edz.\u00a0 A esto se suman unos costes elevados en pr\u00e1cticamente todos los insumos y servicios, como son el gas\u00f3leo, abonos, semillas, fitosanitarios, repuestos, mano de obra, maquinaria, e intereses de los pr\u00e9stamos, entre otros. Consecuencia de todo ellos es que muchas explotaciones, sobre todo cerealistas y de cultivos herb\u00e1ceos en general, \u00a0est\u00e1n produciendo a p\u00e9rdidas. En plena campa\u00f1a de vendimia, la organizaci\u00f3n manifest\u00f3 tambi\u00e9n su preocupaci\u00f3n por los bajos precios de la uva.<\/p>\n<p>Por ser tambi\u00e9n un tema de actualidad que preocupa a los ganaderos, se abord\u00f3 la problem\u00e1tica de la Enfermedad Hemorr\u00e1gica Epizo\u00f3tica y los cambios en el protocolo de la campa\u00f1a oficial de saneamiento ganadero. A este respecto, ASAJA ha pedido que las ayudas\u00a0 por las p\u00e9rdidas ocasionadas por la EHE lleguen pronto a las 83 ganader\u00edas leonesas donde ya se ha confirmado la afecci\u00f3n mediante an\u00e1lisis de PCR.<\/p>\n<p>En las intervenciones del secretario general, Jos\u00e9 Antonio Turrado, del presidente provincial, Arsenio Garc\u00eda Vidal, y en particular en la del presidente regional, Donaciano Dujo, se pidi\u00f3 la revisi\u00f3n del tratado de la Uni\u00f3n Europea con Ucrania para impedir la entrada de cereales baratos que hunden nuestros mercados, as\u00ed como dotar a\u00a0 la Ley de la Cadena Alimentaria de mecanismos que de verdad protejan al productor e impidan la venta a p\u00e9rdidas.<\/p>\n<p>Los responsables de ASAJA exigieron a la Junta de Castilla y Le\u00f3n que resuelva de una vez por todas los expedientes\u00a0 de incorporaci\u00f3n de j\u00f3venes y de modernizaci\u00f3n de explotaciones, y mostraron relativa satisfacci\u00f3n con los cambios que se han introducido este a\u00f1o en la aplicaci\u00f3n de la PAC, de los que se han beneficiado de forma muy particular los productores de ma\u00edz, que no tendr\u00e1n que cumplir con la rotaci\u00f3n de tierras ni con el barbecho obligatorio.<\/p>\n<p>Los responsables de ASAJA reivindicaron infraestructuras como las concentraciones parcelarias, los regad\u00edos y los nuevos regad\u00edos, y reconocieron que el esfuerzo de la Junta y del Estado de los \u00faltimos a\u00f1os ha permitido importantes avances en estas materias.<\/p>\n<h6>La organizaci\u00f3n agraria aprovech\u00f3 tambi\u00e9n la ocasi\u00f3n para exigir que se preserve el suelo agr\u00edcola,\u00a0 oponi\u00e9ndose a la autorizaci\u00f3n de cambio de uso para la instalaci\u00f3n de macroparques fotovoltaicos, y exigiendo que las l\u00edneas de evacuaci\u00f3n de electricidad sean subterr\u00e1neas.<\/h6>\n<h6>Los dirigentes de ASAJA han informado a los socios de que se abre el periodo de posicionamiento sobre la nueva PAC a partir de 2027, y que la organizaci\u00f3n pedir\u00e1 un incremento presupuestario, una apuesta por el modelo de agricultura profesional familiar, y que est\u00e9 dotada de instrumentos para mejorar la competitividad en un mercado cada vez m\u00e1s globalizado que debe de regirse por normas homologables.<\/h6>\n<h6>Le\u00f3n, 13 de septiembre de 2024.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n agraria ASAJA de Le\u00f3n celebr\u00f3 hoy en la localidad de Valencia de Don Juan su XXXVIII Asamblea General, acto que se hab\u00eda pospuesto ya que habitualmente este \u00f3rgano de gobierno se re\u00fane en el primer trimestre del a\u00f1o. Adem\u00e1s del informe de gesti\u00f3n, tanto en la actividad sindical y representativa\u00a0 como de servicios, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":15651,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Asaja de Le\u00f3n celebr\u00f3 hoy la XXXVIII Asamblea General Ordinaria - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La organizaci\u00f3n agraria ASAJA de Le\u00f3n celebr\u00f3 hoy en la localidad de Valencia de Don Juan su XXXVIII Asamblea General, acto que se hab\u00eda pospuesto ya que\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asaja de Le\u00f3n celebr\u00f3 hoy la XXXVIII Asamblea General Ordinaria - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n agraria ASAJA de Le\u00f3n celebr\u00f3 hoy en la localidad de Valencia de Don Juan su XXXVIII Asamblea General, acto que se hab\u00eda pospuesto ya que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-13T13:11:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-25T07:56:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/09\/20240913_123216.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1127\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria\",\"name\":\"Asaja de Le\u00f3n celebr\u00f3 hoy la XXXVIII Asamblea General Ordinaria - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/09\/20240913_123216.jpg\",\"datePublished\":\"2024-09-13T13:11:55+00:00\",\"dateModified\":\"2024-09-25T07:56:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"La organizaci\u00f3n agraria ASAJA de Le\u00f3n celebr\u00f3 hoy en la localidad de Valencia de Don Juan su XXXVIII Asamblea General, acto que se hab\u00eda pospuesto ya que\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/09\/20240913_123216.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/09\/20240913_123216.jpg\",\"width\":2500,\"height\":1127},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asaja de Le\u00f3n celebr\u00f3 hoy la XXXVIII Asamblea General Ordinaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asaja de Le\u00f3n celebr\u00f3 hoy la XXXVIII Asamblea General Ordinaria - ASAJA Le\u00f3n","description":"La organizaci\u00f3n agraria ASAJA de Le\u00f3n celebr\u00f3 hoy en la localidad de Valencia de Don Juan su XXXVIII Asamblea General, acto que se hab\u00eda pospuesto ya que","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria","og_locale":"es_ES","og_type":"article","og_title":"Asaja de Le\u00f3n celebr\u00f3 hoy la XXXVIII Asamblea General Ordinaria - ASAJA Le\u00f3n","og_description":"La organizaci\u00f3n agraria ASAJA de Le\u00f3n celebr\u00f3 hoy en la localidad de Valencia de Don Juan su XXXVIII Asamblea General, acto que se hab\u00eda pospuesto ya que","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2024-09-13T13:11:55+00:00","article_modified_time":"2024-09-25T07:56:27+00:00","og_image":[{"width":2500,"height":1127,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/09\/20240913_123216.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria","name":"Asaja de Le\u00f3n celebr\u00f3 hoy la XXXVIII Asamblea General Ordinaria - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/09\/20240913_123216.jpg","datePublished":"2024-09-13T13:11:55+00:00","dateModified":"2024-09-25T07:56:27+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"La organizaci\u00f3n agraria ASAJA de Le\u00f3n celebr\u00f3 hoy en la localidad de Valencia de Don Juan su XXXVIII Asamblea General, acto que se hab\u00eda pospuesto ya que","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/09\/20240913_123216.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/09\/20240913_123216.jpg","width":2500,"height":1127},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/noticias\/asaja-de-leon-celebro-hoy-la-xxxviii-asamblea-general-ordinaria#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Asaja de Le\u00f3n celebr\u00f3 hoy la XXXVIII Asamblea General Ordinaria"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15650"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=15650"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15650\/revisions"}],"predecessor-version":[{"id":15653,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15650\/revisions\/15653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/15651"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=15650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=15650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=15650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}