{"id":15656,"date":"2024-09-17T11:54:02","date_gmt":"2024-09-17T09:54:02","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=15656"},"modified":"2024-09-27T09:18:17","modified_gmt":"2024-09-27T07:18:17","slug":"asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico","title":{"rendered":"ASAJA celebra que la Consejer\u00eda de Agricultura revise la \u00abUnidad M\u00ednima de Cultivo\u00bb en el suelo r\u00fastico"},"content":{"rendered":"\n<p>La organizaci\u00f3n ASAJA de Le\u00f3n se muestra satisfecha por el anuncio efectuado hoy\u00a0 por la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la Junta de Castilla y Le\u00f3n, Mar\u00eda Gonz\u00e1lez Corral, en la Comisi\u00f3n de Agricultura de las Cortes de Castilla y Le\u00f3n,\u00a0 de \u201ciniciar la tramitaci\u00f3n de la modificaci\u00f3n de la norma reguladora de las unidades m\u00ednimas de cultivo para Castilla y Le\u00f3n\u201d.<\/p>\n<p>Esta es una demanda que se ven\u00eda haciendo desde ASAJA de Le\u00f3n, y as\u00ed se hab\u00eda expuesto en las reuniones del Consejo Agrario Provincial, que por fin la hizo suya en la sesi\u00f3n que se celebr\u00f3 el 14 de marzo de este mismo a\u00f1o en Grajal de Campos. En dicha sesi\u00f3n se aprob\u00f3 la propuesta como propia y se le dio traslado a la Direcci\u00f3n General de Desarrollo Rural.<\/p>\n<p>La normativa\u00a0 en vigor, en esta materia, obsoleta en opini\u00f3n de ASAJA, es el Decreto 76\/1984 de la Comunidad de Castilla y Le\u00f3n, aprobado en la \u00fanica legislatura en la que ha gobernado el PSOE en Castilla y Le\u00f3n. Con las unidades m\u00ednimas de cultivo se trata de evitar que se segreguen las parcelas, degrad\u00e1ndose la mejora conseguida en los procesos de concentraci\u00f3n parcelaria, pr\u00e1ctica que es habitual en muchas familias.<\/p>\n<p>En la provincia de Le\u00f3n, la unidad m\u00ednima de cultivo es de 1 hect\u00e1rea en regad\u00edo y 4 de secano para un grupo de municipios, y de 6 de secano y 2 de regad\u00edo para otro grupo de municipios. ASAJA propondr\u00e1, en el proceso de consulta de la nueva norma que hoy ha anunciado la Consejera, que dichos valores se eleven de forma muy considerable, con el fin de que en la pr\u00e1ctica sea imposible fraccionar una parcela agr\u00edcola.<\/p>\n<p>La provincia de Le\u00f3n, donde se han hecho y se est\u00e1n haciendo importantes inversiones p\u00fablicas en concentraciones y reconcentraciones parcelarias, es no obstante una provincia en la que destaca el minifundismo, dificultando la mecanizaci\u00f3n y quedando devaluadas estas parcelas con el paso del tiempo.<\/p>\n<p>\u00a0<\/p>\n<p>ASAJA. Le\u00f3n, 17 de septiembre de 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n ASAJA de Le\u00f3n se muestra satisfecha por el anuncio efectuado hoy\u00a0 por la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la Junta de Castilla y Le\u00f3n, Mar\u00eda Gonz\u00e1lez Corral, en la Comisi\u00f3n de Agricultura de las Cortes de Castilla y Le\u00f3n,\u00a0 de \u201ciniciar la tramitaci\u00f3n de la modificaci\u00f3n de la norma reguladora [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":14507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA celebra que la Consejer\u00eda de Agricultura revise la &quot;Unidad M\u00ednima de Cultivo&quot; en el suelo r\u00fastico - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La organizaci\u00f3n ASAJA de Le\u00f3n se muestra satisfecha por el anuncio efectuado hoy\u00a0 por la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA celebra que la Consejer\u00eda de Agricultura revise la &quot;Unidad M\u00ednima de Cultivo&quot; en el suelo r\u00fastico - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n ASAJA de Le\u00f3n se muestra satisfecha por el anuncio efectuado hoy\u00a0 por la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T09:54:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-27T07:18:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"344\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico\",\"name\":\"ASAJA celebra que la Consejer\u00eda de Agricultura revise la \\\"Unidad M\u00ednima de Cultivo\\\" en el suelo r\u00fastico - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg\",\"datePublished\":\"2024-09-17T09:54:02+00:00\",\"dateModified\":\"2024-09-27T07:18:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"La organizaci\u00f3n ASAJA de Le\u00f3n se muestra satisfecha por el anuncio efectuado hoy\u00a0 por la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg\",\"width\":612,\"height\":344,\"caption\":\"Tractor cultivating field at spring,aerial view\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA celebra que la Consejer\u00eda de Agricultura revise la \u00abUnidad M\u00ednima de Cultivo\u00bb en el suelo r\u00fastico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA celebra que la Consejer\u00eda de Agricultura revise la \"Unidad M\u00ednima de Cultivo\" en el suelo r\u00fastico - ASAJA Le\u00f3n","description":"La organizaci\u00f3n ASAJA de Le\u00f3n se muestra satisfecha por el anuncio efectuado hoy\u00a0 por la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico","og_locale":"es_ES","og_type":"article","og_title":"ASAJA celebra que la Consejer\u00eda de Agricultura revise la \"Unidad M\u00ednima de Cultivo\" en el suelo r\u00fastico - ASAJA Le\u00f3n","og_description":"La organizaci\u00f3n ASAJA de Le\u00f3n se muestra satisfecha por el anuncio efectuado hoy\u00a0 por la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2024-09-17T09:54:02+00:00","article_modified_time":"2024-09-27T07:18:17+00:00","og_image":[{"width":612,"height":344,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico","name":"ASAJA celebra que la Consejer\u00eda de Agricultura revise la \"Unidad M\u00ednima de Cultivo\" en el suelo r\u00fastico - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg","datePublished":"2024-09-17T09:54:02+00:00","dateModified":"2024-09-27T07:18:17+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"La organizaci\u00f3n ASAJA de Le\u00f3n se muestra satisfecha por el anuncio efectuado hoy\u00a0 por la consejera de Agricultura, Ganader\u00eda y Desarrollo Rural de la","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/08\/finca.jpg","width":612,"height":344,"caption":"Tractor cultivating field at spring,aerial view"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-celebra-que-la-consejeria-de-agricultura-revise-la-unidad-minima-de-cultivo-en-el-suelo-rustico#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ASAJA celebra que la Consejer\u00eda de Agricultura revise la \u00abUnidad M\u00ednima de Cultivo\u00bb en el suelo r\u00fastico"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15656"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=15656"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15656\/revisions"}],"predecessor-version":[{"id":15657,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15656\/revisions\/15657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/14507"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=15656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=15656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=15656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}