{"id":15739,"date":"2024-10-11T15:09:22","date_gmt":"2024-10-11T13:09:22","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=15739"},"modified":"2024-10-25T08:54:54","modified_gmt":"2024-10-25T06:54:54","slug":"los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas","title":{"rendered":"Los agricultores de Castilla y Le\u00f3n reclaman soluciones urgentes que garanticen la continuidad de las explotaciones cerealistas"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Cerca de 500 profesionales del campo se concentran frente a las puertas de la Delegaci\u00f3n del Gobierno, convocados por ASAJA y la Alianza UPA-COAG<\/strong><\/h2>\n\n\n\n<p>Medio millar de profesionales del campo de todas las provincias de Castilla y Le\u00f3n han protestado frente a las puertas de la Delegaci\u00f3n del Gobierno, en Valladolid por la situaci\u00f3n de ruina que soporta el sector cerealista. Convocados en unidad de acci\u00f3n por las organizaciones agrarias ASAJA y la Alianza UPA-COAG, han desplegado una pancarta en la que se le\u00eda \u201cCostes, importaciones y especulaci\u00f3n arruinan nuestra producci\u00f3n\u201d, lema que resume tres de los principales problemas que est\u00e1n descapitalizando a los agricultores y que suponen una amenaza cierta para la continuidad de un sector en una comunidad aut\u00f3noma reconocida hist\u00f3ricamente como \u201cel granero de Espa\u00f1a\u201d.<\/p>\n<p>Durante la concentraci\u00f3n, que comenz\u00f3 a las 12 de la ma\u00f1ana, se han derramado varios sacos de trigo, para subrayar \u201cel sinsentido de que hoy un saco de abono valga m\u00e1s que lo que nos pagan por tres de trigo\u201d, ha denunciado el presidente de ASAJA de Castilla y Le\u00f3n, Donaciano Dujo.<\/p>\n<p>Son ya varias campa\u00f1as consecutivas de n\u00fameros rojos para el sector cerealista, bien a causa de bajas cosechas por la sequ\u00eda, bien por los disparados costes de producci\u00f3n, por el hundimiento de los precios o por la combinaci\u00f3n de varias de ellas. Esta situaci\u00f3n continuada de p\u00e9rdidas est\u00e1 repercutiendo ya en un descenso de las siembras, que seguir\u00e1 ampli\u00e1ndose esta campa\u00f1a si los agricultores no reciben signos claros de que el cereal tiene futuro. As\u00ed, la superficie de siembra hist\u00f3rica en Castilla y Le\u00f3n alcanzaba los 2.000.000 de hect\u00e1reas, y hoy apenas llegan a 1.600.000 hect\u00e1reas, una tendencia que no frenar\u00e1 si los responsables pol\u00edticos no se implican y apoyan al sector.<\/p>\n<p>\u201cEl precio cereal hace dos a\u00f1os fue de 360 euros, ahora apenas 200. Menos de 280 euros es inasumible: mientras que antes de la guerra en Ucrania los costes de producci\u00f3n eran de 500 euros\/ha, y ahora superan los 700\/ha\u201d ha denunciado Donaciano Dujo. El presidente de ASAJA ha cifrado en cerca de 500 millones de euros los que los agricultores de Castilla y Le\u00f3n han dejado de percibir \u201cpor culpa de esa pinza con la que nos est\u00e1n estrangulando, altos costes de producci\u00f3n y precios del cereal hundidos. \u00bfD\u00f3nde se aplica la Ley de la Cadena Alimentaria? Porque en el cereal seguro que no\u201d, se ha preguntado.<\/p>\n<p>Para ASAJA, \u201calguien se est\u00e1 beneficiando y enriqueciendo con todo esto, y no son los agricultores, ni los ganaderos, que siguen pagando el pienso a precios muy altos, en los que para nada se ha repercutido la bajada del cereal\u201d. Ante estos abusos, Donaciano Dujo pide a los responsables pol\u00edticos que act\u00faen, pidan explicaciones y presionen para frenar esta ca\u00edda libre de un sector cerealista que ha sido el orgullo de esta tierra, y que ahora no levanta cabeza\u201d.<\/p>\n<p>Tambi\u00e9n fundamental es que el Gobierno espa\u00f1ol pida en Bruselas que se frenen las importaciones de grano ucranio sin arancel ni ning\u00fan tipo de los controles que se exigen para las producciones europeas. \u201cNo todo vale, ni en tiempos de guerra, no se puede sacrificar al campo espa\u00f1ol. Y si no, que Espa\u00f1a d\u00e9 un paso adelante, como ha hecho Polonia, y compense la p\u00e9rdida que est\u00e1n soportando los agricultores por los efectos indeseados de estos acuerdos\u201d. Todos estos puntos, junto a otras reivindicaciones, se recogen en una Tabla Reivindicativa conjunta (que se adjunta), que las organizaciones agrarias convocantes han depositado hoy en el Registro de la Delegaci\u00f3n del Gobierno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 500 profesionales del campo se concentran frente a las puertas de la Delegaci\u00f3n del Gobierno, convocados por ASAJA y la Alianza UPA-COAG Medio millar de profesionales del campo de todas las provincias de Castilla y Le\u00f3n han protestado frente a las puertas de la Delegaci\u00f3n del Gobierno, en Valladolid por la situaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":15745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los agricultores de Castilla y Le\u00f3n reclaman soluciones urgentes que garanticen la continuidad de las explotaciones cerealistas - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Cerca de 500 profesionales del campo se concentran frente a las puertas de la Delegaci\u00f3n del Gobierno, convocados por ASAJA y la Alianza UPA-COAG Medio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los agricultores de Castilla y Le\u00f3n reclaman soluciones urgentes que garanticen la continuidad de las explotaciones cerealistas - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Cerca de 500 profesionales del campo se concentran frente a las puertas de la Delegaci\u00f3n del Gobierno, convocados por ASAJA y la Alianza UPA-COAG Medio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-11T13:09:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-25T06:54:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/10\/PROTESTA-SACO-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas\",\"name\":\"Los agricultores de Castilla y Le\u00f3n reclaman soluciones urgentes que garanticen la continuidad de las explotaciones cerealistas - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/10\/PROTESTA-SACO-3.jpg\",\"datePublished\":\"2024-10-11T13:09:22+00:00\",\"dateModified\":\"2024-10-25T06:54:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Cerca de 500 profesionales del campo se concentran frente a las puertas de la Delegaci\u00f3n del Gobierno, convocados por ASAJA y la Alianza UPA-COAG Medio\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/10\/PROTESTA-SACO-3.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/10\/PROTESTA-SACO-3.jpg\",\"width\":2048,\"height\":767},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los agricultores de Castilla y Le\u00f3n reclaman soluciones urgentes que garanticen la continuidad de las explotaciones cerealistas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los agricultores de Castilla y Le\u00f3n reclaman soluciones urgentes que garanticen la continuidad de las explotaciones cerealistas - ASAJA Le\u00f3n","description":"Cerca de 500 profesionales del campo se concentran frente a las puertas de la Delegaci\u00f3n del Gobierno, convocados por ASAJA y la Alianza UPA-COAG Medio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas","og_locale":"es_ES","og_type":"article","og_title":"Los agricultores de Castilla y Le\u00f3n reclaman soluciones urgentes que garanticen la continuidad de las explotaciones cerealistas - ASAJA Le\u00f3n","og_description":"Cerca de 500 profesionales del campo se concentran frente a las puertas de la Delegaci\u00f3n del Gobierno, convocados por ASAJA y la Alianza UPA-COAG Medio","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2024-10-11T13:09:22+00:00","article_modified_time":"2024-10-25T06:54:54+00:00","og_image":[{"width":2048,"height":767,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/10\/PROTESTA-SACO-3.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas","name":"Los agricultores de Castilla y Le\u00f3n reclaman soluciones urgentes que garanticen la continuidad de las explotaciones cerealistas - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/10\/PROTESTA-SACO-3.jpg","datePublished":"2024-10-11T13:09:22+00:00","dateModified":"2024-10-25T06:54:54+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Cerca de 500 profesionales del campo se concentran frente a las puertas de la Delegaci\u00f3n del Gobierno, convocados por ASAJA y la Alianza UPA-COAG Medio","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/10\/PROTESTA-SACO-3.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/10\/PROTESTA-SACO-3.jpg","width":2048,"height":767},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-agricultores-de-castilla-y-leon-reclaman-soluciones-urgentes-que-garanticen-la-continuidad-de-las-explotaciones-cerealistas#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Los agricultores de Castilla y Le\u00f3n reclaman soluciones urgentes que garanticen la continuidad de las explotaciones cerealistas"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15739"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=15739"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15739\/revisions"}],"predecessor-version":[{"id":15741,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15739\/revisions\/15741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/15745"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=15739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=15739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=15739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}