{"id":15799,"date":"2024-11-08T11:10:51","date_gmt":"2024-11-08T10:10:51","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=15799"},"modified":"2024-11-21T11:28:16","modified_gmt":"2024-11-21T10:28:16","slug":"las-seis-noticias-agrarias-de-la-semana-08-11-2024","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 08\/11\/2024"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Deforestaci\u00f3n<\/strong>, <strong>Christophe Hansen<\/strong>, <strong>DANA<\/strong>, <strong>Producci\u00f3n alimentaria en t\u00e9rminos de cantidad y calidad<\/strong>, <strong>Embalses leoneses de la Cuenca del Duero<\/strong>, <strong>Seguro de rendimientos en cereales y otros cultivos herb\u00e1ceos<\/strong><\/h2>\n\n\n\n<ol>\n<li>Consejo y Parlamento han dado su visto bueno a la propuesta de la Comisi\u00f3n Europea de modificaci\u00f3n espec\u00edfica del Reglamento de la UE sobre la <strong>deforestaci\u00f3n,<\/strong> aplazando su fecha de aplicaci\u00f3n 12 meses. La Comisi\u00f3n present\u00f3 su propuesta de aplazamiento de la fecha de aplicaci\u00f3n del Reglamento sobre deforestaci\u00f3n en respuesta a las preocupaciones planteadas por los Estados miembros, terceros pa\u00edses, comerciantes y operadores de que exist\u00eda el riesgo de que no pudieran cumplir plenamente las normas a m\u00e1s tardar el 31 de diciembre de 2024.<\/li>\n<\/ol>\n<ol start=\"2\">\n<li>El martes 5 de noviembre se ha dado a conocer la aprobaci\u00f3n de <strong>Christophe Hansen<\/strong> como nuevo comisario de Agricultura y Alimentaci\u00f3n de la Comisi\u00f3n Europea. Esto se ha producido tras la audici\u00f3n al candidato el lunes 4 de noviembre, cuando ha tenido lugar el proceso de audiciones a los candidatos a comisarios por parte del Parlamento Europeo y entre ellos, el luxemburgu\u00e9s Christophe Hansen, que se ha sometido a las preguntas de los miembros de la Comisi\u00f3n de Agricultura y Desarrollo Rural del Parlamento Europeo.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li>La Junta Directiva de ASAJA, celebrada el pasado lunes en Madrid, tuvo como primer punto del orden del d\u00eda la cat\u00e1strofe provocada por la <strong>DANA<\/strong> que asol\u00f3 hace seis d\u00edas buena parte de la Comunidad Valenciana, y algunos municipios de las provincias de Cuenca, Albacete, Almer\u00eda y M\u00e1laga. Los representantes de los agricultores y ganaderos de toda Espa\u00f1a han guardado un minuto de silencio en recuerdo de las v\u00edctimas de las inundaciones y han pedido al Gobierno la m\u00e1xima implicaci\u00f3n en las tareas de recuperaci\u00f3n de los municipios afectados y un plan de infraestructuras hidr\u00e1ulicas ambicioso que permita el m\u00e1ximo aprovechamiento de los recursos y en la medida de lo posible evitar que se produzcan cat\u00e1strofes similares en un futuro.<\/li>\n<\/ol>\n<ol start=\"4\">\n<li>El ministro de Agricultura, Pesca y Alimentaci\u00f3n, Luis Planas, considera que Espa\u00f1a va \u201cpor la v\u00eda correcta\u201d para dar respuesta a la necesidad de mantener, e incluso ampliar, la <strong>producci\u00f3n alimentaria en t\u00e9rminos de cantidad y calidad<\/strong>. Y todo ello, en \u201cun contexto de cada vez mayores dificultades\u201d y en el que ha resaltado que el sector primario ha sido capaz de hacer un uso del agua de regad\u00edo \u201cno solo necesario, sino inteligente\u201d.<\/li>\n<\/ol>\n<ol start=\"5\">\n<li>La situaci\u00f3n de los <strong>embalses leoneses de la Cuenca del Duero<\/strong>, cuando ha\u00a0 pasado un mes del inicio\u00a0 del nuevo a\u00f1o hidrol\u00f3gico, es buena, y almacenan ya 652 hect\u00f3metros c\u00fabicos, el 50% de su capacidad total. El que est\u00e1 en peor situaci\u00f3n es el de Villameca ya que la zona ha recibido menos precipitaciones que el resto.<\/li>\n<\/ol>\n<ol start=\"6\">\n<li>ASAJA recuerda que es el momento de suscribir el <strong>seguro de rendimientos en cereales y otros cultivos herb\u00e1ceos<\/strong>, particularmente en las zonas de secano. Aunque el plazo finaliza el 20 de diciembre, se aplica una bonificaci\u00f3n adicional del 5% a quienes lo suscriban antes del d\u00eda 15 del presente mes de noviembre. Con este seguro se est\u00e1 cubierto ante cualquier tipo de riesgo meteorol\u00f3gico, muy particularmente contra el riesgo de sequ\u00eda.<\/li>\n<\/ol>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deforestaci\u00f3n, Christophe Hansen, DANA, Producci\u00f3n alimentaria en t\u00e9rminos de cantidad y calidad, Embalses leoneses de la Cuenca del Duero, Seguro de rendimientos en cereales y otros cultivos herb\u00e1ceos Consejo y Parlamento han dado su visto bueno a la propuesta de la Comisi\u00f3n Europea de modificaci\u00f3n espec\u00edfica del Reglamento de la UE sobre la deforestaci\u00f3n, aplazando [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":15800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 08\/11\/2024 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Deforestaci\u00f3n, Christophe Hansen, DANA, Producci\u00f3n alimentaria en t\u00e9rminos de cantidad y calidad, Embalses leoneses de la Cuenca del Duero, Seguro de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 08\/11\/2024 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Deforestaci\u00f3n, Christophe Hansen, DANA, Producci\u00f3n alimentaria en t\u00e9rminos de cantidad y calidad, Embalses leoneses de la Cuenca del Duero, Seguro de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T10:10:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-21T10:28:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Deforestacion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024\",\"name\":\"Las seis noticias agrarias de la semana - 08\/11\/2024 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Deforestacion.jpg\",\"datePublished\":\"2024-11-08T10:10:51+00:00\",\"dateModified\":\"2024-11-21T10:28:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Deforestaci\u00f3n, Christophe Hansen, DANA, Producci\u00f3n alimentaria en t\u00e9rminos de cantidad y calidad, Embalses leoneses de la Cuenca del Duero, Seguro de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Deforestacion.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Deforestacion.jpg\",\"width\":1800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 08\/11\/2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 08\/11\/2024 - ASAJA Le\u00f3n","description":"Deforestaci\u00f3n, Christophe Hansen, DANA, Producci\u00f3n alimentaria en t\u00e9rminos de cantidad y calidad, Embalses leoneses de la Cuenca del Duero, Seguro de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 08\/11\/2024 - ASAJA Le\u00f3n","og_description":"Deforestaci\u00f3n, Christophe Hansen, DANA, Producci\u00f3n alimentaria en t\u00e9rminos de cantidad y calidad, Embalses leoneses de la Cuenca del Duero, Seguro de","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2024-11-08T10:10:51+00:00","article_modified_time":"2024-11-21T10:28:16+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Deforestacion.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024","name":"Las seis noticias agrarias de la semana - 08\/11\/2024 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Deforestacion.jpg","datePublished":"2024-11-08T10:10:51+00:00","dateModified":"2024-11-21T10:28:16+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Deforestaci\u00f3n, Christophe Hansen, DANA, Producci\u00f3n alimentaria en t\u00e9rminos de cantidad y calidad, Embalses leoneses de la Cuenca del Duero, Seguro de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Deforestacion.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2024\/11\/Deforestacion.jpg","width":1800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-08-11-2024#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 08\/11\/2024"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15799"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=15799"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15799\/revisions"}],"predecessor-version":[{"id":15801,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15799\/revisions\/15801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/15800"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=15799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=15799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=15799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}