{"id":15853,"date":"2024-12-06T08:53:00","date_gmt":"2024-12-06T07:53:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=15853"},"modified":"2024-12-05T13:58:26","modified_gmt":"2024-12-05T12:58:26","slug":"antibioticos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos","title":{"rendered":"Antibi\u00f3ticos"},"content":{"rendered":"\n\n\n<h6>El sector ganadero ha hecho un \u00edmprobo esfuerzo para contribuir a la estrategia nacional\u00a0 y de la Uni\u00f3n Europea de reducir el uso de antibi\u00f3ticos, en nuestro caso en el tratamiento de enfermedades animales. El ministro de Agricultura, Luis Planas, ofreci\u00f3 cifras de reducci\u00f3n del uso de antibi\u00f3ticos en ganader\u00eda del 53 por ciento entre 2020 y 2023, y lo hizo con motivo de la presentaci\u00f3n del Plan Nacional frente a la Resistencia a los Antibi\u00f3ticos para el periodo de 2025 a 2027 en lo referente a la producci\u00f3n ganadera y la sanidad animal. Digo que se ha hecho un esfuerzo no reconocido, por parte del sector ganadero, porque esto no ha salido gratis, al contrario, ha supuesto y est\u00e1 suponiendo un elevado coste en la cuenta de resultados de las granjas, y todo a pesar de que podr\u00eda pensarse en lo contrario, pues gastar menos, en principio es ahorrar. Pero usar menos antibi\u00f3ticos, en los valores antes citados, y usar antibi\u00f3ticos menos eficaces por la simple raz\u00f3n de que ya est\u00e1n descatalogados en medicina humana y evitan resistencias cruzadas, significa ser menos eficientes en la curaci\u00f3n de las enfermedades, en la prevenci\u00f3n de las mismas, o en reducir las secuelas que dejan. Una sangr\u00eda econ\u00f3mica en las granjas por el aumento de las bajas, por la ca\u00edda en la producci\u00f3n, por los costes m\u00e1s elevados en el manejo y tratamientos alternativos, y por los honorarios veterinarios en tratamientos m\u00e1s complejos que requieren pruebas anal\u00edticas. Para los granjeros esto ha sido un mal negocio, muy malo, y queda por ver si va a ser tan bueno como lo pintan para la salud humana porque evite resistencia en los tratamientos con pacientes aquejados de enfermedades causadas por g\u00e9rmenes sensibles a estos medicamentos. El veterinario, el granjero, dispone de menos principios activos para atajar las enfermedades animales, se le han retirado los m\u00e1s eficientes porque coincide que son tambi\u00e9n los m\u00e1s eficientes en medicina humana, y se le ha dado una segunda vida a productos que ya estaban casi descatalogados y que los laboratorios hab\u00edan dejado de fabricar.<\/h6>\n<p><em>*Art\u00edculo de opini\u00f3n de Jos\u00e9 Antonio Turrado publicado en La Nueva Cr\u00f3nica del viernes 6 de diciembre de 2024.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector ganadero ha hecho un \u00edmprobo esfuerzo para contribuir a la estrategia nacional\u00a0 y de la Uni\u00f3n Europea de reducir el uso de antibi\u00f3ticos, en nuestro caso en el tratamiento de enfermedades animales. El ministro de Agricultura, Luis Planas, ofreci\u00f3 cifras de reducci\u00f3n del uso de antibi\u00f3ticos en ganader\u00eda del 53 por ciento entre [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":13522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Antibi\u00f3ticos - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"El sector ganadero ha hecho un \u00edmprobo esfuerzo para contribuir a la estrategia nacional\u00a0 y de la Uni\u00f3n Europea de reducir el uso de antibi\u00f3ticos, en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antibi\u00f3ticos - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El sector ganadero ha hecho un \u00edmprobo esfuerzo para contribuir a la estrategia nacional\u00a0 y de la Uni\u00f3n Europea de reducir el uso de antibi\u00f3ticos, en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-06T07:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/IMG_0040.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos\",\"name\":\"Antibi\u00f3ticos - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/IMG_0040.jpg\",\"datePublished\":\"2024-12-06T07:53:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"El sector ganadero ha hecho un \u00edmprobo esfuerzo para contribuir a la estrategia nacional\u00a0 y de la Uni\u00f3n Europea de reducir el uso de antibi\u00f3ticos, en\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/IMG_0040.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/IMG_0040.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antibi\u00f3ticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antibi\u00f3ticos - ASAJA Le\u00f3n","description":"El sector ganadero ha hecho un \u00edmprobo esfuerzo para contribuir a la estrategia nacional\u00a0 y de la Uni\u00f3n Europea de reducir el uso de antibi\u00f3ticos, en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos","og_locale":"es_ES","og_type":"article","og_title":"Antibi\u00f3ticos - ASAJA Le\u00f3n","og_description":"El sector ganadero ha hecho un \u00edmprobo esfuerzo para contribuir a la estrategia nacional\u00a0 y de la Uni\u00f3n Europea de reducir el uso de antibi\u00f3ticos, en","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2024-12-06T07:53:00+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/IMG_0040.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos","name":"Antibi\u00f3ticos - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/IMG_0040.jpg","datePublished":"2024-12-06T07:53:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"El sector ganadero ha hecho un \u00edmprobo esfuerzo para contribuir a la estrategia nacional\u00a0 y de la Uni\u00f3n Europea de reducir el uso de antibi\u00f3ticos, en","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/IMG_0040.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2022\/07\/IMG_0040.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/opinion-asaja\/antibioticos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Antibi\u00f3ticos"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15853"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=15853"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15853\/revisions"}],"predecessor-version":[{"id":15854,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/15853\/revisions\/15854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/13522"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=15853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=15853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=15853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}