{"id":16200,"date":"2025-04-11T09:54:28","date_gmt":"2025-04-11T07:54:28","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=16200"},"modified":"2025-04-21T12:34:01","modified_gmt":"2025-04-21T10:34:01","slug":"las-seis-noticias-agrarias-de-la-semana-11-04-2025","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 11\/04\/2025"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Devoluci\u00f3n del impuesto especial de hidrocarburos<\/strong>, <strong>MERCOSUR<\/strong>, <strong>Grupo de trabajo<\/strong>, <strong>DO Rueda y de la DO Bierzo<\/strong>, <strong>Seguro de \u201cm\u00e1s valor\u201d<\/strong>, <strong>Tesorer\u00eda General de la Seguridad Social<\/strong><\/h2>\n\n\n\n<ol>\n<li>Desde primeros de este mes de abril ya se puede solicitar la <strong>devoluci\u00f3n del impuesto especial de hidrocarburos<\/strong> por el consumo de gas\u00f3leo agr\u00edcola consumido durante el a\u00f1o 2024. Recordamos que el importe que se devuelve es de 60 euros por cada mil litros de consumo.<\/li>\n<\/ol>\n<ol start=\"2\">\n<li>En el Parlamento de Estrasburgo se ha producido el 2 de abril un debate y votaci\u00f3n de una enmienda que pone reparos a un acuerdo con <strong>MERCOSUR<\/strong> por las consecuencias que ello puede tener para el sector agroalimentario europeo. La opini\u00f3n de los eurodiputados est\u00e1 muy dividida en esta cuesti\u00f3n, incluso dentro de un mismo grupo parlamentario.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li>El pasado jueves 10 de abril se constituy\u00f3 en la Consejer\u00eda de Agricultura y Ganader\u00eda de la Junta de Castilla y Le\u00f3n un <strong>grupo de trabajo<\/strong>, en el que participan las Opas, que tiene como finalidad elaborar un documento conjunto que marque las directrices de la orientaci\u00f3n pol\u00edtica que deber\u00edan tener estas ayudas para el periodo 2027 a 2033. Es un encargo efectuado por el Consejo Agrario de Castilla y Le\u00f3n.<\/li>\n<\/ol>\n<ol start=\"4\">\n<li>El Viceconsejero de Desarrollo Rural, Jorge Llorente, se reuni\u00f3 recientemente con representantes de la <strong>DO Rueda y de la DO Bierzo<\/strong>, para tratar sobre el conflicto que enfrenta a ambas denominaciones por el inter\u00e9s de la DO Rueda de utilizar la uva Godello en la elaboraci\u00f3n de sus vinos. El Bierzo parece dispuesto a ceder en sus planteamientos iniciales.<\/li>\n<\/ol>\n<ol start=\"5\">\n<li>La organizaci\u00f3n agraria ASAJA ha ofertado a sus socios el <strong>seguro de \u201cm\u00e1s valor\u201d<\/strong> en cultivos herb\u00e1ceos. Con este seguro se\u00a0 garantiza un precio por kilo de producci\u00f3n asegurado, en el caso de siniestro, que puede complementar en hasta un 50% el que paga Agroseguro. ASAJA ofrece asesoramiento personalizado sobre esta opci\u00f3n que est\u00e1 siendo muy bien aceptada por el sector.<\/li>\n<\/ol>\n<ol start=\"6\">\n<li>La <strong>Tesorer\u00eda General de la Seguridad Social<\/strong> ha comenzado a enviar comunicaci\u00f3n a los agricultores aut\u00f3nomos que en el a\u00f1o 2023 cotizaron por debajo de las bases marcadas por su nivel de ingresos, indic\u00e1ndoles el importe de la cuota adicional que tienen que pagar. Si la carta de pago se presenta en el banco fuera de plazo, aplican un recargo del 20%.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Devoluci\u00f3n del impuesto especial de hidrocarburos, MERCOSUR, Grupo de trabajo, DO Rueda y de la DO Bierzo, Seguro de \u201cm\u00e1s valor\u201d, Tesorer\u00eda General de la Seguridad Social Desde primeros de este mes de abril ya se puede solicitar la devoluci\u00f3n del impuesto especial de hidrocarburos por el consumo de gas\u00f3leo agr\u00edcola consumido durante el a\u00f1o [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":5820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9,1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 11\/04\/2025 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Devoluci\u00f3n del impuesto especial de hidrocarburos, MERCOSUR, Grupo de trabajo, DO Rueda y de la DO Bierzo, Seguro de \u201cm\u00e1s valor\u201d, Tesorer\u00eda General de la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 11\/04\/2025 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Devoluci\u00f3n del impuesto especial de hidrocarburos, MERCOSUR, Grupo de trabajo, DO Rueda y de la DO Bierzo, Seguro de \u201cm\u00e1s valor\u201d, Tesorer\u00eda General de la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-11T07:54:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T10:34:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-colza-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025\",\"name\":\"Las seis noticias agrarias de la semana - 11\/04\/2025 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-colza-01.jpg\",\"datePublished\":\"2025-04-11T07:54:28+00:00\",\"dateModified\":\"2025-04-21T10:34:01+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Devoluci\u00f3n del impuesto especial de hidrocarburos, MERCOSUR, Grupo de trabajo, DO Rueda y de la DO Bierzo, Seguro de \u201cm\u00e1s valor\u201d, Tesorer\u00eda General de la\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-colza-01.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-colza-01.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Colza\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 11\/04\/2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 11\/04\/2025 - ASAJA Le\u00f3n","description":"Devoluci\u00f3n del impuesto especial de hidrocarburos, MERCOSUR, Grupo de trabajo, DO Rueda y de la DO Bierzo, Seguro de \u201cm\u00e1s valor\u201d, Tesorer\u00eda General de la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 11\/04\/2025 - ASAJA Le\u00f3n","og_description":"Devoluci\u00f3n del impuesto especial de hidrocarburos, MERCOSUR, Grupo de trabajo, DO Rueda y de la DO Bierzo, Seguro de \u201cm\u00e1s valor\u201d, Tesorer\u00eda General de la","og_url":"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2025-04-11T07:54:28+00:00","article_modified_time":"2025-04-21T10:34:01+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-colza-01.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025","url":"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025","name":"Las seis noticias agrarias de la semana - 11\/04\/2025 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-colza-01.jpg","datePublished":"2025-04-11T07:54:28+00:00","dateModified":"2025-04-21T10:34:01+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Devoluci\u00f3n del impuesto especial de hidrocarburos, MERCOSUR, Grupo de trabajo, DO Rueda y de la DO Bierzo, Seguro de \u201cm\u00e1s valor\u201d, Tesorer\u00eda General de la","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-colza-01.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-colza-01.jpg","width":1920,"height":1080,"caption":"Colza"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/sin-categoria\/las-seis-noticias-agrarias-de-la-semana-11-04-2025#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 11\/04\/2025"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16200"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=16200"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16200\/revisions"}],"predecessor-version":[{"id":16201,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16200\/revisions\/16201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/5820"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=16200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=16200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=16200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}