{"id":16210,"date":"2025-04-21T12:22:25","date_gmt":"2025-04-21T10:22:25","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=16210"},"modified":"2025-04-21T12:22:27","modified_gmt":"2025-04-21T10:22:27","slug":"estomagos-de-cerdos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos","title":{"rendered":"Est\u00f3magos de cerdos"},"content":{"rendered":"\n<p>El pol\u00e9mico viaje comercial de Pedro S\u00e1nchez a China, que ha tenido cr\u00edticas sobre la oportunidad del mismo por parte del principal partido de la oposici\u00f3n, el PP, ha recibido por el contrario los parabienes de la Interprofesional del Porcino de Capa Blanca, asociaci\u00f3n que agrupa a los productores de cerdos y a los mataderos y centros de procesado de la carne de toda Espa\u00f1a. La nota de INTERPORC dice que como consecuencia de ese viaje comercial podremos exportar est\u00f3magos de cerdos, y potenciar todav\u00eda m\u00e1s el mercado de productos de alto valor a\u00f1adido como los jamones, a la vez que recuerdan que China es uno de nuestros principales importadores, con el veinte por ciento de todo lo que exportamos y por valor de mil cien millones de euros anuales referido a dos mil veinticuatro. \u00bfEst\u00f3magos de cerdos?. Pues s\u00ed, todos conocemos el dicho de que \u201cdel cerdo de aprovecha todo\u201d,\u00a0 o se aprovechaba todo cuando se hac\u00edan las matanzas domiciliarias. Antes de exportar no se aprovechaba todo, pero ahora s\u00ed, porque lo que para nosotros es un despojo, puede ser un manjar culinario en otras culturas. En una visita reciente a las instalaciones de Embutidos Rodriguez, en Soto de la Vega, la primera industria agroalimentaria leonesa, el director de la planta nos explicaba a un grupo de ganaderos precisamente eso, de que el \u00e9xito comercial estaba en aprovechar todo y buscar para cada uno de los despieces el mejor mercado posible, que en algunos casos est\u00e1 fuera del consumo, vinculado por ejemplo al \u00e1mbito farmac\u00e9utico.\u00a0 En la Rusia siberiana se com\u00edan gran parte de nuestros excedentes de tocino, pero fue antes de aquel primer embargo cuando invadieron por vez primera Crimea.\u00a0 Somos referente mundial en el sector porcino y exportamos sobre todo a Europa y a pa\u00edses del Este, no a EEUU y resto de Am\u00e9rica, y exportamos m\u00e1xima calidad compitiendo tambi\u00e9n en precio. Aun as\u00ed, necesitamos el apoyo de nuestro Gobierno, y al parecer en eso estuvo Pedro S\u00e1nchez y el ministro de Agricultura Luis Planas. Y eso es lo importante para nosotros.<\/p>\n<ul>\n<li><em>Art\u00edculo de opini\u00f3n de Jos\u00e9 Antonio Turrado publicado en La Nueva Cr\u00f3nica del viernes 18 de abril de 2025<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El pol\u00e9mico viaje comercial de Pedro S\u00e1nchez a China, que ha tenido cr\u00edticas sobre la oportunidad del mismo por parte del principal partido de la oposici\u00f3n, el PP, ha recibido por el contrario los parabienes de la Interprofesional del Porcino de Capa Blanca, asociaci\u00f3n que agrupa a los productores de cerdos y a los mataderos [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Est\u00f3magos de cerdos - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"El pol\u00e9mico viaje comercial de Pedro S\u00e1nchez a China, que ha tenido cr\u00edticas sobre la oportunidad del mismo por parte del principal partido de la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Est\u00f3magos de cerdos - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El pol\u00e9mico viaje comercial de Pedro S\u00e1nchez a China, que ha tenido cr\u00edticas sobre la oportunidad del mismo por parte del principal partido de la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-21T10:22:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T10:22:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/04\/channels4_profile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos\",\"name\":\"Est\u00f3magos de cerdos - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/04\/channels4_profile.jpg\",\"datePublished\":\"2025-04-21T10:22:25+00:00\",\"dateModified\":\"2025-04-21T10:22:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"El pol\u00e9mico viaje comercial de Pedro S\u00e1nchez a China, que ha tenido cr\u00edticas sobre la oportunidad del mismo por parte del principal partido de la\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/04\/channels4_profile.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/04\/channels4_profile.jpg\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Est\u00f3magos de cerdos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Est\u00f3magos de cerdos - ASAJA Le\u00f3n","description":"El pol\u00e9mico viaje comercial de Pedro S\u00e1nchez a China, que ha tenido cr\u00edticas sobre la oportunidad del mismo por parte del principal partido de la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos","og_locale":"es_ES","og_type":"article","og_title":"Est\u00f3magos de cerdos - ASAJA Le\u00f3n","og_description":"El pol\u00e9mico viaje comercial de Pedro S\u00e1nchez a China, que ha tenido cr\u00edticas sobre la oportunidad del mismo por parte del principal partido de la","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2025-04-21T10:22:25+00:00","article_modified_time":"2025-04-21T10:22:27+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/04\/channels4_profile.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos","name":"Est\u00f3magos de cerdos - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/04\/channels4_profile.jpg","datePublished":"2025-04-21T10:22:25+00:00","dateModified":"2025-04-21T10:22:27+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"El pol\u00e9mico viaje comercial de Pedro S\u00e1nchez a China, que ha tenido cr\u00edticas sobre la oportunidad del mismo por parte del principal partido de la","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/04\/channels4_profile.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/04\/channels4_profile.jpg","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/estomagos-de-cerdos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Est\u00f3magos de cerdos"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16210"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=16210"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16210\/revisions"}],"predecessor-version":[{"id":16212,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16210\/revisions\/16212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/16211"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=16210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=16210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=16210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}