{"id":16323,"date":"2025-06-05T09:52:12","date_gmt":"2025-06-05T07:52:12","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=16323"},"modified":"2025-06-05T09:52:13","modified_gmt":"2025-06-05T07:52:13","slug":"ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos","title":{"rendered":"Ayuda a ganaderos que tengan razas puras en libros geneal\u00f3gicos"},"content":{"rendered":"\n<p><a href=\"https:\/\/bocyl.jcyl.es\/boletines\/2025\/06\/04\/pdf\/BOCYL-D-04062025-6.pdf\">El BOCYL ha publicado la Orden de 23 de mayo de 2025, de la Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convocan las ayudas destinadas al fomento de la cr\u00eda e inscripci\u00f3n de ejemplares de razas puras de Castilla y Le\u00f3n en los libros geneal\u00f3gicos<\/a>. (BOCYL n\u00ba105 de 04\/06\/2025)<\/p>\n<p>Se convocan ayudas destinadas al fomento de animales de las razas aut\u00f3ctonas de Castilla y Le\u00f3n. Podr\u00e1n ser beneficiarios las personas f\u00edsicas, jur\u00eddicas, comunidades de bienes y sociedades civiles que sean titulares de explotaciones ganaderas ubicadas en Castilla y Le\u00f3n dedicadas a la cr\u00eda de razas puras, inscritas en REACYL, que formen parte de la asociaci\u00f3n de criadores de raza aut\u00f3ctona pura, que sea explotaci\u00f3n colaboradora del programa de mejora y cumplir las obligaciones especificadas en la reglamentaci\u00f3n del libro geneal\u00f3gico, que comuniquen a su asociaci\u00f3n las incidencias de todos los animales incluidos en el libro geneal\u00f3gico, que registren las hembras y machos nacidos en su explotaci\u00f3n en el libro geneal\u00f3gico de la raza y que cumplan la normativa legal en vigor en materia de medio ambiente, higiene, bienestar y sanidad animal e identificaci\u00f3n y registro de animales.<\/p>\n<p>Se subvencionar\u00e1 la inscripci\u00f3n de ejemplares calificados y registrados como reproductores de las razas puras de Castilla y Le\u00f3n en la secci\u00f3n principal del libro geneal\u00f3gico que se haya realizado durante el a\u00f1o 2024 y los ejemplares que hayan sido inscritos en la secci\u00f3n principal del libro geneal\u00f3gico como reproductor por el titular de la explotaci\u00f3n donde naci\u00f3 el animal y que posteriormente sean adquiridos por otra explotaci\u00f3n, siempre que se realice el cambio de titularidad.<\/p>\n<p>El importe m\u00e1ximo a percibir por titular ser\u00e1 de <strong><u>6.000\u20ac y la cuant\u00eda individual para cada ejemplar ser\u00e1 de 240-360\u20ac\/UGM<\/u><\/strong> seg\u00fan el listado establecido. El presupuesto total de la convocatoria es de 2.000.000\u20ac y <strong><u>el plazo de presentaci\u00f3n de solicitudes se inicia el 05\/06\/2025 y concluye el 04\/07\/2025.<\/u><\/strong><\/p>\n<p>\u00a0<\/p>\n<p>ASAJA. Le\u00f3n, 5 de junio de 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El BOCYL ha publicado la Orden de 23 de mayo de 2025, de la Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convocan las ayudas destinadas al fomento de la cr\u00eda e inscripci\u00f3n de ejemplares de razas puras de Castilla y Le\u00f3n en los libros geneal\u00f3gicos. (BOCYL n\u00ba105 de 04\/06\/2025) Se convocan [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ayuda a ganaderos que tengan razas puras en libros geneal\u00f3gicos - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"El BOCYL ha publicado la Orden de 23 de mayo de 2025, de la Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convocan las ayudas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ayuda a ganaderos que tengan razas puras en libros geneal\u00f3gicos - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El BOCYL ha publicado la Orden de 23 de mayo de 2025, de la Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convocan las ayudas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-05T07:52:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T07:52:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/06\/burro-zamorano-leones.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1063\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos\",\"name\":\"Ayuda a ganaderos que tengan razas puras en libros geneal\u00f3gicos - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/06\/burro-zamorano-leones.jpg\",\"datePublished\":\"2025-06-05T07:52:12+00:00\",\"dateModified\":\"2025-06-05T07:52:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"El BOCYL ha publicado la Orden de 23 de mayo de 2025, de la Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convocan las ayudas\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/06\/burro-zamorano-leones.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/06\/burro-zamorano-leones.jpg\",\"width\":1600,\"height\":1063},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ayuda a ganaderos que tengan razas puras en libros geneal\u00f3gicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ayuda a ganaderos que tengan razas puras en libros geneal\u00f3gicos - ASAJA Le\u00f3n","description":"El BOCYL ha publicado la Orden de 23 de mayo de 2025, de la Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convocan las ayudas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos","og_locale":"es_ES","og_type":"article","og_title":"Ayuda a ganaderos que tengan razas puras en libros geneal\u00f3gicos - ASAJA Le\u00f3n","og_description":"El BOCYL ha publicado la Orden de 23 de mayo de 2025, de la Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convocan las ayudas","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2025-06-05T07:52:12+00:00","article_modified_time":"2025-06-05T07:52:13+00:00","og_image":[{"width":1600,"height":1063,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/06\/burro-zamorano-leones.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos","name":"Ayuda a ganaderos que tengan razas puras en libros geneal\u00f3gicos - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/06\/burro-zamorano-leones.jpg","datePublished":"2025-06-05T07:52:12+00:00","dateModified":"2025-06-05T07:52:13+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"El BOCYL ha publicado la Orden de 23 de mayo de 2025, de la Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convocan las ayudas","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/06\/burro-zamorano-leones.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/06\/burro-zamorano-leones.jpg","width":1600,"height":1063},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayuda-a-ganaderos-que-tengan-razas-puras-en-libros-genealogicos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Ayuda a ganaderos que tengan razas puras en libros geneal\u00f3gicos"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16323"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=16323"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16323\/revisions"}],"predecessor-version":[{"id":16325,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16323\/revisions\/16325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/16324"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=16323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=16323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=16323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}