{"id":16377,"date":"2025-06-27T11:43:30","date_gmt":"2025-06-27T09:43:30","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=16377"},"modified":"2025-07-11T09:30:05","modified_gmt":"2025-07-11T07:30:05","slug":"asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe","title":{"rendered":"ASAJA es contraria a la modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n que impulsa el PSOE"},"content":{"rendered":"\n<p>La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n rechaza la propuesta de modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n (Ley 1\/2014 de 19 de marzo) que ha promovido el Grupo Parlamentario Socialista en las Cortes de Castilla y Le\u00f3n mediante una Proposici\u00f3n de Ley que fue tomada en consideraci\u00f3n en el Pleno del mi\u00e9rcoles 25 de junio.<\/p>\n<p>ASAJA quiere dejar claro que ni la anterior direcci\u00f3n del PSOE con Luis Tudanca a la cabeza, cuando se present\u00f3 en diciembre de 2024, ni la actual presidida por Carlos Mart\u00ednez, ha recabado la opini\u00f3n de la principal organizaci\u00f3n profesional agraria de Castilla y Le\u00f3n.<\/p>\n<p>El fin \u00fanico que persigue la modificaci\u00f3n, seg\u00fan la exposici\u00f3n de motivos, es incorporar al sector forestal, de forma expresa en la misma, de manera que se <strong><em>\u201cgarantice el acceso a los fondos europeos de la Pol\u00edtica Agraria Com\u00fan (PAC) en igualdad de condiciones a la actividad forestal, a la agraria y a la ganadera\u201d<\/em><\/strong>, atendiendo, seg\u00fan dicen, la \u201cjusta reivindicaci\u00f3n y continua de los propietarios forestales\u201d. ASAJA cree que el PSOE, con esta iniciativa, pretende quedar bien con un sector econ\u00f3mico, el forestal, gastando a cuenta de otros, \u201cinvitando a rondas y proponiendo que las paguen los dem\u00e1s\u201d.<\/p>\n<p>ASAJA no va a permitir que los fondos de la PAC destinados al sector agrario, que los necesita m\u00e1s que nunca, se repartan entre otros sectores productivos, y recuerda que el sector forestal ya se lleva una parte importante de las ayudas en medidas de desarrollo rural.\u00a0 Ayudas que han ido destinadas sobre todo a programas de forestaci\u00f3n, de mejora de la masa forestal, y de prevenci\u00f3n y extinci\u00f3n de incendios forestales. Adem\u00e1s, el sector forestal ya aparece citado en la Ley Agraria actual en las \u00e1reas que entroncan directamente con su actividad, como es el desarrollo rural y conservaci\u00f3n, la ordenaci\u00f3n de recursos agropecuarios como son los pastos, o la investigaci\u00f3n.<\/p>\n<p>ASAJA pide a la actual direcci\u00f3n del Grupo Parlamentario del PSOE en las Cortes de Castilla y Le\u00f3n que retire su proposici\u00f3n de ley o, en caso contrario, solicitar\u00e1 al resto de grupos parlamentarios que la voten en contra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n rechaza la propuesta de modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n (Ley 1\/2014 de 19 de marzo) que ha promovido el Grupo Parlamentario Socialista en las Cortes de Castilla y Le\u00f3n mediante una Proposici\u00f3n de Ley que fue tomada en consideraci\u00f3n en el Pleno del [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":14953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA es contraria a la modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n que impulsa el PSOE - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n rechaza la propuesta de modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n (Ley 1\/2014 de 19 de marzo) que\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA es contraria a la modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n que impulsa el PSOE - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n rechaza la propuesta de modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n (Ley 1\/2014 de 19 de marzo) que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-27T09:43:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-11T07:30:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/12\/TERRENOS-FORESTADOS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe\",\"name\":\"ASAJA es contraria a la modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n que impulsa el PSOE - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/12\/TERRENOS-FORESTADOS.jpg\",\"datePublished\":\"2025-06-27T09:43:30+00:00\",\"dateModified\":\"2025-07-11T07:30:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n rechaza la propuesta de modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n (Ley 1\/2014 de 19 de marzo) que\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/12\/TERRENOS-FORESTADOS.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/12\/TERRENOS-FORESTADOS.jpg\",\"width\":2500,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA es contraria a la modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n que impulsa el PSOE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA es contraria a la modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n que impulsa el PSOE - ASAJA Le\u00f3n","description":"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n rechaza la propuesta de modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n (Ley 1\/2014 de 19 de marzo) que","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe","og_locale":"es_ES","og_type":"article","og_title":"ASAJA es contraria a la modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n que impulsa el PSOE - ASAJA Le\u00f3n","og_description":"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n rechaza la propuesta de modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n (Ley 1\/2014 de 19 de marzo) que","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2025-06-27T09:43:30+00:00","article_modified_time":"2025-07-11T07:30:05+00:00","og_image":[{"width":2500,"height":1875,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/12\/TERRENOS-FORESTADOS.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe","name":"ASAJA es contraria a la modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n que impulsa el PSOE - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/12\/TERRENOS-FORESTADOS.jpg","datePublished":"2025-06-27T09:43:30+00:00","dateModified":"2025-07-11T07:30:05+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"La organizaci\u00f3n agraria ASAJA de Castilla y Le\u00f3n rechaza la propuesta de modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n (Ley 1\/2014 de 19 de marzo) que","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/12\/TERRENOS-FORESTADOS.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2023\/12\/TERRENOS-FORESTADOS.jpg","width":2500,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-es-contraria-a-la-modificacion-de-la-ley-agraria-de-castilla-y-leon-que-impulsa-el-psoe#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ASAJA es contraria a la modificaci\u00f3n de la Ley Agraria de Castilla y Le\u00f3n que impulsa el PSOE"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16377"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=16377"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16377\/revisions"}],"predecessor-version":[{"id":16378,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16377\/revisions\/16378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/14953"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=16377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=16377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=16377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}