{"id":16399,"date":"2025-07-04T10:10:26","date_gmt":"2025-07-04T08:10:26","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=16399"},"modified":"2025-07-28T10:16:56","modified_gmt":"2025-07-28T08:16:56","slug":"las-seis-noticias-agrarias-de-la-semana-04-07-2025","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 04\/07\/2025"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Reconocimiento \u201cerga omnes\u201d<\/strong>, <strong>Convenio de Berna<\/strong>, <strong>Nuevas plantaciones de vi\u00f1edo en 2025<\/strong>, <strong>Ayudas para modernizaci\u00f3n de explotaciones e incorporaci\u00f3n de j\u00f3venes al campo<\/strong>, <strong>Patronato del Parque Natural de Babia y Luna<\/strong>, <strong>Ley de agricultura familiar y profesional<\/strong><\/h2>\n\n\n\n<ol>\n<li>El Ayuntamiento de Alija del Infantado, junto a las juntas vecinales de Navianos de la Vega y La Nora del R\u00edo, ha acordado iniciar una acci\u00f3n judicial de naturaleza declarativa para el <strong>reconocimiento \u201cerga omnes\u201d<\/strong>, por parte de la Confederaci\u00f3n Hidrogr\u00e1fica del Duero, del aprovechamiento como de regad\u00edo de las fincas r\u00fasticas de los pol\u00edgonos 1 al 11 en el mencionado municipio, del 106 al 107 en Quintana y Congosto, y del 208 de Roperuelos del P\u00e1ramo.<\/li>\n<\/ol>\n<ol start=\"2\">\n<li>El Consejo de Ministros del martes 1 de julio\u00a0 tom\u00f3 conocimiento de que el 6 de diciembre de 2024 el Comit\u00e9 Permanente del <strong>Convenio de Berna<\/strong> adopt\u00f3 una propuesta presentada por la Uni\u00f3n Europea para modificar el estatus de la protecci\u00f3n del lobo (Canis lupus) de \u00abespecie de fauna estrictamente protegida\u00bb a \u00abespecie de fauna protegida\u00bb. Las enmiendas entraron en vigor el 6 de marzo de 2025.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li>El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n ha comunicado a las comunidades aut\u00f3nomas la resoluci\u00f3n que distribuye 914 hect\u00e1reas para <strong>nuevas plantaciones de vi\u00f1edo en 2025<\/strong>, en el marco del r\u00e9gimen de autorizaciones vigente. La superficie concedida se ha repartido entre los siete grupos de prioridad establecidos. Esto ha permitido que los j\u00f3venes viticultores y las peque\u00f1as y medianas explotaciones reciban el 100 % de la superficie admisible solicitada, con un l\u00edmite m\u00e1ximo de 5 hect\u00e1reas por solicitante.<\/li>\n<\/ol>\n<ol start=\"4\">\n<li>En el BOCYL del jueves 3 de julio se ha publicado la Orden que convoca las <strong>ayudas para modernizaci\u00f3n de explotaciones e incorporaci\u00f3n de j\u00f3venes al campo<\/strong>, abri\u00e9ndose un plazo para tramitarlas que finaliza el 31 de octubre. ASAJA ya ha puesto en marcha todo el operativo para tramitar con \u00e9xito estas importantes ayudas\u00a0 y ha convocado una primera ronda de reuniones informativas en diferentes comarcas de la provincia.<\/li>\n<\/ol>\n<ol start=\"5\">\n<li>El presidente del <strong>Patronato del Parque Natural de Babia y Luna<\/strong> ha convocado reuni\u00f3n del \u00f3rgano de gesti\u00f3n para el jueves 10 de julio, en la sede de la Casa del Parque, en Riolago de Babia. Se presentar\u00e1 el informe de gesti\u00f3n, el informe sobre ayudas a zonas de influencia socioecon\u00f3mica, y habr\u00e1 un apartado de ruegos y preguntas.<\/li>\n<\/ol>\n<ol start=\"6\">\n<li>El ministro de Agricultura, Pesca y Alimentaci\u00f3n, Luis Planas, ha destacado que el Gobierno avanza y \u201cva a acelerar todo lo que sea posible\u201d en la elaboraci\u00f3n y aprobaci\u00f3n de la <strong>ley de agricultura familiar y profesional<\/strong>, que tiene como objetivo priorizar y proteger este modelo, que es clave para la cohesi\u00f3n social, la sostenibilidad y el mantenimiento del medio rural. Esto se produce en un contexto de debilidad del Gobierno, de p\u00e9rdida de apoyos parlamentarios, y de peticiones de adelanto electoral, por lo que lo anunciado parece poco realista, en opini\u00f3n de ASAJA.<\/li>\n<\/ol>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reconocimiento \u201cerga omnes\u201d, Convenio de Berna, Nuevas plantaciones de vi\u00f1edo en 2025, Ayudas para modernizaci\u00f3n de explotaciones e incorporaci\u00f3n de j\u00f3venes al campo, Patronato del Parque Natural de Babia y Luna, Ley de agricultura familiar y profesional El Ayuntamiento de Alija del Infantado, junto a las juntas vecinales de Navianos de la Vega y La [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 04\/07\/2025 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Reconocimiento \u201cerga omnes\u201d, Convenio de Berna, Nuevas plantaciones de vi\u00f1edo en 2025, Ayudas para modernizaci\u00f3n de explotaciones e incorporaci\u00f3n de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 04\/07\/2025 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Reconocimiento \u201cerga omnes\u201d, Convenio de Berna, Nuevas plantaciones de vi\u00f1edo en 2025, Ayudas para modernizaci\u00f3n de explotaciones e incorporaci\u00f3n de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-04T08:10:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T08:16:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/07\/nuevas-plantaciones-devinedo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025\",\"name\":\"Las seis noticias agrarias de la semana - 04\/07\/2025 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/07\/nuevas-plantaciones-devinedo.jpg\",\"datePublished\":\"2025-07-04T08:10:26+00:00\",\"dateModified\":\"2025-07-28T08:16:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Reconocimiento \u201cerga omnes\u201d, Convenio de Berna, Nuevas plantaciones de vi\u00f1edo en 2025, Ayudas para modernizaci\u00f3n de explotaciones e incorporaci\u00f3n de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/07\/nuevas-plantaciones-devinedo.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/07\/nuevas-plantaciones-devinedo.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 04\/07\/2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 04\/07\/2025 - ASAJA Le\u00f3n","description":"Reconocimiento \u201cerga omnes\u201d, Convenio de Berna, Nuevas plantaciones de vi\u00f1edo en 2025, Ayudas para modernizaci\u00f3n de explotaciones e incorporaci\u00f3n de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 04\/07\/2025 - ASAJA Le\u00f3n","og_description":"Reconocimiento \u201cerga omnes\u201d, Convenio de Berna, Nuevas plantaciones de vi\u00f1edo en 2025, Ayudas para modernizaci\u00f3n de explotaciones e incorporaci\u00f3n de","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2025-07-04T08:10:26+00:00","article_modified_time":"2025-07-28T08:16:56+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/07\/nuevas-plantaciones-devinedo.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025","name":"Las seis noticias agrarias de la semana - 04\/07\/2025 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/07\/nuevas-plantaciones-devinedo.jpg","datePublished":"2025-07-04T08:10:26+00:00","dateModified":"2025-07-28T08:16:56+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Reconocimiento \u201cerga omnes\u201d, Convenio de Berna, Nuevas plantaciones de vi\u00f1edo en 2025, Ayudas para modernizaci\u00f3n de explotaciones e incorporaci\u00f3n de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/07\/nuevas-plantaciones-devinedo.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/07\/nuevas-plantaciones-devinedo.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-04-07-2025#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 04\/07\/2025"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16399"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=16399"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16399\/revisions"}],"predecessor-version":[{"id":16401,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16399\/revisions\/16401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/16400"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=16399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=16399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=16399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}