{"id":16427,"date":"2025-07-25T09:00:45","date_gmt":"2025-07-25T07:00:45","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=16427"},"modified":"2025-08-08T09:53:06","modified_gmt":"2025-08-08T07:53:06","slug":"las-seis-noticias-agrarias-de-la-semana-25-07-2025","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 25\/07\/2025"},"content":{"rendered":"\n<h2>Cosecha en verde de vi\u00f1edos, eco r\u00e9gimen de pastoreo extensivo y espacios de biodiversidad, CR Canal de Villadangos, incorporaci\u00f3n de J\u00f3venes, Feria del L\u00fapulo y la Cerveza<\/h2>\n<ol>\n<li>\n<h6>Un total de 7 agricultores de ASAJA pertenecientes a la DO Bierzo se han acogido a la Orden de 8 de abril de 2025, de la Consejer\u00eda de Agricultura, Ganader\u00eda y Desarrollo Rural, por la que se convocan las ayudas a la <strong>cosecha en verde de vi\u00f1edos<\/strong> en la Comunidad de Castilla y Le\u00f3n para la vendimia 2025. De esta forma, han retirado de la producci\u00f3n 17,5 hect\u00e1reas de vi\u00f1edo, labor ya ejecutada y que est\u00e1 pendiente de certificaci\u00f3n por los funcionarios de la consejer\u00eda de Agricultura. Esta medida es como consecuencia de la falta de comprador para la producci\u00f3n de uva en la vendimia de 2025.<\/h6>\n<\/li>\n<li>\n<h6>Los ganaderos que se han acogido al <strong>eco r\u00e9gimen de pastoreo extensivo,<\/strong> agrupando las fincas por grupos de pastoreo e indicando las fechas de inicio y fin del aprovechamiento, en el caso en el que estas fechas reales de aprovechamiento difieran m\u00e1s de quince d\u00edas sobre las fechas declaradas , deber\u00e1n de\u00a0 anotar en el cuaderno digital de explotaci\u00f3n agr\u00edcola las nuevas fechas,\u00a0 o realizar una comunicaci\u00f3n electr\u00f3nica a la Junta de Castilla y Le\u00f3n a m\u00e1s tardar en el plazo de un mes desde la nueva fecha de inicio o fin que haya resultado de la modificaci\u00f3n.<\/h6>\n<\/li>\n<li>\n<h6>Los agricultores acogidos al <strong>eco r\u00e9gimen de espacios de biodiversidad<\/strong> dejando zonas de \u201cno cosechado\u201d, en el caso del cereal la fecha de recolecci\u00f3n en estas parcelas no podr\u00e1 ser antes del 1 de septiembre. En cultivos de primavera como el girasol o el ma\u00edz, la fecha de recolecci\u00f3n ser\u00e1 al menos un mes posterior al momento en el que agron\u00f3micamente se pueda cosechar para la venta al mercado.<\/h6>\n<\/li>\n<li>\n<h6>La <strong>Comunidad de Regantes del Canal de Villadangos<\/strong> firm\u00f3 el mi\u00e9rcoles 23 de julio un convenio tripartito con el Itacyl y con Seiasa para avanzar en la modernizaci\u00f3n del regad\u00edo en esta zona regable dependiente del Pantano de Barrios de Luna. Paralelo a estas obras, se est\u00e1 ejecutando una reconcentraci\u00f3n parcelaria en toda la zona.<\/h6>\n<\/li>\n<li>\n<h6>La organizaci\u00f3n agraria ASAJA de Le\u00f3n ha comenzado a tramitar las ayudas de <strong>incorporaci\u00f3n de j\u00f3venes <\/strong>al sector agrario, una vez que la normativa reguladora se ha publicado recientemente. La \u00faltima convocatoria se efectu\u00f3 hace ahora m\u00e1s de a\u00f1o y medio. La organizaci\u00f3n espera una importante afluencia de nuevos agricultores, situ\u00e1ndose de nuevo a la cabeza de todas las provincias de Castilla y Le\u00f3n.<\/h6>\n<\/li>\n<li>\n<h6>El jueves 31 de julio se inaugurar\u00e1 en Carrizo de la Ribera la XVIII <strong>Feria del L\u00fapulo y la Cerveza<\/strong>. En semanas previas ha tenido lugar tambi\u00e9n la Feria del Ajo tanto en Veguellina de \u00d3rbigo como en Santa Marina del Rey. Este tipo de cert\u00e1menes son habituales en muchos municipios de la provincia de Le\u00f3n, y gran parte de ellos se celebran en estos meses de verano y en los de oto\u00f1o, poniendo en valor los productos locales, las tradiciones y las costumbres.<\/h6>\n<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Cosecha en verde de vi\u00f1edos, eco r\u00e9gimen de pastoreo extensivo y espacios de biodiversidad, CR Canal de Villadangos, incorporaci\u00f3n de J\u00f3venes, Feria del L\u00fapulo y la Cerveza Un total de 7 agricultores de ASAJA pertenecientes a la DO Bierzo se han acogido a la Orden de 8 de abril de 2025, de la Consejer\u00eda de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":5836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 25\/07\/2025 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Cosecha en verde de vi\u00f1edos, eco r\u00e9gimen de pastoreo extensivo y espacios de biodiversidad, CR Canal de Villadangos, incorporaci\u00f3n de J\u00f3venes, Feria del\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 25\/07\/2025 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Cosecha en verde de vi\u00f1edos, eco r\u00e9gimen de pastoreo extensivo y espacios de biodiversidad, CR Canal de Villadangos, incorporaci\u00f3n de J\u00f3venes, Feria del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-25T07:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-08T07:53:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-vi\u00f1edo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025\",\"name\":\"Las seis noticias agrarias de la semana - 25\/07\/2025 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-vi\u00f1edo.jpg\",\"datePublished\":\"2025-07-25T07:00:45+00:00\",\"dateModified\":\"2025-08-08T07:53:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"Cosecha en verde de vi\u00f1edos, eco r\u00e9gimen de pastoreo extensivo y espacios de biodiversidad, CR Canal de Villadangos, incorporaci\u00f3n de J\u00f3venes, Feria del\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-vi\u00f1edo.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-vi\u00f1edo.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Vi\u00f1edo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 25\/07\/2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 25\/07\/2025 - ASAJA Le\u00f3n","description":"Cosecha en verde de vi\u00f1edos, eco r\u00e9gimen de pastoreo extensivo y espacios de biodiversidad, CR Canal de Villadangos, incorporaci\u00f3n de J\u00f3venes, Feria del","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 25\/07\/2025 - ASAJA Le\u00f3n","og_description":"Cosecha en verde de vi\u00f1edos, eco r\u00e9gimen de pastoreo extensivo y espacios de biodiversidad, CR Canal de Villadangos, incorporaci\u00f3n de J\u00f3venes, Feria del","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2025-07-25T07:00:45+00:00","article_modified_time":"2025-08-08T07:53:06+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-vi\u00f1edo.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025","name":"Las seis noticias agrarias de la semana - 25\/07\/2025 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-vi\u00f1edo.jpg","datePublished":"2025-07-25T07:00:45+00:00","dateModified":"2025-08-08T07:53:06+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"Cosecha en verde de vi\u00f1edos, eco r\u00e9gimen de pastoreo extensivo y espacios de biodiversidad, CR Canal de Villadangos, incorporaci\u00f3n de J\u00f3venes, Feria del","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-vi\u00f1edo.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/recurso-vi\u00f1edo.jpg","width":1920,"height":1080,"caption":"Vi\u00f1edo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-25-07-2025#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 25\/07\/2025"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16427"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=16427"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16427\/revisions"}],"predecessor-version":[{"id":16428,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16427\/revisions\/16428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/5836"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=16427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=16427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=16427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}