{"id":16443,"date":"2025-08-01T08:38:03","date_gmt":"2025-08-01T06:38:03","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/?p=16443"},"modified":"2025-08-01T08:38:06","modified_gmt":"2025-08-01T06:38:06","slug":"mildiu-en-la-vina","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina","title":{"rendered":"Mildiu en la vi\u00f1a"},"content":{"rendered":"\n<p>La pasada primavera, inusualmente lluviosa en Espa\u00f1a, trajo como consecuencia unas cosechas abundantes, como nunca se hab\u00edan visto, en los cultivos de invierno. Por el contrario, esa lluvia, tan continuada en el tiempo, ocasion\u00f3 la llegada de una enfermedad causada por hongos, el mildiu, que asol\u00f3 determinados cultivos como la vi\u00f1a. \u00a1El grito en el cielo han puesto muchos viticultores espa\u00f1oles que nunca hab\u00edan visto nada igual y que ya no solo afrontan p\u00e9rdidas en cantidad, sino tambi\u00e9n, y quiz\u00e1s eso sea peor, en calidad!. Y acto seguido se han pedido ayudas a las administraciones, as\u00ed como\u00a0 que los seguros agrarios contemplen esta casu\u00edstica dentro de los da\u00f1os indemnizables vinculados a condiciones meteorol\u00f3gicas excepcionales e imprevisibles.<\/p>\n<p>Los viticultores del Bierzo, nuestros viticultores, no daban cr\u00e9dito a lo que le\u00edan y escuchaban de cuanto a este respecto estaba ocurriendo en otros territorios espa\u00f1oles, algunos geogr\u00e1ficamente pr\u00f3ximos. Porque en la Denominaci\u00f3n de Origen Bierzo, el mildiu es una enfermedad sist\u00e9mica de la vi\u00f1a que obliga a su control todos los a\u00f1os, unos m\u00e1s que otros, y si no se hace y no se hace correctamente, efectivamente se recogen cosechas m\u00edseras y adem\u00e1s de mala calidad. Cualquier viticultor berciano sabe que tras unas lluvias, aunque sean de una tormenta pasajera, toca sulfatar la vi\u00f1a con productos espec\u00edficos para prevenir y combatir esta afecci\u00f3n, y que eso supone tiempo, trabajo, y costes. Por eso, tambi\u00e9n por eso, la viticultura en las zonas del minifundismo berciano, como ocurre en la vecina Galicia, necesita que se remunere mejor el kilo de uva, para que sea rentable producirla, y eso justificar\u00eda un precio m\u00e1s elevado en la venta del vino que el consumidor no siempre est\u00e1 dispuesto a pagar, aunque se le compense en calidad.<\/p>\n<p>Los hongos son grandes enemigos del campo. Lo saben los viticultores o los lupuleros, pero tambi\u00e9n, por ejemplo, los remolacheros leoneses, que en las pr\u00f3ximas semanas luchar\u00e1n contra la cercospora, capaz de arruinar en pocos d\u00edas la expectativa de una buena cosecha de remolacha.<\/p>\n<p><em>*Art\u00edculo de opini\u00f3n de Jos\u00e9 Antonio Turrado publicado en La Nueva Cr\u00f3nica del viernes 1 de agosto de 2025.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pasada primavera, inusualmente lluviosa en Espa\u00f1a, trajo como consecuencia unas cosechas abundantes, como nunca se hab\u00edan visto, en los cultivos de invierno. Por el contrario, esa lluvia, tan continuada en el tiempo, ocasion\u00f3 la llegada de una enfermedad causada por hongos, el mildiu, que asol\u00f3 determinados cultivos como la vi\u00f1a. \u00a1El grito en el [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16444,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mildiu en la vi\u00f1a - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La pasada primavera, inusualmente lluviosa en Espa\u00f1a, trajo como consecuencia unas cosechas abundantes, como nunca se hab\u00edan visto, en los cultivos de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mildiu en la vi\u00f1a - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La pasada primavera, inusualmente lluviosa en Espa\u00f1a, trajo como consecuencia unas cosechas abundantes, como nunca se hab\u00edan visto, en los cultivos de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-01T06:38:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-01T06:38:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/08\/mildu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"341\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina\",\"name\":\"Mildiu en la vi\u00f1a - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/08\/mildu.jpg\",\"datePublished\":\"2025-08-01T06:38:03+00:00\",\"dateModified\":\"2025-08-01T06:38:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\"},\"description\":\"La pasada primavera, inusualmente lluviosa en Espa\u00f1a, trajo como consecuencia unas cosechas abundantes, como nunca se hab\u00edan visto, en los cultivos de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/08\/mildu.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/08\/mildu.jpg\",\"width\":512,\"height\":341},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mildiu en la vi\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32\",\"name\":\"Eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g\",\"caption\":\"Eduardo\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mildiu en la vi\u00f1a - ASAJA Le\u00f3n","description":"La pasada primavera, inusualmente lluviosa en Espa\u00f1a, trajo como consecuencia unas cosechas abundantes, como nunca se hab\u00edan visto, en los cultivos de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina","og_locale":"es_ES","og_type":"article","og_title":"Mildiu en la vi\u00f1a - ASAJA Le\u00f3n","og_description":"La pasada primavera, inusualmente lluviosa en Espa\u00f1a, trajo como consecuencia unas cosechas abundantes, como nunca se hab\u00edan visto, en los cultivos de","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2025-08-01T06:38:03+00:00","article_modified_time":"2025-08-01T06:38:06+00:00","og_image":[{"width":512,"height":341,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/08\/mildu.jpg","type":"image\/jpeg"}],"author":"Eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina","name":"Mildiu en la vi\u00f1a - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/08\/mildu.jpg","datePublished":"2025-08-01T06:38:03+00:00","dateModified":"2025-08-01T06:38:06+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32"},"description":"La pasada primavera, inusualmente lluviosa en Espa\u00f1a, trajo como consecuencia unas cosechas abundantes, como nunca se hab\u00edan visto, en los cultivos de","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/08\/mildu.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2025\/08\/mildu.jpg","width":512,"height":341},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/mildiu-en-la-vina#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Mildiu en la vi\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/a39ff3609fc182e4c789ab486e865d32","name":"Eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ebd6aba21d817dcf9595bc9ca505af5?s=96&d=mm&r=g","caption":"Eduardo"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/eduardovv"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16443"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=16443"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16443\/revisions"}],"predecessor-version":[{"id":16445,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/16443\/revisions\/16445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/16444"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=16443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=16443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=16443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}