{"id":205,"date":"2016-11-11T00:00:00","date_gmt":"2016-11-10T23:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2016\/11\/11\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector\/"},"modified":"2017-11-14T18:24:30","modified_gmt":"2017-11-14T17:24:30","slug":"asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector","title":{"rendered":"ASAJA INSTA A LAS ADMINISTRACIONES A APOYAR EL SEGURO AGROPECUARIO COMO HERRAMIENTA ESENCIAL PARA EL SECTOR"},"content":{"rendered":"<h2>Alto y creciente nivel de aseguramiento en Castilla y Le&#243;n, impulsado por las explotaciones profesionales<\/h2>\n<p align=\"center\">\n<span style=\"color:#006400;\"><strong>ASAJA INSTA A LAS ADMINISTRACIONES A APOYAR EL SEGURO AGROPECUARIO COMO HERRAMIENTA ESENCIAL PARA EL SECTOR0<\/strong><\/span><\/p>\n<p align=\"center\">\n<span style=\"color:#0000cd;\"><strong>Alto y creciente nivel de aseguramiento en Castilla y Le&#243;n, impulsado&#160;<\/strong><strong>por las explotaciones profesionales<\/strong>&#160; &#160; &#160; &#160; &#160; &#160; &#160; &#160; &#160; &#160;<\/span><\/p>\n<p style=\"text-align: justify;\">\nCon el comienzo de las siembras se inicia tambi&#233;n la campa&#241;a de contrataci&#243;n del seguro agrario, fundamental en Castilla y Le&#243;n, que es la comunidad aut&#243;noma con mayor superficie cubierta, 1.759.1655 hect&#225;reas, el 29,4 por ciento del total asegurado en nuestro pa&#237;s (5.981.048 Ha). Las complicadas campa&#241;as agr&#237;colas de 2014 y 2015, sumado al alto nivel de profesionalizaci&#243;n del sector de Castilla y Le&#243;n, explican el incremento del aseguramiento en 2016,&#160; con un 7,20% m&#225;s de superficie de cultivos herb&#225;ceos cubierta y un 3,43% m&#225;s de explotaciones con p&#243;liza.<\/p>\n<p style=\"text-align: justify;\">\nEn conjunto, sumando los cultivos herb&#225;ceos, oleaginosas, leguminosas y proteaginosas, producciones cubiertas por p&#243;liza, en Castilla y Le&#243;n casi tres de cada cuatro hect&#225;reas cuentan con seguro (un 72,85% del la superficie). Este porcentaje es inferior si se refiere a explotaciones agr&#237;colas, ya que son aproximadamente la mitad las que est&#225;n aseguradas (38.145, cuando el total regional suma unas 72.000). &#8220;Estas cifras apuntan que son las explotaciones m&#225;s dimensionadas y verdaderamente profesionales las que aseguran, porque saben que se est&#225;n jugando la rentabilidad de su empresa&#8221;, apunta Donaciano Dujo, presidente de ASAJA de Castilla y Le&#243;n. Por provincias, la que tiene un porcentaje m&#225;s alto de aseguramiento es Soria (92,94%), seguida por Burgos (79,99%), Valladolid (78,44%), Palencia (78,45%), Zamora (62,79%), Segovia (58,66%), &#193;vila (57,25%), Le&#243;n (55,75%) y por &#250;ltimo Salamanca (55,36%).<\/p>\n<p style=\"text-align: justify;\">\nSin embargo, el sistema de seguros agrarios, una de las pol&#237;ticas agrarias m&#225;s importantes de las promovidas en nuestro pa&#237;s en las &#250;ltimas d&#233;cadas, precisa del apoyo continuo de las administraciones, nacional y auton&#243;mica, para cumplir con sus objetivos. M&#225;s a&#250;n cuando el marco europeo e internacional, con unas relaciones cada vez m&#225;s vol&#225;tiles e inestables, hace necesario fortalecer al m&#225;ximo los sistemas de protecci&#243;n de los ingresos de las explotaciones agroganaderas.<\/p>\n<p style=\"text-align: justify;\">\nPese a las promesas de las administraciones, a&#250;n no se ha recuperado el apoyo que exist&#237;a al sistema de seguros agrarios antes de que comenzaran los recortes por la crisis. &#8220;Ha habido alg&#250;n ajuste, pero todav&#237;a muy incompleto. El &#160;ministerio ha aumentado la subvenci&#243;n pero a la vez ha subido el aseguramiento, lo que hace que la ayuda sea menor. Lo m&#225;s urgente es que la Junta recupere el apoyo al seguro y aplique la subvenci&#243;n directamente cuando se suscriba la p&#243;liza&#8221;, subraya ASAJA. Tambi&#233;n es hora de atender las demandas del sector ganadero, que pide que se ampl&#237;e la cobertura de la administraci&#243;n a l&#237;neas hasta ahora desprovistas de apoyo, como son los seguros de vida para el ganado.<\/p>\n<p style=\"text-align: justify;\">\nDe todos estos aspectos se debate hoy en Valladolid en una jornada organizada por ASAJA de Castilla y Le&#243;n, que cuenta con la participaci&#243;n de responsables&#160; de Agroseguro y de la Entidad Estatal de Seguros Agrarios (ENESA), entidad dependiente del Ministerio de Agricultura, Pesca, Alimentaci&#243;n y Medio Ambiente (MAPAMA), que expondr&#225;n todos los detalles sobre el momento actual de la contrataci&#243;n de seguros agrarios en la regi&#243;n y desgranar&#225;n las novedades del Plan Anual de Seguros Agrarios. Con estas ponencias se trata de actualizar y perfilar al m&#225;ximo todos los cambios que cada campa&#241;a modifican el marco del aseguramiento agrario, para que el equipo de la organizaci&#243;n asesore con la mayor eficiencia a los agricultores y ganaderos. Tambi&#233;n el equipo de ASAJA transmitir&#225; a los responsables de las entidades que gestionan el sistema de seguros en Espa&#241;a las demandas y quejas del sector. As&#237;, los agricultores plantean dudas sobre las condiciones que se marcan o los rendimientos por comarcas, no siempre adaptados a la realidad de la agricultura del siglo XXI.<\/p>\n<p>\n&#160;<\/p>\n<p>\n<strong>Evoluci&#243;n 2015-2016 del aseguramiento cultivos herb&#225;ceos Castilla y Le&#243;n <\/strong><\/p>\n<p>\n&#160;<\/p>\n<table border=\"1\" cellpadding=\"0\" cellspacing=\"0\">\n<tbody>\n<tr>\n<td rowspan=\"2\" style=\"width:115px;\">\n<p align=\"center\">\n<strong>CULTIVOS HERB&#193;CEOS<\/strong><\/p>\n<\/td>\n<td colspan=\"2\" style=\"width:230px;\">\n<p align=\"center\">\n2015<\/p>\n<\/td>\n<td colspan=\"2\" style=\"width:230px;\">\n<p align=\"center\">\n2016<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width:115px;\">\n<p align=\"center\">\nP&#243;lizas<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\nSuperficie (ha)<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\nP&#243;lizas<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\nSuperficie (ha)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width:115px;\">\n<p align=\"center\">\nM&#243;dulo 2 (sequ&#237;a, helada, pedrisco e incendio)<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n16.509<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n969.531<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n18.288<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n1.119.246<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width:115px;\">\n<p align=\"center\">\nM&#243;dulo P<\/p>\n<p align=\"center\">\n(pedrisco e incendio)<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n20.371<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n671.509<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n19.857<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n639.919<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width:115px;\">\n<p align=\"center\">\nTOTAL<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n36.880<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n1.641.040<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n38.145<\/p>\n<p align=\"center\">\n(+3,43%)<\/p>\n<\/td>\n<td style=\"width:115px;\">\n<p align=\"center\">\n1.759.165<\/p>\n<p align=\"center\">\n(+7,20%)<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n&#160;<\/p>\n<p>\nFuente: ASAJA CyL sobre datos de Enesa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alto y creciente nivel de aseguramiento en Castilla y Le&#243;n, impulsado por las explotaciones profesionales<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA INSTA A LAS ADMINISTRACIONES A APOYAR EL SEGURO AGROPECUARIO COMO HERRAMIENTA ESENCIAL PARA EL SECTOR - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Alto y creciente nivel de aseguramiento en Castilla y Le&#243;n, impulsado por las explotaciones profesionales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA INSTA A LAS ADMINISTRACIONES A APOYAR EL SEGURO AGROPECUARIO COMO HERRAMIENTA ESENCIAL PARA EL SECTOR - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Alto y creciente nivel de aseguramiento en Castilla y Le&#243;n, impulsado por las explotaciones profesionales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-10T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T17:24:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector\",\"name\":\"ASAJA INSTA A LAS ADMINISTRACIONES A APOYAR EL SEGURO AGROPECUARIO COMO HERRAMIENTA ESENCIAL PARA EL SECTOR - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2016-11-10T23:00:00+00:00\",\"dateModified\":\"2017-11-14T17:24:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Alto y creciente nivel de aseguramiento en Castilla y Le&#243;n, impulsado por las explotaciones profesionales\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA INSTA A LAS ADMINISTRACIONES A APOYAR EL SEGURO AGROPECUARIO COMO HERRAMIENTA ESENCIAL PARA EL SECTOR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA INSTA A LAS ADMINISTRACIONES A APOYAR EL SEGURO AGROPECUARIO COMO HERRAMIENTA ESENCIAL PARA EL SECTOR - ASAJA Le\u00f3n","description":"Alto y creciente nivel de aseguramiento en Castilla y Le&#243;n, impulsado por las explotaciones profesionales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector","og_locale":"es_ES","og_type":"article","og_title":"ASAJA INSTA A LAS ADMINISTRACIONES A APOYAR EL SEGURO AGROPECUARIO COMO HERRAMIENTA ESENCIAL PARA EL SECTOR - ASAJA Le\u00f3n","og_description":"Alto y creciente nivel de aseguramiento en Castilla y Le&#243;n, impulsado por las explotaciones profesionales","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2016-11-10T23:00:00+00:00","article_modified_time":"2017-11-14T17:24:30+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector","name":"ASAJA INSTA A LAS ADMINISTRACIONES A APOYAR EL SEGURO AGROPECUARIO COMO HERRAMIENTA ESENCIAL PARA EL SECTOR - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2016-11-10T23:00:00+00:00","dateModified":"2017-11-14T17:24:30+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Alto y creciente nivel de aseguramiento en Castilla y Le&#243;n, impulsado por las explotaciones profesionales","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-insta-a-las-administraciones-a-apoyar-el-seguro-agropecuario-como-herramienta-esencial-para-el-sector#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ASAJA INSTA A LAS ADMINISTRACIONES A APOYAR EL SEGURO AGROPECUARIO COMO HERRAMIENTA ESENCIAL PARA EL SECTOR"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/205"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=205"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/205\/revisions"}],"predecessor-version":[{"id":3770,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/205\/revisions\/3770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}