{"id":281,"date":"2016-04-21T00:00:00","date_gmt":"2016-04-20T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2016\/04\/21\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl\/"},"modified":"2017-11-14T18:25:54","modified_gmt":"2017-11-14T17:25:54","slug":"comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl","title":{"rendered":"COMUNICADO DE LAS ORGANIZACIONES PROFESIONALES AGRARIAS DE LA PROVINCIA DE LE&#211;N (ASAJA, UGAL-UPA, UCCL, UCALE-COAG Y OPL)"},"content":{"rendered":"<h2>Tras los distintos actos de protesta llevados a cabo por los ganaderos y las organizaciones profesionales agrarias de la provincia de Le&#243;n, en las &#250;ltimas semanas, manifest&#225;ndonos ante la Delegaci&#243;n Territorial de la Junta de Castilla y Le&#243;n, y derramando parte de la leche que las industrias han dejado de recoger&#225; a dos docenas de ganaderos, desde el pasado 1 de abril, los resultados obtenidos no son satisfactorios<\/h2>\n<p>\n&#160;<\/p>\n<p align=\"center\">\n<span style=\"color:#006400;\"><strong>COMUNICADO DE LAS ORGANIZACIONES PROFESIONALES AGRARIAS DE LA PROVINCIA DE LEON (ASAJA, UGAL-UPA, UCCL, UCALE-COAG Y OPL)<\/strong><\/span><\/p>\n<p>\n<span style=\"text-align: justify;\">Tras los distintos actos de protesta llevados a cabo por los ganaderos y las organizaciones profesionales agrarias de la provincia de Le&#243;n, en las &#250;ltimas semanas, manifest&#225;ndonos ante la Delegaci&#243;n Territorial de la Junta de Castilla y Le&#243;n, y derramando parte de la leche que las industrias han dejado de recoger&#225; a dos docenas de ganaderos, desde el pasado 1 de abril, los resultados obtenidos no son satisfactorios.<\/span><\/p>\n<p style=\"text-align: justify;\">\nEl balance es que aproximadamente la mitad de los afectados han encontrado un comprador, independientemente de los precios a los que le liquide las entregas y que en ning&#250;n caso se han podido negociar. La otra mitad, doce en concreto, no han encontrado empresa que se interese por su leche (una producci&#243;n de 3.100 litros diarios), por lo que al d&#237;a de hoy dan casi por abandonada su actividad como ganaderos de vacuno de leche. Tampoco han dado resultado los contactos que las organizaciones han mantenido con alguna industria.<\/p>\n<p style=\"text-align: justify;\">\nLas organizaciones profesionales agrarias que han convocado estas protestas culpan a la administraci&#243;n auton&#243;mica y a las instituciones leonesas en general, de no haber hecho nada para evitar la p&#233;rdida de ganader&#237;as en la monta&#241;a de la provincia, provocando con ello una sangr&#237;a m&#225;s al tejido productivo y a la poblaci&#243;n del medio rural. Las organizaciones convocantes hacen un llamamiento a la consejer&#237;a de Agricultura y a otras instituciones para que agoten la &#250;ltima posibilidad, si es que existe, antes del cierre definitivo de estas ganader&#237;as, que se le compense con ayudas por las p&#233;rdidas que est&#225;n sufriendo, y que&#160; llegado el momento, se le apoye econ&#243;micamente para la reconversi&#243;n a otros subsectores agroganaderos, como es el vacuno de carne extensivo.<\/p>\n<p style=\"text-align: justify;\">\nLas organizaciones agrarias recuerdan que a este problema se suma los bajos precios que perciben todos los ganaderos en general, la inestabilidad por la firma de contratos a corto plazo (tres meses), la amenaza permanente de dejar recogidas, y el incremento de ganaderos y cooperativas que est&#225;n vendiendo toda o parte de su producci&#243;n como leche spot con precios inferiores a los 20 c&#233;ntimos de euro el litro.<\/p>\n<p style=\"text-align: justify;\">\nEn Le&#243;n, a 21 de abril de 2016<\/p>\n<p style=\"text-align: justify;\">\nHa quedado desconvocado sin fecha el acto de protesta que estaba previsto para el viernes d&#237;a 22 ante la sede de la Junta de Castilla y Le&#243;n.<\/p>\n<p style=\"text-align: justify;\">\n&#160;<\/p>\n<p>\n&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras los distintos actos de protesta llevados a cabo por los ganaderos y las organizaciones profesionales agrarias de la provincia de Le&#243;n, en las &#250;ltimas semanas, manifest&#225;ndonos ante la Delegaci&#243;n Territorial de la Junta de Castilla y Le&#243;n, y derramando parte de la leche que las industrias han dejado de recoger&#225; a dos docenas de ganaderos, desde el pasado 1 de abril, los resultados obtenidos no son satisfactorios<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COMUNICADO DE LAS ORGANIZACIONES PROFESIONALES AGRARIAS DE LA PROVINCIA DE LE&#211;N (ASAJA, UGAL-UPA, UCCL, UCALE-COAG Y OPL) - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Tras los distintos actos de protesta llevados a cabo por los ganaderos y las organizaciones profesionales agrarias de la provincia de Le&#243;n, en las &#250;ltimas semanas, manifest&#225;ndonos ante la Delegaci&#243;n Territorial de la Junta de Castilla y Le&#243;n, y derramando parte de la leche que las industrias han dejado de recoger&#225; a dos docenas de ganaderos, desde el pasado 1 de abril, los resultados obtenidos no son satisfactorios\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMUNICADO DE LAS ORGANIZACIONES PROFESIONALES AGRARIAS DE LA PROVINCIA DE LE&#211;N (ASAJA, UGAL-UPA, UCCL, UCALE-COAG Y OPL) - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Tras los distintos actos de protesta llevados a cabo por los ganaderos y las organizaciones profesionales agrarias de la provincia de Le&#243;n, en las &#250;ltimas semanas, manifest&#225;ndonos ante la Delegaci&#243;n Territorial de la Junta de Castilla y Le&#243;n, y derramando parte de la leche que las industrias han dejado de recoger&#225; a dos docenas de ganaderos, desde el pasado 1 de abril, los resultados obtenidos no son satisfactorios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-20T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T17:25:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl\",\"name\":\"COMUNICADO DE LAS ORGANIZACIONES PROFESIONALES AGRARIAS DE LA PROVINCIA DE LE&#211;N (ASAJA, UGAL-UPA, UCCL, UCALE-COAG Y OPL) - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2016-04-20T22:00:00+00:00\",\"dateModified\":\"2017-11-14T17:25:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Tras los distintos actos de protesta llevados a cabo por los ganaderos y las organizaciones profesionales agrarias de la provincia de Le&#243;n, en las &#250;ltimas semanas, manifest&#225;ndonos ante la Delegaci&#243;n Territorial de la Junta de Castilla y Le&#243;n, y derramando parte de la leche que las industrias han dejado de recoger&#225; a dos docenas de ganaderos, desde el pasado 1 de abril, los resultados obtenidos no son satisfactorios\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMUNICADO DE LAS ORGANIZACIONES PROFESIONALES AGRARIAS DE LA PROVINCIA DE LE&#211;N (ASAJA, UGAL-UPA, UCCL, UCALE-COAG Y OPL)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMUNICADO DE LAS ORGANIZACIONES PROFESIONALES AGRARIAS DE LA PROVINCIA DE LE&#211;N (ASAJA, UGAL-UPA, UCCL, UCALE-COAG Y OPL) - ASAJA Le\u00f3n","description":"Tras los distintos actos de protesta llevados a cabo por los ganaderos y las organizaciones profesionales agrarias de la provincia de Le&#243;n, en las &#250;ltimas semanas, manifest&#225;ndonos ante la Delegaci&#243;n Territorial de la Junta de Castilla y Le&#243;n, y derramando parte de la leche que las industrias han dejado de recoger&#225; a dos docenas de ganaderos, desde el pasado 1 de abril, los resultados obtenidos no son satisfactorios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl","og_locale":"es_ES","og_type":"article","og_title":"COMUNICADO DE LAS ORGANIZACIONES PROFESIONALES AGRARIAS DE LA PROVINCIA DE LE&#211;N (ASAJA, UGAL-UPA, UCCL, UCALE-COAG Y OPL) - ASAJA Le\u00f3n","og_description":"Tras los distintos actos de protesta llevados a cabo por los ganaderos y las organizaciones profesionales agrarias de la provincia de Le&#243;n, en las &#250;ltimas semanas, manifest&#225;ndonos ante la Delegaci&#243;n Territorial de la Junta de Castilla y Le&#243;n, y derramando parte de la leche que las industrias han dejado de recoger&#225; a dos docenas de ganaderos, desde el pasado 1 de abril, los resultados obtenidos no son satisfactorios","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2016-04-20T22:00:00+00:00","article_modified_time":"2017-11-14T17:25:54+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl","name":"COMUNICADO DE LAS ORGANIZACIONES PROFESIONALES AGRARIAS DE LA PROVINCIA DE LE&#211;N (ASAJA, UGAL-UPA, UCCL, UCALE-COAG Y OPL) - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2016-04-20T22:00:00+00:00","dateModified":"2017-11-14T17:25:54+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Tras los distintos actos de protesta llevados a cabo por los ganaderos y las organizaciones profesionales agrarias de la provincia de Le&#243;n, en las &#250;ltimas semanas, manifest&#225;ndonos ante la Delegaci&#243;n Territorial de la Junta de Castilla y Le&#243;n, y derramando parte de la leche que las industrias han dejado de recoger&#225; a dos docenas de ganaderos, desde el pasado 1 de abril, los resultados obtenidos no son satisfactorios","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-profesionales-agrarias-de-la-provincia-de-len-asaja-ugal-upa-uccl-ucale-coag-y-opl#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"COMUNICADO DE LAS ORGANIZACIONES PROFESIONALES AGRARIAS DE LA PROVINCIA DE LE&#211;N (ASAJA, UGAL-UPA, UCCL, UCALE-COAG Y OPL)"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/281"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/281\/revisions"}],"predecessor-version":[{"id":3846,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/281\/revisions\/3846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}