{"id":291,"date":"2016-04-05T00:00:00","date_gmt":"2016-04-04T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2016\/04\/05\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl\/"},"modified":"2017-11-14T18:26:34","modified_gmt":"2017-11-14T17:26:34","slug":"comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl","title":{"rendered":"COMUNICADO DE LAS ORGANIZACIONES AGRARIAS ASAJA-LEON, UGAL-UPA, UCALE-COAG, UCCL-LEON Y OPL"},"content":{"rendered":"<h2>Tras la reuni&#243;n celebrada en la ma&#241;ana de hoy  en la C&#225;mara Agraria Provincial, con el grupo de ganaderos de la zona de monta&#241;a de la provincia a los que le han dejado de recoger la leche desde el pasado 1 de abril, se ha acordado llevar a cabo un acto de protesta ma&#241;ana mi&#233;rcoles d&#237;a 6 de abril, a las 12 del mediod&#237;a, ante la sede de la Junta de Castilla y Le&#243;n en la capital leonesa. Los ganaderos que no encuentran comprador desde el pasado viernes son 14, y tienen una producci&#243;n diaria en sus explotaciones de unos 6.500 litros de leche.<\/h2>\n<p align=\"center\">\n<span style=\"color:#006400;\"><strong>COMUNICADO DE LAS ORGANIZACIONES AGRARIAS ASAJA-LEON, UGAL-UPA, UCALE-COAG, UCCL-LEON Y OPL<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\nTras la reuni&#243;n celebrada en la ma&#241;ana de hoy&#160; en la C&#225;mara Agraria Provincial, con el grupo de ganaderos de la zona de monta&#241;a de la provincia a los que le han dejado de recoger la leche desde el pasado 1 de abril, se ha acordado llevar a cabo un acto de protesta ma&#241;ana <strong><u>mi&#233;rcoles d&#237;a 6 de abril, a las 12 del mediod&#237;a<\/u><\/strong>, ante la <strong><u>sede de la Junta de Castilla y Le&#243;n<\/u><\/strong> en la capital leonesa. Los ganaderos que no encuentran comprador desde el pasado viernes son 14, y tienen una producci&#243;n diaria en sus explotaciones de unos 6.500 litros de leche.<\/p>\n<p style=\"text-align: justify;\">\nEn la concentraci&#243;n, y con el fin de escenificar la dif&#237;cil situaci&#243;n que est&#225;n atravesando y exigir a la Junta de Castilla y Le&#243;n que impida que quede leche sin recoger en el campo, se derramar&#225;n varios cientos de litros de leche que los propios ganaderos traer&#225;n con sus medios.<\/p>\n<p>\nLe&#243;n, 5 de abril de 2016.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la reuni&#243;n celebrada en la ma&#241;ana de hoy  en la C&#225;mara Agraria Provincial, con el grupo de ganaderos de la zona de monta&#241;a de la provincia a los que le han dejado de recoger la leche desde el pasado 1 de abril, se ha acordado llevar a cabo un acto de protesta ma&#241;ana mi&#233;rcoles d&#237;a 6 de abril, a las 12 del mediod&#237;a, ante la sede de la Junta de Castilla y Le&#243;n en la capital leonesa. Los ganaderos que no encuentran comprador desde el pasado viernes son 14, y tienen una producci&#243;n diaria en sus explotaciones de unos 6.500 litros de leche.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COMUNICADO DE LAS ORGANIZACIONES AGRARIAS ASAJA-LEON, UGAL-UPA, UCALE-COAG, UCCL-LEON Y OPL - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Tras la reuni&#243;n celebrada en la ma&#241;ana de hoy en la C&#225;mara Agraria Provincial, con el grupo de ganaderos de la zona de monta&#241;a de la provincia a los que le han dejado de recoger la leche desde el pasado 1 de abril, se ha acordado llevar a cabo un acto de protesta ma&#241;ana mi&#233;rcoles d&#237;a 6 de abril, a las 12 del mediod&#237;a, ante la sede de la Junta de Castilla y Le&#243;n en la capital leonesa. Los ganaderos que no encuentran comprador desde el pasado viernes son 14, y tienen una producci&#243;n diaria en sus explotaciones de unos 6.500 litros de leche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMUNICADO DE LAS ORGANIZACIONES AGRARIAS ASAJA-LEON, UGAL-UPA, UCALE-COAG, UCCL-LEON Y OPL - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Tras la reuni&#243;n celebrada en la ma&#241;ana de hoy en la C&#225;mara Agraria Provincial, con el grupo de ganaderos de la zona de monta&#241;a de la provincia a los que le han dejado de recoger la leche desde el pasado 1 de abril, se ha acordado llevar a cabo un acto de protesta ma&#241;ana mi&#233;rcoles d&#237;a 6 de abril, a las 12 del mediod&#237;a, ante la sede de la Junta de Castilla y Le&#243;n en la capital leonesa. Los ganaderos que no encuentran comprador desde el pasado viernes son 14, y tienen una producci&#243;n diaria en sus explotaciones de unos 6.500 litros de leche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-04T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T17:26:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl\",\"name\":\"COMUNICADO DE LAS ORGANIZACIONES AGRARIAS ASAJA-LEON, UGAL-UPA, UCALE-COAG, UCCL-LEON Y OPL - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2016-04-04T22:00:00+00:00\",\"dateModified\":\"2017-11-14T17:26:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Tras la reuni&#243;n celebrada en la ma&#241;ana de hoy en la C&#225;mara Agraria Provincial, con el grupo de ganaderos de la zona de monta&#241;a de la provincia a los que le han dejado de recoger la leche desde el pasado 1 de abril, se ha acordado llevar a cabo un acto de protesta ma&#241;ana mi&#233;rcoles d&#237;a 6 de abril, a las 12 del mediod&#237;a, ante la sede de la Junta de Castilla y Le&#243;n en la capital leonesa. Los ganaderos que no encuentran comprador desde el pasado viernes son 14, y tienen una producci&#243;n diaria en sus explotaciones de unos 6.500 litros de leche.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COMUNICADO DE LAS ORGANIZACIONES AGRARIAS ASAJA-LEON, UGAL-UPA, UCALE-COAG, UCCL-LEON Y OPL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMUNICADO DE LAS ORGANIZACIONES AGRARIAS ASAJA-LEON, UGAL-UPA, UCALE-COAG, UCCL-LEON Y OPL - ASAJA Le\u00f3n","description":"Tras la reuni&#243;n celebrada en la ma&#241;ana de hoy en la C&#225;mara Agraria Provincial, con el grupo de ganaderos de la zona de monta&#241;a de la provincia a los que le han dejado de recoger la leche desde el pasado 1 de abril, se ha acordado llevar a cabo un acto de protesta ma&#241;ana mi&#233;rcoles d&#237;a 6 de abril, a las 12 del mediod&#237;a, ante la sede de la Junta de Castilla y Le&#243;n en la capital leonesa. Los ganaderos que no encuentran comprador desde el pasado viernes son 14, y tienen una producci&#243;n diaria en sus explotaciones de unos 6.500 litros de leche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl","og_locale":"es_ES","og_type":"article","og_title":"COMUNICADO DE LAS ORGANIZACIONES AGRARIAS ASAJA-LEON, UGAL-UPA, UCALE-COAG, UCCL-LEON Y OPL - ASAJA Le\u00f3n","og_description":"Tras la reuni&#243;n celebrada en la ma&#241;ana de hoy en la C&#225;mara Agraria Provincial, con el grupo de ganaderos de la zona de monta&#241;a de la provincia a los que le han dejado de recoger la leche desde el pasado 1 de abril, se ha acordado llevar a cabo un acto de protesta ma&#241;ana mi&#233;rcoles d&#237;a 6 de abril, a las 12 del mediod&#237;a, ante la sede de la Junta de Castilla y Le&#243;n en la capital leonesa. Los ganaderos que no encuentran comprador desde el pasado viernes son 14, y tienen una producci&#243;n diaria en sus explotaciones de unos 6.500 litros de leche.","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2016-04-04T22:00:00+00:00","article_modified_time":"2017-11-14T17:26:34+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl","name":"COMUNICADO DE LAS ORGANIZACIONES AGRARIAS ASAJA-LEON, UGAL-UPA, UCALE-COAG, UCCL-LEON Y OPL - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2016-04-04T22:00:00+00:00","dateModified":"2017-11-14T17:26:34+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Tras la reuni&#243;n celebrada en la ma&#241;ana de hoy en la C&#225;mara Agraria Provincial, con el grupo de ganaderos de la zona de monta&#241;a de la provincia a los que le han dejado de recoger la leche desde el pasado 1 de abril, se ha acordado llevar a cabo un acto de protesta ma&#241;ana mi&#233;rcoles d&#237;a 6 de abril, a las 12 del mediod&#237;a, ante la sede de la Junta de Castilla y Le&#243;n en la capital leonesa. Los ganaderos que no encuentran comprador desde el pasado viernes son 14, y tienen una producci&#243;n diaria en sus explotaciones de unos 6.500 litros de leche.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/comunicado-de-las-organizaciones-agrarias-asaja-leon-ugal-upa-ucale-coag-uccl-leon-y-opl#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"COMUNICADO DE LAS ORGANIZACIONES AGRARIAS ASAJA-LEON, UGAL-UPA, UCALE-COAG, UCCL-LEON Y OPL"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/291"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=291"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/291\/revisions"}],"predecessor-version":[{"id":3856,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/291\/revisions\/3856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}