{"id":2987,"date":"2015-09-29T00:00:00","date_gmt":"2015-09-28T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2015\/09\/29\/ayudas-del-estado-al-vacuno-de-leche\/"},"modified":"2017-11-14T16:52:26","modified_gmt":"2017-11-14T15:52:26","slug":"ayudas-del-estado-al-vacuno-de-leche","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche","title":{"rendered":"AYUDAS DEL ESTADO AL VACUNO DE LECHE"},"content":{"rendered":"<h2>El martes 29 de septiembre se public&#243; en el BOE el Real Decreto 849\/2015 por el que se establecen las normas reguladoras para la concesi&#243;n directa de ayudas &#8220;de m&#237;nimis&#8221; destinadas a compensar las dificultades econ&#243;micas en el sector l&#225;cteo.<\/h2>\n<p align=\"center\">\n<span style=\"color:#006400;\"><strong>AYUDAS DEL ESTADO AL VACUNO DE LECHE<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\nEl martes 29 de septiembre se public&#243; en el BOE el Real Decreto 849\/2015 por el que se establecen las normas reguladoras para la concesi&#243;n directa de ayudas &#8220;de m&#237;nimis&#8221; destinadas a compensar las dificultades econ&#243;micas en el sector l&#225;cteo. Van dirigidas a titulares de ganader&#237;as de vacuno de leche que hayan efectuado entregas a compradores en los meses de abril, mayo, junio y julio, y que en la facturaci&#243;n, no hayan alcanzado unos umbrales de precios que va a determinar el Magrama, y que al d&#237;a de hoy no se conocen. El ministerio va a establecer dos umbrales, y por debajo del m&#225;s bajo de ellos, se aprobar&#225; una ayuda de 300 euros por vaca,&#160; mientras que por debajo del umbral m&#225;s alto que establezca, la ayuda ser&#225; de 110 eros por vaca. Ninguna explotaci&#243;n cobrar&#225; m&#225;s de 10.000 euros por este concepto. Los animales que se tienen en cuenta para efectuar estos pagos, son los que consten en el registro oficial a fecha 30 de septiembre. Estas ayudas las concede el ministerio con los datos que obran en su poder, por lo tanto no es necesario solicitarlas y no hay un plazo para hacerlo.&#160; Habr&#225; una propuesta de resoluci&#243;n que se publicar&#225; en la web del ministerio, a la cual el interesado podr&#225; presentar alegaciones y comunicar el n&#250;mero de cuenta en el que quiere que se le abone el importe.<\/p>\n<p>\n<a href=\"http:\/\/www.boe.es\/boe\/dias\/2015\/09\/29\/pdfs\/BOE-A-2015-10396.pdf\">Real Decreto 849\/2015, de 28 de septiembre, por el que se establecen las normas reguladoras para la concesi&#243;n directa de ayudas &#34;de minimis&#34; destinadas a compensar las dificultades econ&#243;micas en el sector l&#225;cteo.<\/a><\/p>\n<p>\nASAJA Le&#243;n, 29 septiembre de 2015.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El martes 29 de septiembre se public&#243; en el BOE el Real Decreto 849\/2015 por el que se establecen las normas reguladoras para la concesi&#243;n directa de ayudas &#8220;de m&#237;nimis&#8221; destinadas a compensar las dificultades econ&#243;micas en el sector l&#225;cteo.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AYUDAS DEL ESTADO AL VACUNO DE LECHE - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"El martes 29 de septiembre se public&#243; en el BOE el Real Decreto 849\/2015 por el que se establecen las normas reguladoras para la concesi&#243;n directa de ayudas &#8220;de m&#237;nimis&#8221; destinadas a compensar las dificultades econ&#243;micas en el sector l&#225;cteo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AYUDAS DEL ESTADO AL VACUNO DE LECHE - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El martes 29 de septiembre se public&#243; en el BOE el Real Decreto 849\/2015 por el que se establecen las normas reguladoras para la concesi&#243;n directa de ayudas &#8220;de m&#237;nimis&#8221; destinadas a compensar las dificultades econ&#243;micas en el sector l&#225;cteo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-28T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T15:52:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche\",\"name\":\"AYUDAS DEL ESTADO AL VACUNO DE LECHE - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2015-09-28T22:00:00+00:00\",\"dateModified\":\"2017-11-14T15:52:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"El martes 29 de septiembre se public&#243; en el BOE el Real Decreto 849\/2015 por el que se establecen las normas reguladoras para la concesi&#243;n directa de ayudas &#8220;de m&#237;nimis&#8221; destinadas a compensar las dificultades econ&#243;micas en el sector l&#225;cteo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AYUDAS DEL ESTADO AL VACUNO DE LECHE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AYUDAS DEL ESTADO AL VACUNO DE LECHE - ASAJA Le\u00f3n","description":"El martes 29 de septiembre se public&#243; en el BOE el Real Decreto 849\/2015 por el que se establecen las normas reguladoras para la concesi&#243;n directa de ayudas &#8220;de m&#237;nimis&#8221; destinadas a compensar las dificultades econ&#243;micas en el sector l&#225;cteo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche","og_locale":"es_ES","og_type":"article","og_title":"AYUDAS DEL ESTADO AL VACUNO DE LECHE - ASAJA Le\u00f3n","og_description":"El martes 29 de septiembre se public&#243; en el BOE el Real Decreto 849\/2015 por el que se establecen las normas reguladoras para la concesi&#243;n directa de ayudas &#8220;de m&#237;nimis&#8221; destinadas a compensar las dificultades econ&#243;micas en el sector l&#225;cteo.","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2015-09-28T22:00:00+00:00","article_modified_time":"2017-11-14T15:52:26+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche","name":"AYUDAS DEL ESTADO AL VACUNO DE LECHE - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2015-09-28T22:00:00+00:00","dateModified":"2017-11-14T15:52:26+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"El martes 29 de septiembre se public&#243; en el BOE el Real Decreto 849\/2015 por el que se establecen las normas reguladoras para la concesi&#243;n directa de ayudas &#8220;de m&#237;nimis&#8221; destinadas a compensar las dificultades econ&#243;micas en el sector l&#225;cteo.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/ayudas-del-estado-al-vacuno-de-leche#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"AYUDAS DEL ESTADO AL VACUNO DE LECHE"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/2987"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=2987"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/2987\/revisions"}],"predecessor-version":[{"id":4187,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/2987\/revisions\/4187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=2987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=2987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=2987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}