{"id":3011,"date":"2014-10-01T00:00:00","date_gmt":"2014-09-30T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2014\/10\/01\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015\/"},"modified":"2017-11-14T16:52:49","modified_gmt":"2017-11-14T15:52:49","slug":"cmo-se-pagar-la-remolacha-en-esta-campaa-20142015","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015","title":{"rendered":"&#191;C&#243;mo se pagar&#225; la remolacha en esta campa&#241;a 2014\/2015?"},"content":{"rendered":"<h2><\/h2>\n<p align=\"center\">\n<strong>&#160;<\/strong><\/p>\n<p style=\"text-align: justify\">\nEn esta &#250;ltima campa&#241;a 2014\/2015 antes de la entrada en vigor de la reforma de la PAC&#160; y de un nuevo AMI, la remolacha tiene un precio oficial de 26,29 &#8364;\/t. A esta cantidad se le resta 0,84 &#8364;\/t. en concepto de canon de producci&#243;n. Se suman otros conceptos como 0,36 &#8364;\/t. por compensaci&#243;n de pulpa, 2 &#8364;\/t. por renunciar al derecho de retirada de pulpa y 9,60 &#8364;\/t. de complemento de precio de Azucarera. A estos 37,41 &#8364;\/t. totales, se le suma la subvenci&#243;n a la calidad, que se estima en 2,60 euros la tonelada, lo que lleva el precio total a 40 euros la tonelada.<strong>&#160;<\/strong><\/p>\n<p style=\"text-align: justify\">\n<strong>Los 37,41 euros tonelada figuran en factura, por lo tanto se pagan con las liquidaciones mensuales reteniendo un 10% para el final de la campa&#241;a. A dicha cantidad se le suma el IVA que corresponda seg&#250;n el r&#233;gimen en el que est&#233; el agricultor (12% si es R&#233;gimen Especial Agrario), y se resta el importe del IRPF (2%) si es el caso.&#160;<\/strong><\/p>\n<p>\n<strong>La subvenci&#243;n a la calidad se cobra cuando finalice la campa&#241;a remolachera en Espa&#241;a, por lo que hay que esperar a las entregas de Andaluc&#237;a, que ser&#225;n en el verano de 2015. El mes de septiembre de 2015 ser&#237;a la fecha previsible de pago de la ayuda a la calidad de unos 2,60 euros por tonelada.<\/strong><\/p>\n<p>\n<strong>&#160;<\/strong><\/p>\n<p>\n<strong>Adem&#225;s, los agricultores que pacten con Azucarera un acuerdo de entrega tard&#237;a, recibir&#225;n un pago adicional que va de 1 a 1,75 &#8364;\/t.<\/strong><\/p>\n<p>\n<strong>&#160;<\/strong><\/p>\n<p>\n<strong>ASAJA Le&#243;n, octubre 2014.&#160;<\/strong><\/p>\n<p>\n<strong><strong><span fck_bookmark=\"1\" style=\"display: none\">&#160;<\/span><\/strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#160; En esta &#250;ltima campa&#241;a 2014\/2015 antes de la entrada en vigor de la reforma de la PAC&#160; y de un nuevo AMI, la remolacha tiene un precio oficial de 26,29 &#8364;\/t. A esta cantidad se le resta 0,84 &#8364;\/t. en concepto de canon de producci&#243;n. Se suman otros conceptos como 0,36 &#8364;\/t. por compensaci&#243;n [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&#191;C&#243;mo se pagar&#225; la remolacha en esta campa&#241;a 2014\/2015? - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"&#160; En esta &#250;ltima campa&#241;a 2014\/2015 antes de la entrada en vigor de la reforma de la PAC&#160; y de un nuevo AMI, la remolacha tiene un\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#191;C&#243;mo se pagar&#225; la remolacha en esta campa&#241;a 2014\/2015? - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"&#160; En esta &#250;ltima campa&#241;a 2014\/2015 antes de la entrada en vigor de la reforma de la PAC&#160; y de un nuevo AMI, la remolacha tiene un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-30T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T15:52:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015\",\"name\":\"&#191;C&#243;mo se pagar&#225; la remolacha en esta campa&#241;a 2014\/2015? - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2014-09-30T22:00:00+00:00\",\"dateModified\":\"2017-11-14T15:52:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"&#160; En esta &#250;ltima campa&#241;a 2014\/2015 antes de la entrada en vigor de la reforma de la PAC&#160; y de un nuevo AMI, la remolacha tiene un\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#191;C&#243;mo se pagar&#225; la remolacha en esta campa&#241;a 2014\/2015?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"&#191;C&#243;mo se pagar&#225; la remolacha en esta campa&#241;a 2014\/2015? - ASAJA Le\u00f3n","description":"&#160; En esta &#250;ltima campa&#241;a 2014\/2015 antes de la entrada en vigor de la reforma de la PAC&#160; y de un nuevo AMI, la remolacha tiene un","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015","og_locale":"es_ES","og_type":"article","og_title":"&#191;C&#243;mo se pagar&#225; la remolacha en esta campa&#241;a 2014\/2015? - ASAJA Le\u00f3n","og_description":"&#160; En esta &#250;ltima campa&#241;a 2014\/2015 antes de la entrada en vigor de la reforma de la PAC&#160; y de un nuevo AMI, la remolacha tiene un","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2014-09-30T22:00:00+00:00","article_modified_time":"2017-11-14T15:52:49+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015","name":"&#191;C&#243;mo se pagar&#225; la remolacha en esta campa&#241;a 2014\/2015? - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2014-09-30T22:00:00+00:00","dateModified":"2017-11-14T15:52:49+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"&#160; En esta &#250;ltima campa&#241;a 2014\/2015 antes de la entrada en vigor de la reforma de la PAC&#160; y de un nuevo AMI, la remolacha tiene un","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/cmo-se-pagar-la-remolacha-en-esta-campaa-20142015#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"&#191;C&#243;mo se pagar&#225; la remolacha en esta campa&#241;a 2014\/2015?"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/3011"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=3011"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/3011\/revisions"}],"predecessor-version":[{"id":4211,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/3011\/revisions\/4211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=3011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=3011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=3011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}