{"id":3098,"date":"2004-03-04T00:00:00","date_gmt":"2004-03-03T23:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2004\/03\/04\/la-industria-emitira-recibo-por-cada-entrega-de-leche\/"},"modified":"2017-11-14T16:54:17","modified_gmt":"2017-11-14T15:54:17","slug":"la-industria-emitira-recibo-por-cada-entrega-de-leche","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche","title":{"rendered":"LA INDUSTRIA EMITIRA RECIBO POR CADA ENTREGA DE LECHE"},"content":{"rendered":"<h2>El Real Decreto 217\/2004 de 6 de febrero, y la normativa para su desarrollo que prepara la comunidad aut&#243;noma de Castilla y Le&#243;n, contempla una serie de registros y obligaciones de los ganaderos y otros agentes que intervienen en la comercializaci&#243;n de la leche.<\/h2>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"center\"><font size=\"2\">&#160;<\/font><b><font size=\"2\"> <\/font><font color=\"#009900\" size=\"2\">LA INDUSTRIA EMITIRA RECIBO <\/font><font color=\"#009900\" size=\"2\">POR CADA ENTREGA DE LECHE<\/font><\/b><font size=\"2\"> <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">El Real Decreto 217\/2004 de 6 de febrero, y la normativa para su desarrollo que prepara la comunidad aut&#243;noma de Castilla y Le&#243;n, contempla una serie de registros y obligaciones de los ganaderos y otros agentes que intervienen en la comercializaci&#243;n de la leche. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">De entrada, y en pr&#243;ximas fechas, tanto ganaderos como otros operadores tendr&#225;n que darse de alta en el registro correspondiente, para lo que habr&#225; que tramitar la correspondiente solicitud, y se inscribir&#225; as&#237; mismo los tanques de leche que tengan el ganadero en su explotaci&#243;n (c&#243;digo de explotaci&#243;n, marca, modelo y capacidad). <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">A partir del 1 de abril, todos los ganaderos tendr&#225;n que anotar en un impreso normalizado los d&#237;as que entregan leche, la cantidad entregada, el comprador, el c&#243;digo de identificaci&#243;n de la cisterna que la recoge, la fecha de la toma de muestras, y los resultados de esa toma de muestras una vez que los env&#237;e el laboratorio. Esta informaci&#243;n estar&#225; permanentemente actualizada, y existe la obligaci&#243;n de hacer las anotaciones en el momento de realizarse el movimiento de la leche de la explotaci&#243;n a la cisterna. Este registro se conservar&#225; como m&#237;nimo durante 3 a&#241;os, y estar&#225; a disposici&#243;n de la autoridad competente. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font><u><\/p>\n<p align=\"justify\"><font color=\"#0066ff\" size=\"2\">Albaranes de entrega de la leche.<\/font><\/p>\n<p><\/u><font size=\"2\"> <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">La empresa que compra la leche proporcionar&#225; cada d&#237;a al ganadero un recibo tipo \u00abalbar&#225;n\u00bb, en el que se recoger&#225; informaci&#243;n como: identificaci&#243;n del ganadero, c&#243;digo de explotaci&#243;n, fecha y hora de la recogida de la leche, cantidad de leche entregada, y comprador y cisterna que la recoge, as&#237; como informaci&#243;n sobre si se ha efectuado o no toma de muestras. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Aunque no sea ese el fin de este recibo, el documento va a tener valor de prueba de cara a acreditar las ventas de leche, sustituyendo a la famosa cuadr&#237;cula que se colgaba detr&#225;s de la puerta del establo y en la que se apuntaban los litros, sin que tan siquiera muchas veces figurase la raz&#243;n social de la industria. Ahora este recibo har&#225; las veces de albar&#225;n de entrega, aunque seguir&#225; sin figurar el precio del producto que se llevan, un producto al que le ponen precio de forma unilateral a mes vencido.<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Real Decreto 217\/2004 de 6 de febrero, y la normativa para su desarrollo que prepara la comunidad aut&#243;noma de Castilla y Le&#243;n, contempla una serie de registros y obligaciones de los ganaderos y otros agentes que intervienen en la comercializaci&#243;n de la leche.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LA INDUSTRIA EMITIRA RECIBO POR CADA ENTREGA DE LECHE - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"El Real Decreto 217\/2004 de 6 de febrero, y la normativa para su desarrollo que prepara la comunidad aut&#243;noma de Castilla y Le&#243;n, contempla una serie de registros y obligaciones de los ganaderos y otros agentes que intervienen en la comercializaci&#243;n de la leche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA INDUSTRIA EMITIRA RECIBO POR CADA ENTREGA DE LECHE - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El Real Decreto 217\/2004 de 6 de febrero, y la normativa para su desarrollo que prepara la comunidad aut&#243;noma de Castilla y Le&#243;n, contempla una serie de registros y obligaciones de los ganaderos y otros agentes que intervienen en la comercializaci&#243;n de la leche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2004-03-03T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T15:54:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche\",\"name\":\"LA INDUSTRIA EMITIRA RECIBO POR CADA ENTREGA DE LECHE - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2004-03-03T23:00:00+00:00\",\"dateModified\":\"2017-11-14T15:54:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"El Real Decreto 217\/2004 de 6 de febrero, y la normativa para su desarrollo que prepara la comunidad aut&#243;noma de Castilla y Le&#243;n, contempla una serie de registros y obligaciones de los ganaderos y otros agentes que intervienen en la comercializaci&#243;n de la leche.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA INDUSTRIA EMITIRA RECIBO POR CADA ENTREGA DE LECHE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA INDUSTRIA EMITIRA RECIBO POR CADA ENTREGA DE LECHE - ASAJA Le\u00f3n","description":"El Real Decreto 217\/2004 de 6 de febrero, y la normativa para su desarrollo que prepara la comunidad aut&#243;noma de Castilla y Le&#243;n, contempla una serie de registros y obligaciones de los ganaderos y otros agentes que intervienen en la comercializaci&#243;n de la leche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche","og_locale":"es_ES","og_type":"article","og_title":"LA INDUSTRIA EMITIRA RECIBO POR CADA ENTREGA DE LECHE - ASAJA Le\u00f3n","og_description":"El Real Decreto 217\/2004 de 6 de febrero, y la normativa para su desarrollo que prepara la comunidad aut&#243;noma de Castilla y Le&#243;n, contempla una serie de registros y obligaciones de los ganaderos y otros agentes que intervienen en la comercializaci&#243;n de la leche.","og_url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2004-03-03T23:00:00+00:00","article_modified_time":"2017-11-14T15:54:17+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche","url":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche","name":"LA INDUSTRIA EMITIRA RECIBO POR CADA ENTREGA DE LECHE - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2004-03-03T23:00:00+00:00","dateModified":"2017-11-14T15:54:17+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"El Real Decreto 217\/2004 de 6 de febrero, y la normativa para su desarrollo que prepara la comunidad aut&#243;noma de Castilla y Le&#243;n, contempla una serie de registros y obligaciones de los ganaderos y otros agentes que intervienen en la comercializaci&#243;n de la leche.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/servicios-socio\/la-industria-emitira-recibo-por-cada-entrega-de-leche#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"LA INDUSTRIA EMITIRA RECIBO POR CADA ENTREGA DE LECHE"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/3098"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=3098"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/3098\/revisions"}],"predecessor-version":[{"id":4298,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/3098\/revisions\/4298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=3098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=3098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=3098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}