{"id":319,"date":"2016-02-08T00:00:00","date_gmt":"2016-02-07T23:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2016\/02\/08\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015\/"},"modified":"2017-11-14T18:27:42","modified_gmt":"2017-11-14T17:27:42","slug":"la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015","title":{"rendered":"LA COMPRA DE TRACTORES NUEVOS CAY&#211; CASI UN 25% EN LA PROVINCIA DE LE&#211;N EN 2015"},"content":{"rendered":"<h2>Los datos proporcionados por el Magrama del Registro Oficial de Maquinaria Agr&#237;cola (ROMA) cifran en 159 el n&#250;mero de tractores comprados nuevos a lo largo de 2015 en la provincia de Le&#243;n, lo que representa una ca&#237;da del 24,6% respecto a los 211 del a&#241;o 2014<\/h2>\n<p align=\"center\">\n<span style=\"color:#006400;\"><strong>LA COMPRA DE TRACTORES NUEVOS CAY&#211; CASI UN 25% EN LA PROVINCIA DE LE&#211;N EN 2015<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\nLos datos proporcionados por el Magrama del Registro Oficial de Maquinaria Agr&#237;cola (ROMA) cifran en 159 el n&#250;mero de tractores comprados nuevos a lo largo de 2015 en la provincia de Le&#243;n, lo que representa una ca&#237;da del 24,6% respecto a los 211 del a&#241;o 2014. En los cinco a&#241;os anteriores, la media de tractores nuevos matricularos en la provincia de Le&#243;n fue de 205 tractores por a&#241;o. Estos malos n&#250;meros en la matriculaci&#243;n de tractores se han producido en el conjunto de Castilla y Le&#243;n, aunque con descenso m&#225;s moderado, el 5,75% (de 1372 a 1.293), mientras que en el conjunto de Espa&#241;a se creci&#243; el 5,8% al pasar de los 10.004 tractores matriculados en 2014 a los 10.587 de 2015.<\/p>\n<p style=\"text-align: justify;\">\nASAJA de Le&#243;n hab&#237;a hecho ya un avance de esta situaci&#243;n en el mes de diciembre. La ca&#237;da de la rentabilidad del sector vacuno de leche, vendiendo a p&#233;rdidas la mayor parte de los meses del a&#241;o, y las bajas cotizaciones de sectores cuantitativamente importantes como los cereales y el ma&#237;z, son dos de las razones de estas menores ventas. Pero adem&#225;s, el sector agrario ha priorizado sus inversiones, obligado por las circunstancias, en la modernizaci&#243;n de los regad&#237;os y en la compra de tierras. La modernizaci&#243;n de los regad&#237;os ha venido obligada por la ejecuci&#243;n de la obra p&#250;blica y consecuencia de ello la implantaci&#243;n del sistema de riego a la demanda, y la compra de tierras motivada por un mayor movimiento en este mercado tan r&#237;gido cuya tendencia ha cambiado en las fechas m&#225;s recientes donde se detecta una mayor oferta vendedora. En definitiva, el agricultor ha tenido que posponer la reposici&#243;n del tractor, maquinaria agr&#237;cola por excelencia con unos precios medios de mercado en torno a los 100.000 euros, para dar prioridad a otras inversiones m&#225;s acuciantes, administrando una capacidad de endeudamiento que la marca la rentabilidad, el volumen de negocio, y la disponibilidad de cr&#233;dito por parte de bancos y empresas financieras.<\/p>\n<p>\nLe&#243;n, 8 de febrero de 2016<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los datos proporcionados por el Magrama del Registro Oficial de Maquinaria Agr&#237;cola (ROMA) cifran en 159 el n&#250;mero de tractores comprados nuevos a lo largo de 2015 en la provincia de Le&#243;n, lo que representa una ca&#237;da del 24,6% respecto a los 211 del a&#241;o 2014<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LA COMPRA DE TRACTORES NUEVOS CAY&#211; CASI UN 25% EN LA PROVINCIA DE LE&#211;N EN 2015 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Los datos proporcionados por el Magrama del Registro Oficial de Maquinaria Agr&#237;cola (ROMA) cifran en 159 el n&#250;mero de tractores comprados nuevos a lo largo de 2015 en la provincia de Le&#243;n, lo que representa una ca&#237;da del 24,6% respecto a los 211 del a&#241;o 2014\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA COMPRA DE TRACTORES NUEVOS CAY&#211; CASI UN 25% EN LA PROVINCIA DE LE&#211;N EN 2015 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Los datos proporcionados por el Magrama del Registro Oficial de Maquinaria Agr&#237;cola (ROMA) cifran en 159 el n&#250;mero de tractores comprados nuevos a lo largo de 2015 en la provincia de Le&#243;n, lo que representa una ca&#237;da del 24,6% respecto a los 211 del a&#241;o 2014\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-07T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T17:27:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015\",\"name\":\"LA COMPRA DE TRACTORES NUEVOS CAY&#211; CASI UN 25% EN LA PROVINCIA DE LE&#211;N EN 2015 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2016-02-07T23:00:00+00:00\",\"dateModified\":\"2017-11-14T17:27:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Los datos proporcionados por el Magrama del Registro Oficial de Maquinaria Agr&#237;cola (ROMA) cifran en 159 el n&#250;mero de tractores comprados nuevos a lo largo de 2015 en la provincia de Le&#243;n, lo que representa una ca&#237;da del 24,6% respecto a los 211 del a&#241;o 2014\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA COMPRA DE TRACTORES NUEVOS CAY&#211; CASI UN 25% EN LA PROVINCIA DE LE&#211;N EN 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA COMPRA DE TRACTORES NUEVOS CAY&#211; CASI UN 25% EN LA PROVINCIA DE LE&#211;N EN 2015 - ASAJA Le\u00f3n","description":"Los datos proporcionados por el Magrama del Registro Oficial de Maquinaria Agr&#237;cola (ROMA) cifran en 159 el n&#250;mero de tractores comprados nuevos a lo largo de 2015 en la provincia de Le&#243;n, lo que representa una ca&#237;da del 24,6% respecto a los 211 del a&#241;o 2014","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015","og_locale":"es_ES","og_type":"article","og_title":"LA COMPRA DE TRACTORES NUEVOS CAY&#211; CASI UN 25% EN LA PROVINCIA DE LE&#211;N EN 2015 - ASAJA Le\u00f3n","og_description":"Los datos proporcionados por el Magrama del Registro Oficial de Maquinaria Agr&#237;cola (ROMA) cifran en 159 el n&#250;mero de tractores comprados nuevos a lo largo de 2015 en la provincia de Le&#243;n, lo que representa una ca&#237;da del 24,6% respecto a los 211 del a&#241;o 2014","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2016-02-07T23:00:00+00:00","article_modified_time":"2017-11-14T17:27:42+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015","name":"LA COMPRA DE TRACTORES NUEVOS CAY&#211; CASI UN 25% EN LA PROVINCIA DE LE&#211;N EN 2015 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2016-02-07T23:00:00+00:00","dateModified":"2017-11-14T17:27:42+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Los datos proporcionados por el Magrama del Registro Oficial de Maquinaria Agr&#237;cola (ROMA) cifran en 159 el n&#250;mero de tractores comprados nuevos a lo largo de 2015 en la provincia de Le&#243;n, lo que representa una ca&#237;da del 24,6% respecto a los 211 del a&#241;o 2014","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-compra-de-tractores-nuevos-cay-casi-un-25-en-la-provincia-de-len-en-2015#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"LA COMPRA DE TRACTORES NUEVOS CAY&#211; CASI UN 25% EN LA PROVINCIA DE LE&#211;N EN 2015"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/319"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=319"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/319\/revisions"}],"predecessor-version":[{"id":3884,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/319\/revisions\/3884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}