{"id":357,"date":"2015-10-15T00:00:00","date_gmt":"2015-10-14T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2015\/10\/15\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario\/"},"modified":"2017-11-14T18:28:49","modified_gmt":"2017-11-14T17:28:49","slug":"asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario","title":{"rendered":"ASAJA: EL DESPLOME DEL PRESUPUESTO AGRARIO AUGURA UN 2016 MUY COMPLICADO PARA LAS INVERSIONES EN EL SECTOR AGRARIO"},"content":{"rendered":"<h2>La OPA critica que la Junta quiera &#8220;rizar el rizo&#8221; defendiendo con argumentos peregrinos que sube la partida, cuando cae en una cuarta parte<\/h2>\n<div>\n<p style=\"text-align: center;\">\n<span style=\"color:#006400;\"><strong>ASAJA: EL DESPLOME DEL PRESUPUESTO AGRARIO AUGURA UN 2016 MUY COMPLICADO PARA LAS INVERSIONES EN EL SECTOR AGRARIO<\/strong><\/span><\/p>\n<p style=\"text-align: center;\">\n<span style=\"color:#0000cd;\"><strong>La OPA<\/strong><strong> critica que la Junta quiera &#8220;rizar el rizo&#8221; defendiendo con argumentos peregrinos que sube la partida, cuando cae en una cuarta parte<\/strong><\/span><\/p>\n<\/div>\n<p style=\"text-align: justify;\">\nASAJA ha criticado el desplome de la partida destinada a agricultura y ganader&#237;a contenida en el proyecto de presupuestos para 2016 presentado ayer por el presidente de la Junta de Castilla y Le&#243;n, Juan Vicente Herrera, que disminuye cerca del 25 por ciento, una reducci&#243;n brutal y de la que dif&#237;cilmente se puede encontrar un precedente en el departamento de Agricultura.<\/p>\n<p style=\"text-align: justify;\">\nPara la Junta Directiva de ASAJA Castilla y Le&#243;n, reunida hoy en Valladolid, que los responsables pol&#237;ticos atribuyan todo a &#8220;un ajuste contable&#8221; no servir&#225; para maquillar el hecho real de la p&#233;rdida progresiva &#8211;hasta casi la invisibilidad&#8211; del peso que el campo tiene en las inversiones reales que impulsa la administraci&#243;n regional. Desde 2009, el a&#241;o en el que m&#225;s recursos se destinaron al sector, el departamento fue recortando sus aportaciones, y esta tendencia no se ha corregido pese a la mejora de los indicadores econ&#243;micos del pa&#237;s. Hay que recordar que del compromiso de la Junta depende el &#233;xito en la aplicaci&#243;n de pol&#237;ticas tan vitales para el sector como las contenidas en el Programa de Desarrollo Rural (incorporaci&#243;n, modernizaci&#243;n de explotaciones, agroambientales etc.), as&#237; como otras muchas encaminadas a propiciar el crecimiento y sostenibilidad de la actividad agroganadera, como las l&#237;neas de apoyo al seguro agrario, esenciales para el sector, as&#237; como proyectos de saneamiento, regad&#237;os, infraestructuras, investigaci&#243;n, etc.<\/p>\n<p style=\"text-align: justify;\">\nCon estas cuentas sobre la mesa, ASAJA considera &#8220;pr&#225;cticamente imposible&#8221; que la nueva consejera de Agricultura, Milagros Marcos, pueda impulsar un proyecto serio de modernizaci&#243;n del campo, que cumpla con los compromisos de financiaci&#243;n compartida del Programa de Desarrollo Rural, y menos a&#250;n que pueda afrontar situaciones de crisis por los bajos precios o por las malas cosechas, crisis que en un sector inestable como es el agrario y ganadero siempre pueden surgir y para las que la administraci&#243;n tiene la obligaci&#243;n de contar con recursos preparados. Por &#250;ltimo, ASAJA lamenta que la Consejer&#237;a &#8220;claudique ante su obligaci&#243;n de promover pol&#237;ticas activas y se refugie en el c&#243;modo papel de gestionar la PAC y poco m&#225;s&#8221;.<\/p>\n<p style=\"text-align: justify;\">\n<img decoding=\"async\" alt=\"\" src=\"\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/EVOLUCION_PRESUPUESTO_AGRICULTURA.jpg\" style=\"width: 417px; height: 267px;\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La OPA critica que la Junta quiera &#8220;rizar el rizo&#8221; defendiendo con argumentos peregrinos que sube la partida, cuando cae en una cuarta parte<\/p>\n","protected":false},"author":3,"featured_media":6283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA: EL DESPLOME DEL PRESUPUESTO AGRARIO AUGURA UN 2016 MUY COMPLICADO PARA LAS INVERSIONES EN EL SECTOR AGRARIO - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La OPA critica que la Junta quiera &#8220;rizar el rizo&#8221; defendiendo con argumentos peregrinos que sube la partida, cuando cae en una cuarta parte\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA: EL DESPLOME DEL PRESUPUESTO AGRARIO AUGURA UN 2016 MUY COMPLICADO PARA LAS INVERSIONES EN EL SECTOR AGRARIO - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La OPA critica que la Junta quiera &#8220;rizar el rizo&#8221; defendiendo con argumentos peregrinos que sube la partida, cuando cae en una cuarta parte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-14T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T17:28:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/EVOLUCION_PRESUPUESTO_AGRICULTURA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"787\" \/>\n\t<meta property=\"og:image:height\" content=\"504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario\",\"name\":\"ASAJA: EL DESPLOME DEL PRESUPUESTO AGRARIO AUGURA UN 2016 MUY COMPLICADO PARA LAS INVERSIONES EN EL SECTOR AGRARIO - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/EVOLUCION_PRESUPUESTO_AGRICULTURA.jpg\",\"datePublished\":\"2015-10-14T22:00:00+00:00\",\"dateModified\":\"2017-11-14T17:28:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"La OPA critica que la Junta quiera &#8220;rizar el rizo&#8221; defendiendo con argumentos peregrinos que sube la partida, cuando cae en una cuarta parte\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/EVOLUCION_PRESUPUESTO_AGRICULTURA.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/EVOLUCION_PRESUPUESTO_AGRICULTURA.jpg\",\"width\":787,\"height\":504},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA: EL DESPLOME DEL PRESUPUESTO AGRARIO AUGURA UN 2016 MUY COMPLICADO PARA LAS INVERSIONES EN EL SECTOR AGRARIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA: EL DESPLOME DEL PRESUPUESTO AGRARIO AUGURA UN 2016 MUY COMPLICADO PARA LAS INVERSIONES EN EL SECTOR AGRARIO - ASAJA Le\u00f3n","description":"La OPA critica que la Junta quiera &#8220;rizar el rizo&#8221; defendiendo con argumentos peregrinos que sube la partida, cuando cae en una cuarta parte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario","og_locale":"es_ES","og_type":"article","og_title":"ASAJA: EL DESPLOME DEL PRESUPUESTO AGRARIO AUGURA UN 2016 MUY COMPLICADO PARA LAS INVERSIONES EN EL SECTOR AGRARIO - ASAJA Le\u00f3n","og_description":"La OPA critica que la Junta quiera &#8220;rizar el rizo&#8221; defendiendo con argumentos peregrinos que sube la partida, cuando cae en una cuarta parte","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2015-10-14T22:00:00+00:00","article_modified_time":"2017-11-14T17:28:49+00:00","og_image":[{"width":787,"height":504,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/EVOLUCION_PRESUPUESTO_AGRICULTURA.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario","name":"ASAJA: EL DESPLOME DEL PRESUPUESTO AGRARIO AUGURA UN 2016 MUY COMPLICADO PARA LAS INVERSIONES EN EL SECTOR AGRARIO - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/EVOLUCION_PRESUPUESTO_AGRICULTURA.jpg","datePublished":"2015-10-14T22:00:00+00:00","dateModified":"2017-11-14T17:28:49+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"La OPA critica que la Junta quiera &#8220;rizar el rizo&#8221; defendiendo con argumentos peregrinos que sube la partida, cuando cae en una cuarta parte","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/EVOLUCION_PRESUPUESTO_AGRICULTURA.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/EVOLUCION_PRESUPUESTO_AGRICULTURA.jpg","width":787,"height":504},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-el-desplome-del-presupuesto-agrario-augura-un-2016-muy-complicado-para-las-inversiones-en-el-sector-agrario#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ASAJA: EL DESPLOME DEL PRESUPUESTO AGRARIO AUGURA UN 2016 MUY COMPLICADO PARA LAS INVERSIONES EN EL SECTOR AGRARIO"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/357"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=357"}],"version-history":[{"count":3,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/357\/revisions"}],"predecessor-version":[{"id":4372,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/357\/revisions\/4372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/6283"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}