{"id":489,"date":"2015-01-09T00:00:00","date_gmt":"2015-01-08T23:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2015\/01\/09\/las-seis-noticias-agrarias-de-la-semana-09012015\/"},"modified":"2017-11-14T18:37:44","modified_gmt":"2017-11-14T17:37:44","slug":"las-seis-noticias-agrarias-de-la-semana-09012015","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015","title":{"rendered":"LAS SEIS NOTICIAS AGRARIAS DE LA SEMANA &#8211; 09\/01\/2015"},"content":{"rendered":"<h2>Carb&#243;n, siembras de cereal, Katia Abreu, demarcaci&#243;n 5, comisi&#243;n mixta de zona y Confederaci&#243;n Hidrogr&#225;fica del Duero<\/h2>\n<p style=\"text-align: center;\">\n<span style=\"color:#006400;\"><strong>LAS SEIS NOTICIAS AGRARIAS DE LA SEMANA 09\/01\/2015<\/strong><\/span><\/p>\n<p style=\"margin-left: 36pt; text-align: justify;\">\n&#183;&#160;&#160;&#160;&#160;&#160;&#160;&#160; En el tradicional acto reivindicativo que celebra ASAJA de Castilla y Le&#243;n cada a&#241;o, coincidiendo con la festividad de los Reyes Magos, este a&#241;o el destinatario del <strong>carb&#243;n<\/strong> fue el consejero de Econom&#237;a Tom&#225;s Villanueva. ASAJA le hace responsable de no escuchar al sector agrario e imponer trabas en las inspecciones de ITV a los tractores comprados en los a&#241;os 80. Con las nuevas normas, estos tractores de hace 30 a&#241;os que hasta ahora circulaban con normalidad, no pasar&#225;n la ITV sin un gasto econ&#243;mico a&#241;adido que tendr&#225;n que soportar los usuarios.<\/p>\n<p style=\"margin-left: 36pt; text-align: justify;\">\n&#183;&#160;&#160;&#160;&#160;&#160;&#160;&#160; La exigencia de tener en la explotaci&#243;n dos o m&#225;s cultivos a partir de un n&#250;mero determinado de hect&#225;reas, que contempla la nueva PAC en vigor ya para esta campa&#241;a, est&#225; obligando a muchos agricultores de la provincia de Le&#243;n a hacer <strong>siembras de cereal<\/strong>, por lo general de trigo, que se han estado prolongando hasta estos d&#237;as. Con m&#225;s de un mes de retraso sobre las fechas habituales, los agricultores han estado sembrando en fincas que han ido quedando libres del cultivo anterior, por lo general remolacha o ma&#237;z, y cuando las condiciones meteorol&#243;gicas lo han permitido.<\/p>\n<p style=\"margin-left: 36pt; text-align: justify;\">\n&#183;&#160;&#160;&#160;&#160;&#160;&#160;&#160; La Junta de Castilla y Le&#243;n ha anunciado a trav&#233;s del Bolet&#237;n Oficial de la Provincia que van a dar comienzo los trabajos de investigaci&#243;n de la propiedad en la <strong>Demarcaci&#243;n 5<\/strong> de la Concentraci&#243;n Parcelaria del Paramo Bajo. Esta demarcaci&#243;n afecta a las localidades de&#160; Altobar de la Encomienda, Pozuelo del P&#225;ramo, Saludes de Castroponce y San Adri&#225;n del Valle. Por estas raz&#243;n los propietarios y los titulares de cualquier derecho han de presentar las Hojas de Investigaci&#243;n as&#237; como los t&#237;tulos en los que fundamenten sus derechos y grav&#225;menes si es el caso.<\/p>\n<p style=\"margin-left: 36pt; text-align: justify;\">\n&#183;&#160;&#160;&#160;&#160;&#160;&#160;&#160; La presidenta de Brasil, Dilma Rousselff, ha nombrado como ministra de Agricultura a <strong>Katia Abreu<\/strong>, hasta ahora senadora por el partido del Movimiento Democr&#225;tico Brasile&#241;o &#8211; una de las fuerzas pol&#237;ticas que apoy&#243; la reelecci&#243;n de la presidenta-,&#160; y presidenta de la Confederaci&#243;n de Agricultores y Ganaderos de Brasil. El perfil de la nueva ministra de un pa&#237;s agr&#237;colamente tan potente como Brasil es el de una persona de centro derecha comprometida con la agricultura de mercado de las grandes explotaciones brasile&#241;as. Se le apoda como &#8220;la reina de la motosierra&#8221; por su pol&#237;tica a favor de que la agricultura avance sobre la Amazon&#237;a.<\/p>\n<p style=\"margin-left: 36pt; text-align: justify;\">\n&#183;&#160;&#160;&#160;&#160;&#160;&#160;&#160; El pasado jueves se celebr&#243; en la f&#225;brica azucarera de Toro una reuni&#243;n de la <strong>Comisi&#243;n Mixta de Zona<\/strong> del Acuerdo Marco Interprofesional, para abordar el cierre de f&#225;bricas al concluir la actual campa&#241;a 2014\/2015. El sector productor puso de manifiesto las dificultades para el arranque de remolacha en algunas zonas productoras de la provincia de Le&#243;n, donde se han acumulado m&#225;s precipitaciones que en otras. El sector productor pidi&#243; a Azucarera que planifique el cierre como estime oportuno, pero que garantice que no va a quedar remolacha de los agricultores en el campo, llegando, si es el caso, a hacer un cierre temporal en la f&#225;brica de La Ba&#241;eza.<\/p>\n<p style=\"margin-left: 36pt; text-align: justify;\">\n&#183;&#160;&#160;&#160;&#160;&#160;&#160;&#160; El presidente de la <strong>Confederaci&#243;n Hidrogr&#225;fica del Duero<\/strong>, Juan Ignacio Diego Ru&#237;z, recibir&#225; el pr&#243;ximo lunes d&#237;a 12 a la Junta Directiva de ASAJA de Castilla y Le&#243;n encabezada por su presidente Donaciano Dujo. Se trata del primer contacto oficial desde que el nuevo presidente tomara posesi&#243;n del cargo en sustituci&#243;n de Jos&#233; Val&#237;n. ASAJA har&#225; llegar al responsable del organismo de cuenca todas sus propuestas en materia de regad&#237;os, y en particular su postura de cara al nuevo Plan Hidrol&#243;gico para el periodo 2015-2021.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carb&#243;n, siembras de cereal, Katia Abreu, demarcaci&#243;n 5, comisi&#243;n mixta de zona y Confederaci&#243;n Hidrogr&#225;fica del Duero<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LAS SEIS NOTICIAS AGRARIAS DE LA SEMANA - 09\/01\/2015 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Carb&#243;n, siembras de cereal, Katia Abreu, demarcaci&#243;n 5, comisi&#243;n mixta de zona y Confederaci&#243;n Hidrogr&#225;fica del Duero\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LAS SEIS NOTICIAS AGRARIAS DE LA SEMANA - 09\/01\/2015 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Carb&#243;n, siembras de cereal, Katia Abreu, demarcaci&#243;n 5, comisi&#243;n mixta de zona y Confederaci&#243;n Hidrogr&#225;fica del Duero\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-08T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T17:37:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015\",\"name\":\"LAS SEIS NOTICIAS AGRARIAS DE LA SEMANA - 09\/01\/2015 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2015-01-08T23:00:00+00:00\",\"dateModified\":\"2017-11-14T17:37:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Carb&#243;n, siembras de cereal, Katia Abreu, demarcaci&#243;n 5, comisi&#243;n mixta de zona y Confederaci&#243;n Hidrogr&#225;fica del Duero\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LAS SEIS NOTICIAS AGRARIAS DE LA SEMANA &#8211; 09\/01\/2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LAS SEIS NOTICIAS AGRARIAS DE LA SEMANA - 09\/01\/2015 - ASAJA Le\u00f3n","description":"Carb&#243;n, siembras de cereal, Katia Abreu, demarcaci&#243;n 5, comisi&#243;n mixta de zona y Confederaci&#243;n Hidrogr&#225;fica del Duero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015","og_locale":"es_ES","og_type":"article","og_title":"LAS SEIS NOTICIAS AGRARIAS DE LA SEMANA - 09\/01\/2015 - ASAJA Le\u00f3n","og_description":"Carb&#243;n, siembras de cereal, Katia Abreu, demarcaci&#243;n 5, comisi&#243;n mixta de zona y Confederaci&#243;n Hidrogr&#225;fica del Duero","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2015-01-08T23:00:00+00:00","article_modified_time":"2017-11-14T17:37:44+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015","name":"LAS SEIS NOTICIAS AGRARIAS DE LA SEMANA - 09\/01\/2015 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2015-01-08T23:00:00+00:00","dateModified":"2017-11-14T17:37:44+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Carb&#243;n, siembras de cereal, Katia Abreu, demarcaci&#243;n 5, comisi&#243;n mixta de zona y Confederaci&#243;n Hidrogr&#225;fica del Duero","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-09012015#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"LAS SEIS NOTICIAS AGRARIAS DE LA SEMANA &#8211; 09\/01\/2015"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/489"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=489"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/489\/revisions"}],"predecessor-version":[{"id":4054,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/489\/revisions\/4054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}