{"id":542,"date":"2014-09-11T00:00:00","date_gmt":"2014-09-10T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2014\/09\/11\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl\/"},"modified":"2017-11-14T18:51:00","modified_gmt":"2017-11-14T17:51:00","slug":"asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl","title":{"rendered":"ASAJA HAR&#193; UN LLAMAMIENTO AL BOICOT DE LAS CANDIDATURAS DE UGAL-COAG Y UPL"},"content":{"rendered":"<h2>La organizaci&#243;n agraria ASAJA de Le&#243;n, ampliamente mayoritaria en la provincia, pedir&#225; a sus socios y simpatizantes que no integren ni voten candidaturas pol&#237;ticas de la Uni&#243;n del Pueblo Leon&#233;s, si se consuma el pacto electoral, anunciado estos d&#237;as, con la Alianza UGAL-UPA y COAG<\/h2>\n<p style=\"text-align: center\">\n<span style=\"color: #006400\"><strong>ASAJA HAR&#193; UN LLAMAMIENTO AL BOICOT DE LAS CANDIDATURAS DE UGAL-COAG Y UPL<\/strong>&#160;<\/span><\/p>\n<p style=\"text-align: justify\">\nLa organizaci&#243;n agraria ASAJA de Le&#243;n, ampliamente mayoritaria en la provincia, pedir&#225; a sus socios y simpatizantes que no integren ni voten candidaturas pol&#237;ticas de la Uni&#243;n del Pueblo Leon&#233;s, si se consuma el pacto electoral, anunciado estos d&#237;as, con la Alianza UGAL-UPA y COAG. La organizaci&#243;n agraria ASAJA considera que la independencia que viene mostrando respecto a dar libertad de voto y de integraci&#243;n en listas electorales a sus socios, debe de quedar rota respecto a un partido pol&#237;tico que se posiciona a favor de una de las organizaciones agrarias, mediante nexo tan estrecho como un pacto electoral, para concurrir a las elecciones municipales y auton&#243;micas. Por eso, el Comit&#233; Ejecutivo de la organizaci&#243;n, que se reunir&#225; la pr&#243;xima semana, tomar&#225; de nuevo la decisi&#243;n de no recomendar el voto para ninguna opci&#243;n pol&#237;tica, en l&#237;nea con lo decidido en anteriores comicios electorales, con la excepci&#243;n de que pedir&#225; el boicot a las listas y candidaturas del pacto UPL-UGAL.&#160;<\/p>\n<p style=\"text-align: justify\">\nASAJA, como organizaci&#243;n mayoritaria en el campo de la provincia de Le&#243;n, tiene en sus filas afiliados y simpatizantes de todas las fuerzas pol&#237;ticas que concurren a las elecciones en la provincia de Le&#243;n, sobre todo de los partidos mayoritarios PP y PSOE. La organizaci&#243;n agraria, que tiene en la pluralidad pol&#237;tica una de sus fortalezas, siempre ha propiciado la presencia de los agricultores en la vida pol&#237;tica, y anima a sus&#160; socios a presentarse como candidatos en los municipios y entidades locales menores&#160; -juntas vecinales- para defender los intereses agroganaderos y del medio rural. La organizaci&#243;n agraria ha puesto siempre a disposici&#243;n de todas las formaciones pol&#237;ticas sus informes y propuestas en materia de desarrollo agr&#237;cola y ganadero, medio ambiente y desarrollo rural.<\/p>\n<p style=\"text-align: justify\">\n&#160;<\/p>\n<p style=\"text-align: justify\">\nLe&#243;n, 11 de octubre de 2014.&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci&#243;n agraria ASAJA de Le&#243;n, ampliamente mayoritaria en la provincia, pedir&#225; a sus socios y simpatizantes que no integren ni voten candidaturas pol&#237;ticas de la Uni&#243;n del Pueblo Leon&#233;s, si se consuma el pacto electoral, anunciado estos d&#237;as, con la Alianza UGAL-UPA y COAG<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA HAR&#193; UN LLAMAMIENTO AL BOICOT DE LAS CANDIDATURAS DE UGAL-COAG Y UPL - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La organizaci&#243;n agraria ASAJA de Le&#243;n, ampliamente mayoritaria en la provincia, pedir&#225; a sus socios y simpatizantes que no integren ni voten candidaturas pol&#237;ticas de la Uni&#243;n del Pueblo Leon&#233;s, si se consuma el pacto electoral, anunciado estos d&#237;as, con la Alianza UGAL-UPA y COAG\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA HAR&#193; UN LLAMAMIENTO AL BOICOT DE LAS CANDIDATURAS DE UGAL-COAG Y UPL - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La organizaci&#243;n agraria ASAJA de Le&#243;n, ampliamente mayoritaria en la provincia, pedir&#225; a sus socios y simpatizantes que no integren ni voten candidaturas pol&#237;ticas de la Uni&#243;n del Pueblo Leon&#233;s, si se consuma el pacto electoral, anunciado estos d&#237;as, con la Alianza UGAL-UPA y COAG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-10T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T17:51:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl\",\"name\":\"ASAJA HAR&#193; UN LLAMAMIENTO AL BOICOT DE LAS CANDIDATURAS DE UGAL-COAG Y UPL - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2014-09-10T22:00:00+00:00\",\"dateModified\":\"2017-11-14T17:51:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"La organizaci&#243;n agraria ASAJA de Le&#243;n, ampliamente mayoritaria en la provincia, pedir&#225; a sus socios y simpatizantes que no integren ni voten candidaturas pol&#237;ticas de la Uni&#243;n del Pueblo Leon&#233;s, si se consuma el pacto electoral, anunciado estos d&#237;as, con la Alianza UGAL-UPA y COAG\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA HAR&#193; UN LLAMAMIENTO AL BOICOT DE LAS CANDIDATURAS DE UGAL-COAG Y UPL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA HAR&#193; UN LLAMAMIENTO AL BOICOT DE LAS CANDIDATURAS DE UGAL-COAG Y UPL - ASAJA Le\u00f3n","description":"La organizaci&#243;n agraria ASAJA de Le&#243;n, ampliamente mayoritaria en la provincia, pedir&#225; a sus socios y simpatizantes que no integren ni voten candidaturas pol&#237;ticas de la Uni&#243;n del Pueblo Leon&#233;s, si se consuma el pacto electoral, anunciado estos d&#237;as, con la Alianza UGAL-UPA y COAG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl","og_locale":"es_ES","og_type":"article","og_title":"ASAJA HAR&#193; UN LLAMAMIENTO AL BOICOT DE LAS CANDIDATURAS DE UGAL-COAG Y UPL - ASAJA Le\u00f3n","og_description":"La organizaci&#243;n agraria ASAJA de Le&#243;n, ampliamente mayoritaria en la provincia, pedir&#225; a sus socios y simpatizantes que no integren ni voten candidaturas pol&#237;ticas de la Uni&#243;n del Pueblo Leon&#233;s, si se consuma el pacto electoral, anunciado estos d&#237;as, con la Alianza UGAL-UPA y COAG","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2014-09-10T22:00:00+00:00","article_modified_time":"2017-11-14T17:51:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl","name":"ASAJA HAR&#193; UN LLAMAMIENTO AL BOICOT DE LAS CANDIDATURAS DE UGAL-COAG Y UPL - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2014-09-10T22:00:00+00:00","dateModified":"2017-11-14T17:51:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"La organizaci&#243;n agraria ASAJA de Le&#243;n, ampliamente mayoritaria en la provincia, pedir&#225; a sus socios y simpatizantes que no integren ni voten candidaturas pol&#237;ticas de la Uni&#243;n del Pueblo Leon&#233;s, si se consuma el pacto electoral, anunciado estos d&#237;as, con la Alianza UGAL-UPA y COAG","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-har-un-llamamiento-al-boicot-de-las-candidaturas-de-ugal-coag-y-upl#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ASAJA HAR&#193; UN LLAMAMIENTO AL BOICOT DE LAS CANDIDATURAS DE UGAL-COAG Y UPL"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/542"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=542"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/542\/revisions"}],"predecessor-version":[{"id":4107,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/542\/revisions\/4107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}