{"id":625,"date":"2016-11-18T00:00:00","date_gmt":"2016-11-17T23:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2016\/11\/18\/tiempo-de-cosecha\/"},"modified":"2017-11-15T09:58:55","modified_gmt":"2017-11-15T08:58:55","slug":"tiempo-de-cosecha","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha","title":{"rendered":"Tiempo de cosecha"},"content":{"rendered":"<h2>Si todav&#237;a quedan leoneses que piensan que la cosecha se hace en los meses de julio y agosto, es que est&#225;n reviviendo la agricultura que se hac&#237;a en otros tiempos.<\/h2>\n<p style=\"text-align: center;\">\n<span style=\"color:#006400;\"><strong>Tiempo de cosecha<\/strong><\/span><\/p>\n<div>\n<p style=\"text-align: justify; margin-left: 40px;\">\nSi todav&#237;a quedan leoneses que piensan que la cosecha se hace en los meses de julio y agosto, es que est&#225;n reviviendo la agricultura que se hac&#237;a en otros tiempos. Y siendo verdad que en esos meses seguimos cosechando nuestros campos de cereal, y as&#237; seguir&#225; siendo, no es menos cierto que en las &#250;ltimas d&#233;cadas se ha producido un cambio de cultivos que nos lleva la mayor parte de la recolecci&#243;n a los meses de finales de oto&#241;o e invierno. Por eso podemos decir que estos d&#237;as estamos comenzando la cosecha, porque estamos trabajando en la recolecci&#243;n del ma&#237;z y en la de la remolacha, dos cultivos que en a&#241;os normales se acercan a una ocupaci&#243;n de ochenta mil hect&#225;reas, y que generan un valor en el sector primario de ciento setenta millones de euros. El fruto del trabajo de todo un a&#241;o, en el campo de nuestra provincia, se recoge mayoritariamente en invierno, unos meses que habitualmente eran de menor actividad en las labores agr&#237;colas. Estos trabajos est&#225;n mecanizados, se hacen con maquinaria capaz de desarrollar altos rendimientos, y en la mayor&#237;a de los casos se encargan a empresas de servicios, as&#237; que por lo general no representa un excesivo trabajo y ocupaci&#243;n para nuestros profesionales del campo. El problema agron&#243;mico surge cuando el tiempo se tuerce y no se pueden hacer las labores, algo habitual con los crudos inviernos leoneses, y el problema econ&#243;mico lo tenemos cuando los mercados no remuneran el producto en su justa media, que es tambi&#233;n muy frecuente. Este a&#241;o, por ahora, la climatolog&#237;a no est&#225; entorpeciendo estos arranques de cosecha, los rendimientos son francamente escasos por las dificultades que hubo en el momento de las siembras, y los precios en estos mercados tan globalizados no pagan los elevados costes de producir. Estos cambios que se han producido en nuestra agricultura, de la mano de los regad&#237;os modernizados, son cambios positivos que contribuyen a una modernizaci&#243;n del campo, a una mayor competitividad, y que representan un aliciente para generaciones futuras.<\/p>\n<\/div>\n<p>\nArt&#237;culo de opini&#243;n de Jos&#233; Antonio Turrado publicado en La Nueva Cr&#243;nica del viernes 18 de noviembre de 2016.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si todav&#237;a quedan leoneses que piensan que la cosecha se hace en los meses de julio y agosto, es que est&#225;n reviviendo la agricultura que se hac&#237;a en otros tiempos.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tiempo de cosecha - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Si todav&#237;a quedan leoneses que piensan que la cosecha se hace en los meses de julio y agosto, es que est&#225;n reviviendo la agricultura que se hac&#237;a en otros tiempos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tiempo de cosecha - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Si todav&#237;a quedan leoneses que piensan que la cosecha se hace en los meses de julio y agosto, es que est&#225;n reviviendo la agricultura que se hac&#237;a en otros tiempos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-17T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T08:58:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha\",\"name\":\"Tiempo de cosecha - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2016-11-17T23:00:00+00:00\",\"dateModified\":\"2017-11-15T08:58:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Si todav&#237;a quedan leoneses que piensan que la cosecha se hace en los meses de julio y agosto, es que est&#225;n reviviendo la agricultura que se hac&#237;a en otros tiempos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tiempo de cosecha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tiempo de cosecha - ASAJA Le\u00f3n","description":"Si todav&#237;a quedan leoneses que piensan que la cosecha se hace en los meses de julio y agosto, es que est&#225;n reviviendo la agricultura que se hac&#237;a en otros tiempos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha","og_locale":"es_ES","og_type":"article","og_title":"Tiempo de cosecha - ASAJA Le\u00f3n","og_description":"Si todav&#237;a quedan leoneses que piensan que la cosecha se hace en los meses de julio y agosto, es que est&#225;n reviviendo la agricultura que se hac&#237;a en otros tiempos.","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2016-11-17T23:00:00+00:00","article_modified_time":"2017-11-15T08:58:55+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha","name":"Tiempo de cosecha - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2016-11-17T23:00:00+00:00","dateModified":"2017-11-15T08:58:55+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Si todav&#237;a quedan leoneses que piensan que la cosecha se hace en los meses de julio y agosto, es que est&#225;n reviviendo la agricultura que se hac&#237;a en otros tiempos.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/tiempo-de-cosecha#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Tiempo de cosecha"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/625"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=625"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/625\/revisions"}],"predecessor-version":[{"id":990,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/625\/revisions\/990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}