{"id":6735,"date":"2013-11-15T00:00:00","date_gmt":"2013-11-14T23:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/leon\/sin-categoria\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad"},"modified":"2013-11-15T00:00:00","modified_gmt":"2013-11-14T23:00:00","slug":"el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad","title":{"rendered":"EL 36 POR CIENTO  DE LAS FINCAS DE CULTIVO EN LA PROVINCIA DE LE&#211;N, NO TIENEN T&#205;TULO DE PROPIEDAD"},"content":{"rendered":"<h2>Esta situaci&#243;n hace que no tengan valor para las entidades de cr&#233;dito, al no ser garant&#237;a real por no poderse hipotecar, lo que supone un gran obst&#225;culo para la financiaci&#243;n del campo.<\/h2>\n<div align=\"center\"><b><font color=\"#003300\">EL 36 POR CIENTO&#160; DE LAS FINCAS DE CULTIVO EN LA PROVINCIA DE LE&#211;N, NO TIENEN T&#205;TULO DE PROPIEDAD<\/font><\/b><\/div>\n<div align=\"center\"><b>&#160;<\/b><\/div>\n<div align=\"center\"><u><font color=\"#0000ff\">Esta situaci&#243;n hace que no tengan valor para las entidades de cr&#233;dito, al no ser garant&#237;a real por no poderse hipotecar, lo que supone un gran obst&#225;culo para la financiaci&#243;n del campo.<\/font><\/u><\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">Concentraciones parcelarias en zonas donde no se hab&#237;a ejecutado esta infraestructura, pero sobre todo la declaraci&#243;n de inter&#233;s p&#250;blico de la gran zona de nuevos regad&#237;os de Payuelos, as&#237; como la modernizaci&#243;n de los regad&#237;os del P&#225;ramo, junto a otros regad&#237;os tradicionales, han requerido una reconcentraci&#243;n parcelaria y por consiguiente reasignaci&#243;n de unas parcelas que por ahora no est&#225;n protocolizadas ante Notario y no est&#225;n inscritas en el Registro de la Propiedad. Los&#160; c&#225;lculos de ASAJA apuntan a <b>113.903 hect&#225;reas<\/b> de cultivo -aproximadamente <b>el 36 por ciento de la superficie cultivable de la provincia de Le&#243;n<\/b>&#8211; y se debe a la desidia administrativa de la Junta de Castilla y Le&#243;n que tarda a&#241;os en entregar los nuevos t&#237;tulos de propiedad una vez que hace entrega provisional de las nuevas fincas de reemplazo. En algunas de estas zonas concentradas las nuevas parcelas se entregaron a los propietarios hace m&#225;s de quince a&#241;os.<\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">Esta situaci&#243;n de precariedad en la acreditaci&#243;n de la propiedad est&#225; causando enormes perjuicios a la hora de comprar y vender o heredar la fincas, pero sobre todo causa da&#241;os irreparables a los agricultores que necesitan construir naves agroganaderas, instalar sistemas de riego, o hacer inversiones de cualquier tipo, pues la propiedad r&#250;stica, si no est&#225; inscrita en el Registro, no es una garant&#237;a real. ASAJA ha detectado que, a las dificultades de financiaci&#243;n que tienen los agricultores como otros empresarios y aut&#243;nomos, se suma este hecho de no poder aportar garant&#237;as reales con el principal capital que tienen los agricultores y ganaderos, que son sus tierras, unas tierras que a los ojos de las entidades financieras, al no estar Registradas, no tienen valor alguno.<\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">Esta situaci&#243;n denunciada por ASAJA, que afecta a tantas hect&#225;reas y a tantos agricultores, golpea m&#225;s a las explotaciones m&#225;s productivas y donde m&#225;s actividad inversora se est&#225; produciendo, por ser las zonas de nuevos regad&#237;os y regad&#237;os modernizados. Por si fuera poco, estos agricultores, que necesitan cambiar sus sistemas de riego con fuertes inversiones, no reciben ayuda alguna de la Junta, ya que la partida de &#8220;ayudas a planes de mejora de explotaciones&#8221;, del PDR, est&#225; agotada desde hace m&#225;s de un a&#241;o.<\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">ASAJA hace un <b>en&#233;simo llamamiento a la Junta de Castilla y Le&#243;n<\/b> para que ponga soluci&#243;n a este grave problema, una cuesti&#243;n que no requiere de gasto presupuestario y que &#250;nicamente depende de la voluntad pol&#237;tica por solucionar problemas de los ciudadanos.<\/div>\n<div align=\"justify\"><b>&#160;<\/b><\/div>\n<div align=\"justify\"><b><i>*Concentraciones parcelarias a las que hace referencia esta nota de prensa<\/i><\/b><i>: Alcoba de la Ribera, Besande, Brazuelo, Carracedelo, Culebros, Fojedo- Meizara, La Majua, Magaz de Cepeda, Noceda- Quintana de Fuseros, de la Demarcaci&#243;n 1 a la 10 de Payuelos (hay superficie que pertenece a la provincia de Valladolid), la Demarcaci&#243;n 8 del P&#225;ramo Medio, las Demarcaci&#243;nes 1, 2 y 3 del P&#225;ramo Bajo, la de Valderrueda, Villasabariego, Vega de Infanzones, Valencia de Don Juan- Villafer, Val de San Lorenzo y Riego de la Vega. <\/i><\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">Le&#243;n, 15 de noviembre de 2013.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esta situaci&#243;n hace que no tengan valor para las entidades de cr&#233;dito, al no ser garant&#237;a real por no poderse hipotecar, lo que supone un gran obst&#225;culo para la financiaci&#243;n del campo.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EL 36 POR CIENTO DE LAS FINCAS DE CULTIVO EN LA PROVINCIA DE LE&#211;N, NO TIENEN T&#205;TULO DE PROPIEDAD - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Esta situaci&#243;n hace que no tengan valor para las entidades de cr&#233;dito, al no ser garant&#237;a real por no poderse hipotecar, lo que supone un gran obst&#225;culo para la financiaci&#243;n del campo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EL 36 POR CIENTO DE LAS FINCAS DE CULTIVO EN LA PROVINCIA DE LE&#211;N, NO TIENEN T&#205;TULO DE PROPIEDAD - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Esta situaci&#243;n hace que no tengan valor para las entidades de cr&#233;dito, al no ser garant&#237;a real por no poderse hipotecar, lo que supone un gran obst&#225;culo para la financiaci&#243;n del campo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-14T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad\",\"name\":\"EL 36 POR CIENTO DE LAS FINCAS DE CULTIVO EN LA PROVINCIA DE LE&#211;N, NO TIENEN T&#205;TULO DE PROPIEDAD - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2013-11-14T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Esta situaci&#243;n hace que no tengan valor para las entidades de cr&#233;dito, al no ser garant&#237;a real por no poderse hipotecar, lo que supone un gran obst&#225;culo para la financiaci&#243;n del campo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EL 36 POR CIENTO DE LAS FINCAS DE CULTIVO EN LA PROVINCIA DE LE&#211;N, NO TIENEN T&#205;TULO DE PROPIEDAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EL 36 POR CIENTO DE LAS FINCAS DE CULTIVO EN LA PROVINCIA DE LE&#211;N, NO TIENEN T&#205;TULO DE PROPIEDAD - ASAJA Le\u00f3n","description":"Esta situaci&#243;n hace que no tengan valor para las entidades de cr&#233;dito, al no ser garant&#237;a real por no poderse hipotecar, lo que supone un gran obst&#225;culo para la financiaci&#243;n del campo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad","og_locale":"es_ES","og_type":"article","og_title":"EL 36 POR CIENTO DE LAS FINCAS DE CULTIVO EN LA PROVINCIA DE LE&#211;N, NO TIENEN T&#205;TULO DE PROPIEDAD - ASAJA Le\u00f3n","og_description":"Esta situaci&#243;n hace que no tengan valor para las entidades de cr&#233;dito, al no ser garant&#237;a real por no poderse hipotecar, lo que supone un gran obst&#225;culo para la financiaci&#243;n del campo.","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2013-11-14T23:00:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad","name":"EL 36 POR CIENTO DE LAS FINCAS DE CULTIVO EN LA PROVINCIA DE LE&#211;N, NO TIENEN T&#205;TULO DE PROPIEDAD - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2013-11-14T23:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Esta situaci&#243;n hace que no tengan valor para las entidades de cr&#233;dito, al no ser garant&#237;a real por no poderse hipotecar, lo que supone un gran obst&#225;culo para la financiaci&#243;n del campo.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-36-por-ciento-de-las-fincas-de-cultivo-en-la-provincia-de-len-no-tienen-ttulo-de-propiedad#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"EL 36 POR CIENTO DE LAS FINCAS DE CULTIVO EN LA PROVINCIA DE LE&#211;N, NO TIENEN T&#205;TULO DE PROPIEDAD"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/6735"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=6735"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/6735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=6735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=6735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=6735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}