{"id":6771,"date":"2013-09-26T00:00:00","date_gmt":"2013-09-25T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/leon\/sin-categoria\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario"},"modified":"2013-09-26T00:00:00","modified_gmt":"2013-09-25T22:00:00","slug":"asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario","title":{"rendered":"ASAJA VALORA EL RANGO QUE OTORGA AL CAMPO LA LEY AGRARIA, PERO PIDE QUE SE &#147;PERFILE Y MEJORE&#148; EN EL TR&#193;MITE PARLAMENTARIO"},"content":{"rendered":"<h2>Tras conocerse que el Consejo de Gobierno de la Junta celebrado hoy ha aprobado el proyecto de Ley Agraria de Castilla y Le&#243;n, ASAJA de Castilla y Le&#243;n ha valorado el rango que otorga a la agricultura y la ganader&#237;a la futura Ley, aunque pide que la normativa &#8220;se perfile y mejore en el tr&#225;mite parlamentario&#8221;, para lo que solicita el compromiso y colaboraci&#243;n de todos los partidos pol&#237;ticos representados en las Cortes de la Comunidad Aut&#243;noma.<\/h2>\n<div align=\"center\"><font color=\"#003300\"><b>ASAJA VALORA EL RANGO QUE OTORGA AL CAMPO <\/b><b>LA LEY AGRARIA<\/b><b>, PERO PIDE QUE SE &#8220;PERFILE Y MEJORE&#8221; <\/b><b>EN EL TR&#193;MITE PARLAMENTARIO<\/b>&#160;<\/font><\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">Tras conocerse que el Consejo de Gobierno de la Junta celebrado hoy ha aprobado el proyecto de Ley Agraria de Castilla y Le&#243;n<a name=\"ley_agraria_2\"><\/a>, ASAJA de Castilla y Le&#243;n ha valorado el rango que otorga a la agricultura y la ganader&#237;a la futura Ley, aunque pide que la normativa &#8220;se perfile y mejore en el tr&#225;mite parlamentario&#8221;, para lo que solicita el compromiso y colaboraci&#243;n de todos los partidos pol&#237;ticos representados en las Cortes de la Comunidad Aut&#243;noma.<\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">En opini&#243;n de ASAJA, que ha apoyado desde el primer momento esta iniciativa de la Junta de dotar a Castilla y Le&#243;n &#8211;una comunidad en la que el sector primario es absolutamente clave&#8211; de una Ley espec&#237;fica, &#8220;aun recogiendo numerosos cap&#237;tulos, este proyecto de Ley deber&#237;a ser m&#225;s ambicioso y abrirse a otras &#225;reas relacionadas con el campo pero que no son &#250;nicamente competencia de la Consejer&#237;a de Agricultura y Ganader&#237;a&#8221;. En este sentido, ASAJA cita materias como el medio ambiente, la econom&#237;a, las infraestructuras, o los servicios sanitarios, sociales o educativos, aspectos &#8220;inseparables del sector, porque a diferencia de otros profesionales, el trabajo del agricultor y del ganadero est&#225; unido al territorio y a los pueblos&#8221;.<\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">ASAJA conf&#237;a en que esta dimensi&#243;n sea tenida en cuenta e incorporada al esp&#237;ritu y desarrollo de esta nueva norma en el tr&#225;mite parlamentario, &#8220;cuajando entre todos una Ley generosa que d&#233; un marco de posibilidades y desarrollo, no s&#243;lo para la agricultura y la ganader&#237;a, sino para el medio rural en su conjunto&#8221;.<b><\/b><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tras conocerse que el Consejo de Gobierno de la Junta celebrado hoy ha aprobado el proyecto de Ley Agraria de Castilla y Le&#243;n, ASAJA de Castilla y Le&#243;n ha valorado el rango que otorga a la agricultura y la ganader&#237;a la futura Ley, aunque pide que la normativa &#8220;se perfile y mejore en el tr&#225;mite parlamentario&#8221;, para lo que solicita el compromiso y colaboraci&#243;n de todos los partidos pol&#237;ticos representados en las Cortes de la Comunidad Aut&#243;noma.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA VALORA EL RANGO QUE OTORGA AL CAMPO LA LEY AGRARIA, PERO PIDE QUE SE &#147;PERFILE Y MEJORE&#148; EN EL TR&#193;MITE PARLAMENTARIO - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Tras conocerse que el Consejo de Gobierno de la Junta celebrado hoy ha aprobado el proyecto de Ley Agraria de Castilla y Le&#243;n, ASAJA de Castilla y Le&#243;n ha valorado el rango que otorga a la agricultura y la ganader&#237;a la futura Ley, aunque pide que la normativa &#8220;se perfile y mejore en el tr&#225;mite parlamentario&#8221;, para lo que solicita el compromiso y colaboraci&#243;n de todos los partidos pol&#237;ticos representados en las Cortes de la Comunidad Aut&#243;noma.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA VALORA EL RANGO QUE OTORGA AL CAMPO LA LEY AGRARIA, PERO PIDE QUE SE &#147;PERFILE Y MEJORE&#148; EN EL TR&#193;MITE PARLAMENTARIO - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Tras conocerse que el Consejo de Gobierno de la Junta celebrado hoy ha aprobado el proyecto de Ley Agraria de Castilla y Le&#243;n, ASAJA de Castilla y Le&#243;n ha valorado el rango que otorga a la agricultura y la ganader&#237;a la futura Ley, aunque pide que la normativa &#8220;se perfile y mejore en el tr&#225;mite parlamentario&#8221;, para lo que solicita el compromiso y colaboraci&#243;n de todos los partidos pol&#237;ticos representados en las Cortes de la Comunidad Aut&#243;noma.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-25T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario\",\"name\":\"ASAJA VALORA EL RANGO QUE OTORGA AL CAMPO LA LEY AGRARIA, PERO PIDE QUE SE &#147;PERFILE Y MEJORE&#148; EN EL TR&#193;MITE PARLAMENTARIO - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2013-09-25T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Tras conocerse que el Consejo de Gobierno de la Junta celebrado hoy ha aprobado el proyecto de Ley Agraria de Castilla y Le&#243;n, ASAJA de Castilla y Le&#243;n ha valorado el rango que otorga a la agricultura y la ganader&#237;a la futura Ley, aunque pide que la normativa &#8220;se perfile y mejore en el tr&#225;mite parlamentario&#8221;, para lo que solicita el compromiso y colaboraci&#243;n de todos los partidos pol&#237;ticos representados en las Cortes de la Comunidad Aut&#243;noma.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA VALORA EL RANGO QUE OTORGA AL CAMPO LA LEY AGRARIA, PERO PIDE QUE SE &#147;PERFILE Y MEJORE&#148; EN EL TR&#193;MITE PARLAMENTARIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA VALORA EL RANGO QUE OTORGA AL CAMPO LA LEY AGRARIA, PERO PIDE QUE SE &#147;PERFILE Y MEJORE&#148; EN EL TR&#193;MITE PARLAMENTARIO - ASAJA Le\u00f3n","description":"Tras conocerse que el Consejo de Gobierno de la Junta celebrado hoy ha aprobado el proyecto de Ley Agraria de Castilla y Le&#243;n, ASAJA de Castilla y Le&#243;n ha valorado el rango que otorga a la agricultura y la ganader&#237;a la futura Ley, aunque pide que la normativa &#8220;se perfile y mejore en el tr&#225;mite parlamentario&#8221;, para lo que solicita el compromiso y colaboraci&#243;n de todos los partidos pol&#237;ticos representados en las Cortes de la Comunidad Aut&#243;noma.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario","og_locale":"es_ES","og_type":"article","og_title":"ASAJA VALORA EL RANGO QUE OTORGA AL CAMPO LA LEY AGRARIA, PERO PIDE QUE SE &#147;PERFILE Y MEJORE&#148; EN EL TR&#193;MITE PARLAMENTARIO - ASAJA Le\u00f3n","og_description":"Tras conocerse que el Consejo de Gobierno de la Junta celebrado hoy ha aprobado el proyecto de Ley Agraria de Castilla y Le&#243;n, ASAJA de Castilla y Le&#243;n ha valorado el rango que otorga a la agricultura y la ganader&#237;a la futura Ley, aunque pide que la normativa &#8220;se perfile y mejore en el tr&#225;mite parlamentario&#8221;, para lo que solicita el compromiso y colaboraci&#243;n de todos los partidos pol&#237;ticos representados en las Cortes de la Comunidad Aut&#243;noma.","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2013-09-25T22:00:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario","name":"ASAJA VALORA EL RANGO QUE OTORGA AL CAMPO LA LEY AGRARIA, PERO PIDE QUE SE &#147;PERFILE Y MEJORE&#148; EN EL TR&#193;MITE PARLAMENTARIO - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2013-09-25T22:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Tras conocerse que el Consejo de Gobierno de la Junta celebrado hoy ha aprobado el proyecto de Ley Agraria de Castilla y Le&#243;n, ASAJA de Castilla y Le&#243;n ha valorado el rango que otorga a la agricultura y la ganader&#237;a la futura Ley, aunque pide que la normativa &#8220;se perfile y mejore en el tr&#225;mite parlamentario&#8221;, para lo que solicita el compromiso y colaboraci&#243;n de todos los partidos pol&#237;ticos representados en las Cortes de la Comunidad Aut&#243;noma.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-valora-el-rango-que-otorga-al-campo-la-ley-agraria-pero-pide-que-se-perfile-y-mejore-en-el-trmite-parlamentario#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ASAJA VALORA EL RANGO QUE OTORGA AL CAMPO LA LEY AGRARIA, PERO PIDE QUE SE &#147;PERFILE Y MEJORE&#148; EN EL TR&#193;MITE PARLAMENTARIO"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/6771"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=6771"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/6771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=6771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=6771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=6771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}