{"id":6802,"date":"2013-07-18T00:00:00","date_gmt":"2013-07-17T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/leon\/sin-categoria\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac"},"modified":"2013-07-18T00:00:00","modified_gmt":"2013-07-17T22:00:00","slug":"conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac","title":{"rendered":"CONFERENCIA SOBRE LOS ACUERDOS DE LA REFORMA DE LA PAC"},"content":{"rendered":"<h2>Recientemente se ha aprobado en Bruselas la reforma de la PAC hasta el a&#241;o 2020. En los pr&#243;ximos meses se tomar&#225;n importantes decisiones por parte del ministerio de Agricultura y de la Junta que nos afectan de lleno. Pedro Medina, Director General de la Pol&#237;tica Agr&#237;cola Com&#250;n, dar&#225; un conferencia sobre estas cuestiones.<\/h2>\n<div align=\"center\"><b><font color=\"#006600\" size=\"3\">CONFERENCIA SOBRE LOS ACUERDOS<\/font><\/b><\/div>\n<div align=\"center\"><b><font color=\"#006600\" size=\"3\">DE LA REFORMA DE LA PAC<\/font><\/b><\/div>\n<div>&#160;<\/div>\n<div align=\"justify\"><font size=\"1\">&#160;<\/font><\/div>\n<div align=\"justify\"><font size=\"2\">Recientemente se ha aprobado en Bruselas la reforma de la PAC hasta el a&#241;o 2020. En los pr&#243;ximos meses se tomar&#225;n importantes decisiones por parte del ministerio de Agricultura y de la Junta que nos afectan de lleno. Para informarnos de lo que ha pasado y de lo que puede pasar, hemos invitado a un acto de ASAJA a quien m&#225;s sabe del tema y m&#225;s influir&#225; en la consejera de Agricultura sobre esta materia. El Director General de la Pol&#237;tica Agr&#237;cola Com&#250;n, <u>Pedro Medina Rebollo<\/u>, dar&#225; una conferencia&#160; sobre esta cuesti&#243;n el <b><u>MARTES d&#237;a 23 de julio, a las 8 de la tarde<\/u><\/b>, en el Sal&#243;n del Centro C&#237;vico de <b><u>Santa Mar&#237;a del P&#225;ramo<\/u><\/b> (antiguo Colegio de las Monjas). Nos acompa&#241;ar&#225; tambi&#233;n el presidente regional de ASAJA, Donaciano Dujo. El acto est&#225; abierto a socios y simpatizantes de ASAJA. <\/font><\/div>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pedro_medina.jpg\" width=\"150\" height=\"161\" alt=\"\"\/><\/p>\n<div align=\"center\"><font size=\"1\"><strong><\/strong><\/font><\/div>\n<div align=\"center\"><font size=\"1\"><strong>Pedro Medina Rebollo<\/strong><\/font><\/div>\n<div align=\"justify\"><font size=\"2\"><\/font><\/div>\n<div align=\"justify\"><font size=\"2\"><\/font><\/div>\n<div align=\"justify\"><font size=\"2\"><\/font><\/div>\n<div align=\"justify\"><font size=\"2\"><\/font><\/div>\n<div align=\"justify\"><font size=\"2\">Dentro de este mismo acto, ASAJA y Canal 8 de RTVCYL presentar&#225;n el programa <b><i>&#8220;A pie del campo&#8221;<\/i><\/b>, un espacio semanal de informaci&#243;n agroganadera producido y emitido fruto de la colaboraci&#243;n de ambas entidades y el patrocinio de empresas del sector. El primer programa se emitir&#225; el <u>s&#225;bado 3 de agosto a las 14,30<\/u> horas, en La 8 de Castilla y Le&#243;n Televisi&#243;n (lo que antes era Televisi&#243;n de Le&#243;n). Este acuerdo se ha firmado por un periodo de 4 a&#241;os. ASAJA pretende dar un servicio p&#250;blico de informaci&#243;n al campo con un programa de calidad que ponga en valor el trabajo de los hombres y mujeres de la agricultura y la ganader&#237;a leonesas.<\/font><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Recientemente se ha aprobado en Bruselas la reforma de la PAC hasta el a&#241;o 2020. En los pr&#243;ximos meses se tomar&#225;n importantes decisiones por parte del ministerio de Agricultura y de la Junta que nos afectan de lleno. Pedro Medina, Director General de la Pol&#237;tica Agr&#237;cola Com&#250;n, dar&#225; un conferencia sobre estas cuestiones.<\/p>\n","protected":false},"author":3,"featured_media":6803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CONFERENCIA SOBRE LOS ACUERDOS DE LA REFORMA DE LA PAC - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Recientemente se ha aprobado en Bruselas la reforma de la PAC hasta el a&#241;o 2020. En los pr&#243;ximos meses se tomar&#225;n importantes decisiones por parte del ministerio de Agricultura y de la Junta que nos afectan de lleno. Pedro Medina, Director General de la Pol&#237;tica Agr&#237;cola Com&#250;n, dar&#225; un conferencia sobre estas cuestiones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONFERENCIA SOBRE LOS ACUERDOS DE LA REFORMA DE LA PAC - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Recientemente se ha aprobado en Bruselas la reforma de la PAC hasta el a&#241;o 2020. En los pr&#243;ximos meses se tomar&#225;n importantes decisiones por parte del ministerio de Agricultura y de la Junta que nos afectan de lleno. Pedro Medina, Director General de la Pol&#237;tica Agr&#237;cola Com&#250;n, dar&#225; un conferencia sobre estas cuestiones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-17T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pedro_medina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"309\" \/>\n\t<meta property=\"og:image:height\" content=\"468\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac\",\"name\":\"CONFERENCIA SOBRE LOS ACUERDOS DE LA REFORMA DE LA PAC - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pedro_medina.jpg\",\"datePublished\":\"2013-07-17T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Recientemente se ha aprobado en Bruselas la reforma de la PAC hasta el a&#241;o 2020. En los pr&#243;ximos meses se tomar&#225;n importantes decisiones por parte del ministerio de Agricultura y de la Junta que nos afectan de lleno. Pedro Medina, Director General de la Pol&#237;tica Agr&#237;cola Com&#250;n, dar&#225; un conferencia sobre estas cuestiones.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pedro_medina.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pedro_medina.jpg\",\"width\":309,\"height\":468},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONFERENCIA SOBRE LOS ACUERDOS DE LA REFORMA DE LA PAC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONFERENCIA SOBRE LOS ACUERDOS DE LA REFORMA DE LA PAC - ASAJA Le\u00f3n","description":"Recientemente se ha aprobado en Bruselas la reforma de la PAC hasta el a&#241;o 2020. En los pr&#243;ximos meses se tomar&#225;n importantes decisiones por parte del ministerio de Agricultura y de la Junta que nos afectan de lleno. Pedro Medina, Director General de la Pol&#237;tica Agr&#237;cola Com&#250;n, dar&#225; un conferencia sobre estas cuestiones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac","og_locale":"es_ES","og_type":"article","og_title":"CONFERENCIA SOBRE LOS ACUERDOS DE LA REFORMA DE LA PAC - ASAJA Le\u00f3n","og_description":"Recientemente se ha aprobado en Bruselas la reforma de la PAC hasta el a&#241;o 2020. En los pr&#243;ximos meses se tomar&#225;n importantes decisiones por parte del ministerio de Agricultura y de la Junta que nos afectan de lleno. Pedro Medina, Director General de la Pol&#237;tica Agr&#237;cola Com&#250;n, dar&#225; un conferencia sobre estas cuestiones.","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2013-07-17T22:00:00+00:00","og_image":[{"width":309,"height":468,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pedro_medina.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac","name":"CONFERENCIA SOBRE LOS ACUERDOS DE LA REFORMA DE LA PAC - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pedro_medina.jpg","datePublished":"2013-07-17T22:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Recientemente se ha aprobado en Bruselas la reforma de la PAC hasta el a&#241;o 2020. En los pr&#243;ximos meses se tomar&#225;n importantes decisiones por parte del ministerio de Agricultura y de la Junta que nos afectan de lleno. Pedro Medina, Director General de la Pol&#237;tica Agr&#237;cola Com&#250;n, dar&#225; un conferencia sobre estas cuestiones.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pedro_medina.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/pedro_medina.jpg","width":309,"height":468},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/conferencia-sobre-los-acuerdos-de-la-reforma-de-la-pac#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"CONFERENCIA SOBRE LOS ACUERDOS DE LA REFORMA DE LA PAC"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/6802"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=6802"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/6802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/6803"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=6802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=6802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=6802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}