{"id":6828,"date":"2013-05-24T00:00:00","date_gmt":"2013-05-23T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/leon\/sin-categoria\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac"},"modified":"2013-05-24T00:00:00","modified_gmt":"2013-05-23T22:00:00","slug":"el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac","title":{"rendered":"El PSOE INICIA CON ASAJA SU SONDEO AL SECTOR AGROGANADERO DE CASTILLA Y LE&#211;N ANTE LA FUTURA PAC"},"content":{"rendered":"<h2>La organizaci&#243;n agraria mayoritaria advierte que &#8220;tan importante o m&#225;s&#8221; que lo que se apruebe en Bruselas es c&#243;mo se aplique en el pa&#237;s y en la regi&#243;n<\/h2>\n<div align=\"center\"><font color=\"#003300\"><b>El PSOE INICIA CON ASAJA SU SONDEO AL SECTOR AGROGANADERO DE CASTILLA Y LE&#211;N ANTE <\/b><b>LA FUTURA<\/b><b> PAC<\/b><b><\/b><\/font><\/div>\n<div align=\"center\"><b>&#160;<\/b><\/div>\n<div align=\"center\"><b><font color=\"#0000ff\">La organizaci&#243;n agraria mayoritaria advierte que &#8220;tan importante o m&#225;s&#8221; que lo que se apruebe en Bruselas es c&#243;mo se aplique en el pa&#237;s y en la regi&#243;n<\/font><\/b><\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">El Partido Socialista de Castilla y Le&#243;n ha iniciado con ASAJA, como organizaci&#243;n agraria mayoritaria, una ronda de contactos con el sector agroganadero para &#8220;escuchar y determinar&#8221; su postura ante la futura aplicaci&#243;n en la regi&#243;n de la reforma de la Pol&#237;tica Agr&#237;cola Com&#250;n. La delegaci&#243;n del PSOE CyL ha estado compuesta por Julio Villarubia, secretario general, acompa&#241;ado por la eurodiputada Iratxe Garc&#237;a y la responsable de Agricultura y Desarrollo Rural, Ana S&#225;nchez, mientras que por parte de ASAJA ha asistido el presidente de Castilla y Le&#243;n, Donaciano Dujo, el secretario general, Jos&#233; Antonio Turrado, y el responsable provincial, Lino Rodr&#237;guez.<\/div>\n<div align=\"justify\">El presidente de ASAJA de Castilla y Le&#243;n pidi&#243; al PSOE que &#8220;se emplee a fondo&#8221; para procurar, desde su posici&#243;n de principal partido de la oposici&#243;n, que el proceso de aplicaci&#243;n de la futura PAC se aplique en Espa&#241;a y en Castilla y Le&#243;n atendiendo a los mayores criterios de profesionalidad, &#8220;dando una prioridad absoluta a los que viven e invierten de verdad en el campo&#8221;, y permitiendo el desarrollo de un sector agroganadero competitivo y acorde con el marco de exigencias de calidad, productividad y sostenibilidad que se exige en el siglo XXI.<\/div>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" style=\"WIDTH: 400px; HEIGHT: 289px\" src=\"\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/reunion_PSOE5.jpg\" width=\"400\" height=\"429\" alt=\"\"\/><\/p>\n<div align=\"justify\">Por su parte, Julio Villarubia hizo una cr&#237;tica frontal al Plan Integral Agrario de Castilla y Le&#243;n, periodo 2007-2013, &#8220;por su incumplimiento&#8221; y calific&#243; de &#8220;absoluto fracaso&#8221; la pol&#237;tica agraria de la Junta de Castilla y Le&#243;n.&#160; Adem&#225;s, subray&#243; que las medidas del Gobierno auton&#243;mico &#8220;lejos de evitar la despoblaci&#243;n del medio rural, la han acentuado&#8221;. Respecto a la futura Ley Agraria, y en sinton&#237;a con lo defendido desde ASAJA, el l&#237;der socialista indic&#243; que &#8220;tiene que ser una normativa en de car&#225;cter transversal&#8221;.<\/div>\n<div align=\"justify\">Otros puntos tratados con los responsables del PSOE fueron el momento actual de las producciones, especialmente la situaci&#243;n de la campa&#241;a cerealista, la crisis del sector ganadero y los desajustes en los precios percibidos por los productores y los embolsados por los intermediarios. Tambi&#233;n se habl&#243; sobre el tema, vital para los peque&#241;os municipios de la Comunidad Aut&#243;noma, de la ordenaci&#243;n del territorio, punto en el que ASAJA apel&#243; por que el partido liderado por Villarubia &#8220;no se olvide de presionar, puesto que cuando se habla de sanidad, educaci&#243;n o transporte no se trata s&#243;lo de n&#250;meros, sino de personas, que no pueden quedar desasistidas&#8221;, recalc&#243; Dujo.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci&#243;n agraria mayoritaria advierte que &#8220;tan importante o m&#225;s&#8221; que lo que se apruebe en Bruselas es c&#243;mo se aplique en el pa&#237;s y en la regi&#243;n<\/p>\n","protected":false},"author":3,"featured_media":6829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El PSOE INICIA CON ASAJA SU SONDEO AL SECTOR AGROGANADERO DE CASTILLA Y LE&#211;N ANTE LA FUTURA PAC - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"La organizaci&#243;n agraria mayoritaria advierte que &#8220;tan importante o m&#225;s&#8221; que lo que se apruebe en Bruselas es c&#243;mo se aplique en el pa&#237;s y en la regi&#243;n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSOE INICIA CON ASAJA SU SONDEO AL SECTOR AGROGANADERO DE CASTILLA Y LE&#211;N ANTE LA FUTURA PAC - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La organizaci&#243;n agraria mayoritaria advierte que &#8220;tan importante o m&#225;s&#8221; que lo que se apruebe en Bruselas es c&#243;mo se aplique en el pa&#237;s y en la regi&#243;n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-23T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/reunion_PSOE5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1166\" \/>\n\t<meta property=\"og:image:height\" content=\"875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac\",\"name\":\"El PSOE INICIA CON ASAJA SU SONDEO AL SECTOR AGROGANADERO DE CASTILLA Y LE&#211;N ANTE LA FUTURA PAC - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/reunion_PSOE5.jpg\",\"datePublished\":\"2013-05-23T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"La organizaci&#243;n agraria mayoritaria advierte que &#8220;tan importante o m&#225;s&#8221; que lo que se apruebe en Bruselas es c&#243;mo se aplique en el pa&#237;s y en la regi&#243;n\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/reunion_PSOE5.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/reunion_PSOE5.jpg\",\"width\":1166,\"height\":875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSOE INICIA CON ASAJA SU SONDEO AL SECTOR AGROGANADERO DE CASTILLA Y LE&#211;N ANTE LA FUTURA PAC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSOE INICIA CON ASAJA SU SONDEO AL SECTOR AGROGANADERO DE CASTILLA Y LE&#211;N ANTE LA FUTURA PAC - ASAJA Le\u00f3n","description":"La organizaci&#243;n agraria mayoritaria advierte que &#8220;tan importante o m&#225;s&#8221; que lo que se apruebe en Bruselas es c&#243;mo se aplique en el pa&#237;s y en la regi&#243;n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac","og_locale":"es_ES","og_type":"article","og_title":"El PSOE INICIA CON ASAJA SU SONDEO AL SECTOR AGROGANADERO DE CASTILLA Y LE&#211;N ANTE LA FUTURA PAC - ASAJA Le\u00f3n","og_description":"La organizaci&#243;n agraria mayoritaria advierte que &#8220;tan importante o m&#225;s&#8221; que lo que se apruebe en Bruselas es c&#243;mo se aplique en el pa&#237;s y en la regi&#243;n","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2013-05-23T22:00:00+00:00","og_image":[{"width":1166,"height":875,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/reunion_PSOE5.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac","name":"El PSOE INICIA CON ASAJA SU SONDEO AL SECTOR AGROGANADERO DE CASTILLA Y LE&#211;N ANTE LA FUTURA PAC - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/reunion_PSOE5.jpg","datePublished":"2013-05-23T22:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"La organizaci&#243;n agraria mayoritaria advierte que &#8220;tan importante o m&#225;s&#8221; que lo que se apruebe en Bruselas es c&#243;mo se aplique en el pa&#237;s y en la regi&#243;n","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/reunion_PSOE5.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/reunion_PSOE5.jpg","width":1166,"height":875},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-psoe-inicia-con-asaja-su-sondeo-al-sector-agroganadero-de-castilla-y-len-ante-la-futura-pac#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"El PSOE INICIA CON ASAJA SU SONDEO AL SECTOR AGROGANADERO DE CASTILLA Y LE&#211;N ANTE LA FUTURA PAC"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/6828"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=6828"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/6828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/6829"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=6828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=6828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=6828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}