{"id":6853,"date":"2013-04-17T00:00:00","date_gmt":"2013-04-16T22:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/leon\/sin-categoria\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20"},"modified":"2013-04-17T00:00:00","modified_gmt":"2013-04-16T22:00:00","slug":"el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20","title":{"rendered":"EL COSTE DEL SEGURO DE L&#218;PULO SE INCREMENTA ESTE A&#209;O UN 20%"},"content":{"rendered":"<h2>El ministerio de Agricultura reduce la subvenci&#243;n y la Junta ya la retir&#243; por completo la pasada campa&#241;a<\/h2>\n<div align=\"center\"><b><font color=\"#003300\">EL COSTE DEL SEGURO DE L&#218;PULO SE INCREMENTA ESTE A&#209;O UN 20%<\/font><\/b><\/div>\n<div align=\"center\">&#160;<\/div>\n<div align=\"center\"><u><font color=\"#008080\">El ministerio de Agricultura reduce la subvenci&#243;n y la Junta ya la retir&#243; por completo la pasada campa&#241;a<\/font><\/u><\/div>\n<div align=\"justify\"><u>&#160;<\/u><\/div>\n<div align=\"justify\">Asegurar este a&#241;o una hect&#225;rea de l&#250;pulo es un 20 por ciento m&#225;s caro de&#160; lo que lo era el pasado a&#241;o por estas fechas. El ministerio de Agricultura revis&#243; el pasado mes de junio las subvenciones que otorga a las diferentes l&#237;neas del seguro agr&#237;cola y ganadero, a trav&#233;s de la entidad ENESA, y decidi&#243; reducir los apoyos a la l&#237;nea de seguro del l&#250;pulo, un cultivo eminentemente leon&#233;s&#160; cuya producci&#243;n se concentra en las vegas del&#160; &#211;rbigo y el Tuerto. El seguro abarca el riesgo de siniestro de pedrisco y viento huracanado, fen&#243;menos meteorol&#243;gicos que acompa&#241;an a las tormentas de verano muy comunes en la ribera del r&#237;o &#211;rbigo.<\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">La organizaci&#243;n agraria ASAJA considera que este seguro es imprescindible para los lupuleros, ya que el riesgo que se asumen si no se suscribe es muy alto, por lo tanto ASAJA aconseja suscribir las p&#243;lizas a pesar del sobrecoste. El plazo para suscribir este seguro finaliza el 10 de mayo. No obstante, ASAJA elevar&#225; una queja ante el ministerio de Agricultura para que revise al alza el apoyo a esta l&#237;nea de seguro, y no renuncia a que la Junta de Castilla y Le&#243;n, a trav&#233;s de la consejer&#237;a de Agricultura, vuelva a subvencionar los seguros agr&#237;colas y ganaderos. ASAJA siempre ha defendido los seguros como una de las principales medidas de pol&#237;tica agraria de nuestro pa&#237;s &#8211; implantados como una de las medidas de los Pactos de la Moncloa- y ha alertado de que estamos asistiendo a su desmantelamiento por el alto coste que est&#225; suponiendo para los agricultores y ganaderos debido a la pol&#237;tica de la compa&#241;&#237;a Agroseguro y a la retirada de apoyos del presupuesto p&#250;blico.<\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">La oficina de ASAJA en Carrizo de la Ribera est&#225; ofreciendo a los cultivadores de l&#250;pulo todos los servicios que demanda. En estas fechas el principal trabajo se centra en la tramitaci&#243;n de las ayudas de la PAC, cuyo plazo finaliza el 30 de abril, y la suscripci&#243;n de los seguros agrarios.<\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">Le&#243;n, 17 de abril de 2013.<\/div>\n<div align=\"justify\">&#160;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El ministerio de Agricultura reduce la subvenci&#243;n y la Junta ya la retir&#243; por completo la pasada campa&#241;a<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EL COSTE DEL SEGURO DE L&#218;PULO SE INCREMENTA ESTE A&#209;O UN 20% - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"El ministerio de Agricultura reduce la subvenci&#243;n y la Junta ya la retir&#243; por completo la pasada campa&#241;a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EL COSTE DEL SEGURO DE L&#218;PULO SE INCREMENTA ESTE A&#209;O UN 20% - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El ministerio de Agricultura reduce la subvenci&#243;n y la Junta ya la retir&#243; por completo la pasada campa&#241;a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-16T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20\",\"name\":\"EL COSTE DEL SEGURO DE L&#218;PULO SE INCREMENTA ESTE A&#209;O UN 20% - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2013-04-16T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"El ministerio de Agricultura reduce la subvenci&#243;n y la Junta ya la retir&#243; por completo la pasada campa&#241;a\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EL COSTE DEL SEGURO DE L&#218;PULO SE INCREMENTA ESTE A&#209;O UN 20%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EL COSTE DEL SEGURO DE L&#218;PULO SE INCREMENTA ESTE A&#209;O UN 20% - ASAJA Le\u00f3n","description":"El ministerio de Agricultura reduce la subvenci&#243;n y la Junta ya la retir&#243; por completo la pasada campa&#241;a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20","og_locale":"es_ES","og_type":"article","og_title":"EL COSTE DEL SEGURO DE L&#218;PULO SE INCREMENTA ESTE A&#209;O UN 20% - ASAJA Le\u00f3n","og_description":"El ministerio de Agricultura reduce la subvenci&#243;n y la Junta ya la retir&#243; por completo la pasada campa&#241;a","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2013-04-16T22:00:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20","name":"EL COSTE DEL SEGURO DE L&#218;PULO SE INCREMENTA ESTE A&#209;O UN 20% - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2013-04-16T22:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"El ministerio de Agricultura reduce la subvenci&#243;n y la Junta ya la retir&#243; por completo la pasada campa&#241;a","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/el-coste-del-seguro-de-lpulo-se-incrementa-este-ao-un-20#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"EL COSTE DEL SEGURO DE L&#218;PULO SE INCREMENTA ESTE A&#209;O UN 20%"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/6853"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=6853"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/6853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=6853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=6853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=6853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}