{"id":700,"date":"2015-07-24T00:00:00","date_gmt":"2015-07-23T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2015\/07\/24\/miedo-al-fuego\/"},"modified":"2017-11-15T10:00:02","modified_gmt":"2017-11-15T09:00:02","slug":"miedo-al-fuego","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego","title":{"rendered":"Miedo al fuego"},"content":{"rendered":"<h2>Cada vez son m&#225;s frecuentes los incendios en los montes que amenazan con llegar a los n&#250;cleos de poblaci&#243;n de nuestra provincia<\/h2>\n<p style=\"text-align: center;\">\n<span style=\"color:#006400;\"><strong>Miedo al fuego<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\nCada vez son m&#225;s frecuentes los incendios en los montes que amenazan con llegar a los n&#250;cleos de poblaci&#243;n de nuestra provincia. Este fen&#243;meno antes no ocurr&#237;a, pues el monte no rodeaba el n&#250;cleo urbano, ya que entre las viviendas y el monte, lo que hab&#237;a eran prados y tierras de cultivo. En las &#250;ltimas d&#233;cadas, donde la actividad agraria ha ido a menos en cientos de pueblos de las zonas m&#225;s altas de la provincia, no necesariamente clasificadas como monta&#241;osas, el monte se ha apoderado de los terrenos agr&#237;colas y llega a tocar con las casas de los pocos vecinos que todav&#237;a quedan. Por eso ahora, cada vez que hay un incendio en un monte pr&#243;ximo a un pueblo, los vecinos&#160; sienten el miedo en sus carnes ante la probabilidad de perder, adem&#225;s del monte de toda la vida, la vivienda que tanto sacrificio y desvelos le cost&#243;. Y en muchos casos, esta invasi&#243;n del monte, proviene de la pol&#237;tica conservacionista que impide tocar un &#225;rbol o un arbusto, que tiene prioridad sobre las tierras de cultivo y al parecer tambi&#233;n sobre la seguridad de la poblaci&#243;n. Ante esta situaci&#243;n, las autoridades de Medio Ambiente, y en su caso los ayuntamientos, deben de plantearse establecer un plan de seguridad de los n&#250;cleos urbanos ante el riesgo de incendios forestales. Y este plan, que seguramente ha de contender distintas medidas, ha de comenzar con establecer el l&#237;mite del monte, limpiar parcelas lim&#237;trofes, y fijar cortafuegos en un per&#237;metro determinado para que en el caso de que se produzca un incendio, no peligre la vida de las personas o sus propiedades urbanas.<\/p>\n<div>\n<p style=\"text-align: justify;\">\nEsta cuesti&#243;n forma parte de los problemas de seguridad que asolan nuestro medio rural despoblado y envejecido.&#160; En nuestros pueblos no hay personas ni medios para luchar contra un gran incendio, como tampoco las hay para luchar contra la delincuencia, organizada o no, que estafa, roba o saquea impunemente. Se necesita de un poyo de las administraciones en cuestiones legislativas y medidas concretas, y muchas de ellas han de ser de prevenci&#243;n.<\/p>\n<\/div>\n<p>\nArt&#237;culo de opini&#243;n de Jos&#233; Antonio Turrado publicado en La Nueva Cr&#243;nica del viernes 24 de julio de 2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada vez son m&#225;s frecuentes los incendios en los montes que amenazan con llegar a los n&#250;cleos de poblaci&#243;n de nuestra provincia<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Miedo al fuego - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Cada vez son m&#225;s frecuentes los incendios en los montes que amenazan con llegar a los n&#250;cleos de poblaci&#243;n de nuestra provincia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miedo al fuego - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Cada vez son m&#225;s frecuentes los incendios en los montes que amenazan con llegar a los n&#250;cleos de poblaci&#243;n de nuestra provincia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-23T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T09:00:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego\",\"name\":\"Miedo al fuego - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2015-07-23T22:00:00+00:00\",\"dateModified\":\"2017-11-15T09:00:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Cada vez son m&#225;s frecuentes los incendios en los montes que amenazan con llegar a los n&#250;cleos de poblaci&#243;n de nuestra provincia\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Miedo al fuego\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miedo al fuego - ASAJA Le\u00f3n","description":"Cada vez son m&#225;s frecuentes los incendios en los montes que amenazan con llegar a los n&#250;cleos de poblaci&#243;n de nuestra provincia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego","og_locale":"es_ES","og_type":"article","og_title":"Miedo al fuego - ASAJA Le\u00f3n","og_description":"Cada vez son m&#225;s frecuentes los incendios en los montes que amenazan con llegar a los n&#250;cleos de poblaci&#243;n de nuestra provincia","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2015-07-23T22:00:00+00:00","article_modified_time":"2017-11-15T09:00:02+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego","name":"Miedo al fuego - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2015-07-23T22:00:00+00:00","dateModified":"2017-11-15T09:00:02+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Cada vez son m&#225;s frecuentes los incendios en los montes que amenazan con llegar a los n&#250;cleos de poblaci&#243;n de nuestra provincia","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/miedo-al-fuego#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Miedo al fuego"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/700"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=700"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/700\/revisions"}],"predecessor-version":[{"id":1065,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/700\/revisions\/1065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}