{"id":728,"date":"2015-01-23T00:00:00","date_gmt":"2015-01-22T23:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2015\/01\/23\/los-carburantes-2\/"},"modified":"2017-11-15T10:00:36","modified_gmt":"2017-11-15T09:00:36","slug":"los-carburantes-2","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2","title":{"rendered":"LOS CARBURANTES"},"content":{"rendered":"<h2>No entiendo a algunos economistas que se empe&#241;an en ir contracorriente, quiz&#225;s para hacerse los interesantes, y le encuentran pegas al hecho de que en los &#250;ltimos meses se haya producido una escalada de bajada del precio de los carburantes.<\/h2>\n<p style=\"text-align: center;\">\n<span style=\"color:#006400;\"><strong>LOS CARBURANTES<\/strong><\/span><\/p>\n<div>\n<p style=\"text-align: justify;\">\nNo entiendo a algunos economistas que se empe&#241;an en ir contracorriente, quiz&#225;s para hacerse los interesantes, y le encuentran pegas al hecho de que en los &#250;ltimos meses se haya producido una escalada de bajada del precio de los carburantes. Algunos creen que puede abocar a una deflaci&#243;n, cuesti&#243;n menor comparado con las muchas ventajas que est&#225; acarreando para nuestra econom&#237;a, y en todo caso, pienso yo que no es lo mismo una deflaci&#243;n por precios bajos en materias primas importadas, que por precios bajos consecuencia de la ca&#237;da del consumo interno. En la econom&#237;a real, la bajada de los carburantes supone todo un alivio del que de una u otra forma nos estamos beneficiando toda la sociedad leonesa. Se beneficia un sector del transporte que lleva a&#241;os con poca carga de trabajo y unos precios francamente muy ajustados, inferiores a los de antes del inicio de la crisis. Nos beneficiamos los miles de trabajadores que necesitamos el veh&#237;culo para ir al puesto de trabajo o simplemente para las cuestiones personales y dom&#233;sticas. Y se benefician amplios sectores productivos que consumen este tipo de energ&#237;as, en particular el sector agropecuario que mueve sus m&#225;quinas, sus tractores, con gas&#243;leo. Y en una provincia como la nuestra, con inviernos largos y duros, la bajada que ya se ha producido de al menos treinta c&#233;ntimos en el gas&#243;leo de calefacci&#243;n contribuir&#225; a mejorar los recursos familiares y disponer de mayor capacidad de compra para otros bienes o servicios, o simplemente para destinar al ahorro si es el caso. Por lo tanto, hay que celebrar que el mercado en esta ocasi&#243;n nos est&#233; dando buenas noticias, que nuestro pa&#237;s ahorre divisas como importador que somos de estas energ&#237;as, que los negocios funcionen mejor al abaratar costes, y que las familias tengamos un alivio al pasar por el surtidor o llenar el dep&#243;sito de la calefacci&#243;n. La l&#225;stima es que la bajada del carburante no guarde la misma proporci&#243;n que la ca&#237;da de las cotizaciones del crudo, lo que beneficia a las grandes empresas refinadoras, y l&#225;stima que un injusto sistema impositivo como es el impuesto indirecto de hidrocarburos, nos obligue a pagar un precio pol&#237;tico por algo que es art&#237;culo de primera necesidad.<\/p>\n<\/div>\n<p>\nArt&#237;culo de opini&#243;n de Jos&#233; Antonio Turrado publicado en La Nueva Cr&#243;nica del viernes 23 de enero de 2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No entiendo a algunos economistas que se empe&#241;an en ir contracorriente, quiz&#225;s para hacerse los interesantes, y le encuentran pegas al hecho de que en los &#250;ltimos meses se haya producido una escalada de bajada del precio de los carburantes.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LOS CARBURANTES - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"No entiendo a algunos economistas que se empe&#241;an en ir contracorriente, quiz&#225;s para hacerse los interesantes, y le encuentran pegas al hecho de que en los &#250;ltimos meses se haya producido una escalada de bajada del precio de los carburantes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LOS CARBURANTES - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"No entiendo a algunos economistas que se empe&#241;an en ir contracorriente, quiz&#225;s para hacerse los interesantes, y le encuentran pegas al hecho de que en los &#250;ltimos meses se haya producido una escalada de bajada del precio de los carburantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-22T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T09:00:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2\",\"name\":\"LOS CARBURANTES - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2015-01-22T23:00:00+00:00\",\"dateModified\":\"2017-11-15T09:00:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"No entiendo a algunos economistas que se empe&#241;an en ir contracorriente, quiz&#225;s para hacerse los interesantes, y le encuentran pegas al hecho de que en los &#250;ltimos meses se haya producido una escalada de bajada del precio de los carburantes.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LOS CARBURANTES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LOS CARBURANTES - ASAJA Le\u00f3n","description":"No entiendo a algunos economistas que se empe&#241;an en ir contracorriente, quiz&#225;s para hacerse los interesantes, y le encuentran pegas al hecho de que en los &#250;ltimos meses se haya producido una escalada de bajada del precio de los carburantes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2","og_locale":"es_ES","og_type":"article","og_title":"LOS CARBURANTES - ASAJA Le\u00f3n","og_description":"No entiendo a algunos economistas que se empe&#241;an en ir contracorriente, quiz&#225;s para hacerse los interesantes, y le encuentran pegas al hecho de que en los &#250;ltimos meses se haya producido una escalada de bajada del precio de los carburantes.","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2015-01-22T23:00:00+00:00","article_modified_time":"2017-11-15T09:00:36+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2","name":"LOS CARBURANTES - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2015-01-22T23:00:00+00:00","dateModified":"2017-11-15T09:00:36+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"No entiendo a algunos economistas que se empe&#241;an en ir contracorriente, quiz&#225;s para hacerse los interesantes, y le encuentran pegas al hecho de que en los &#250;ltimos meses se haya producido una escalada de bajada del precio de los carburantes.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/los-carburantes-2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"LOS CARBURANTES"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/728"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=728"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/728\/revisions"}],"predecessor-version":[{"id":1093,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/728\/revisions\/1093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}