{"id":760,"date":"2014-06-27T00:00:00","date_gmt":"2014-06-26T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2014\/06\/27\/concentraciones-parcelarias\/"},"modified":"2017-11-15T10:01:15","modified_gmt":"2017-11-15T09:01:15","slug":"concentraciones-parcelarias","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias","title":{"rendered":"CONCENTRACIONES PARCELARIAS"},"content":{"rendered":"<h2>A tenor de las publicaciones que aparecen en el Bolet&#237;n Oficial de Castilla y Le&#243;n, parece que la consejera de Agricultura est&#225; cumpliendo su compromiso con varios alcaldes de acometer infraestructuras y entregar las parcelas en varias concentraciones parcelarias iniciadas hace dos d&#233;cadas.<\/h2>\n<p style=\"text-align: center\">\n<span style=\"color: #006400\"><strong>CONCENTRACIONES PARCELARIAS<\/strong>&#160;<\/span><\/p>\n<p style=\"text-align: justify\">\nA tenor de las publicaciones que aparecen en el Bolet&#237;n Oficial de Castilla y Le&#243;n, parece que la consejera de Agricultura est&#225; cumpliendo su compromiso con varios alcaldes de acometer infraestructuras y entregar las parcelas en varias concentraciones parcelarias iniciadas hace dos d&#233;cadas. Todo perfecto si a la vez, con sus propios medios, la Consejer&#237;a preparase los t&#237;tulos de propiedad para entrega al notario y registrador, en vez de retrasarlo tambi&#233;n durante d&#233;cadas con el consiguiente trastorno para las ventas, donaciones, herencias y sobre todo a la hora de depositar la propiedad como garant&#237;a de un pr&#233;stamo.&#160;<\/p>\n<div>\n<p style=\"text-align: justify\">\nSi la Junta entra en racha de poner al d&#237;a sus concentraciones parcelarias y llegan fondos frescos del nuevo Programa de Desarrollo Rural, a la vez que nueva legislaci&#243;n en la materia de la mano de la nueva Ley Agraria, es el momento de acometer un ambicioso proyecto de reconcentraci&#243;n parcelaria en nuestra provincia que seguramente est&#225; en mente de todos los agraristas. Me refiero a la amplia superficie de cultivo de secano que quedar&#237;a en el tri&#225;ngulo formado por los r&#237;os Esla y Cea y la carretera nacional 601 que une Le&#243;n y Valladolid. Sin duda las mejores fincas de secano, sin posibilidad alguna de transformarse alg&#250;n d&#237;a en regad&#237;o, que se concentraron parcialmente hace m&#225;s de cuarenta a&#241;o y cuyas parcelas no re&#250;nen ya los est&#225;ndares que exige una agricultura moderna. Y hago este planteamiento a sabiendas de que no es algo fara&#243;nico imposible de ejecutarse, m&#225;s bien al contrario, es un proyecto asumible econ&#243;micamente, aceptable por parte de los propietarios de tierra y demandado por los agricultores. Estando como est&#225; la propiedad investigada y la zona cartografiada, y aprovechando la mayor&#237;a de los trazados de caminos y desag&#252;es, esto es m&#225;s cuesti&#243;n de voluntades pol&#237;ticas que de disponibilidad de recursos p&#250;blicos. Ser&#237;a un proyecto similar a la reconcentraci&#243;n de Payuelos, que se resolvi&#243; en tres o cuatro a&#241;os y se entregaron las parcelas en 2005, con la diferencia que aquello era con vistas al regad&#237;o y esto es para seguir cultivando de secano. Mucho m&#225;s f&#225;cil.&#160;<\/p>\n<\/div>\n<p style=\"text-align: justify\">\nArt&#237;culo de opini&#243;n de Jos&#233; Antonio Turrado publicado en La Nueva Cr&#243;nica del viernes 27 de junio de 2014.&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A tenor de las publicaciones que aparecen en el Bolet&#237;n Oficial de Castilla y Le&#243;n, parece que la consejera de Agricultura est&#225; cumpliendo su compromiso con varios alcaldes de acometer infraestructuras y entregar las parcelas en varias concentraciones parcelarias iniciadas hace dos d&#233;cadas.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CONCENTRACIONES PARCELARIAS - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"A tenor de las publicaciones que aparecen en el Bolet&#237;n Oficial de Castilla y Le&#243;n, parece que la consejera de Agricultura est&#225; cumpliendo su compromiso con varios alcaldes de acometer infraestructuras y entregar las parcelas en varias concentraciones parcelarias iniciadas hace dos d&#233;cadas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONCENTRACIONES PARCELARIAS - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"A tenor de las publicaciones que aparecen en el Bolet&#237;n Oficial de Castilla y Le&#243;n, parece que la consejera de Agricultura est&#225; cumpliendo su compromiso con varios alcaldes de acometer infraestructuras y entregar las parcelas en varias concentraciones parcelarias iniciadas hace dos d&#233;cadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-26T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T09:01:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias\",\"name\":\"CONCENTRACIONES PARCELARIAS - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2014-06-26T22:00:00+00:00\",\"dateModified\":\"2017-11-15T09:01:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"A tenor de las publicaciones que aparecen en el Bolet&#237;n Oficial de Castilla y Le&#243;n, parece que la consejera de Agricultura est&#225; cumpliendo su compromiso con varios alcaldes de acometer infraestructuras y entregar las parcelas en varias concentraciones parcelarias iniciadas hace dos d&#233;cadas.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONCENTRACIONES PARCELARIAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONCENTRACIONES PARCELARIAS - ASAJA Le\u00f3n","description":"A tenor de las publicaciones que aparecen en el Bolet&#237;n Oficial de Castilla y Le&#243;n, parece que la consejera de Agricultura est&#225; cumpliendo su compromiso con varios alcaldes de acometer infraestructuras y entregar las parcelas en varias concentraciones parcelarias iniciadas hace dos d&#233;cadas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias","og_locale":"es_ES","og_type":"article","og_title":"CONCENTRACIONES PARCELARIAS - ASAJA Le\u00f3n","og_description":"A tenor de las publicaciones que aparecen en el Bolet&#237;n Oficial de Castilla y Le&#243;n, parece que la consejera de Agricultura est&#225; cumpliendo su compromiso con varios alcaldes de acometer infraestructuras y entregar las parcelas en varias concentraciones parcelarias iniciadas hace dos d&#233;cadas.","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2014-06-26T22:00:00+00:00","article_modified_time":"2017-11-15T09:01:15+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias","name":"CONCENTRACIONES PARCELARIAS - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2014-06-26T22:00:00+00:00","dateModified":"2017-11-15T09:01:15+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"A tenor de las publicaciones que aparecen en el Bolet&#237;n Oficial de Castilla y Le&#243;n, parece que la consejera de Agricultura est&#225; cumpliendo su compromiso con varios alcaldes de acometer infraestructuras y entregar las parcelas en varias concentraciones parcelarias iniciadas hace dos d&#233;cadas.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/concentraciones-parcelarias#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"CONCENTRACIONES PARCELARIAS"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/760"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=760"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/760\/revisions"}],"predecessor-version":[{"id":1125,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/760\/revisions\/1125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}