{"id":7646,"date":"2007-03-06T00:00:00","date_gmt":"2007-03-05T23:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/leon\/sin-categoria\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias"},"modified":"2007-03-06T00:00:00","modified_gmt":"2007-03-05T23:00:00","slug":"asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias","title":{"rendered":"ASAJA SE PRONUNCIAR&#193; HOY EN LA JUNTA SOBRE LAS ELECCIONES A C&#193;MARAS AGRARIAS"},"content":{"rendered":"<h2>ASAJA de Castilla y Le&#243;n participar&#225; hoy en la reuni&#243;n convocada por la Consejer&#237;a de Agricultura y Ganader&#237;a para analizar el \u00abproyecto de Acuerdo de la Junta de Castilla y Le&#243;n por el que se convocan elecciones a C&#225;maras Agrarias Provinciales y se fijan los gastos electorales\u00bb.<\/h2>\n<p><b><\/p>\n<p align=\"center\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"center\"><font color=\"#009900\" size=\"2\">ASAJA SE PRONUNCIAR&#193; HOY EN LA JUNTA SOBRE L<\/font><font size=\"2\"><font color=\"#009900\">AS ELECCIONES A C&#193;MARAS AGRARIAS<\/font> <\/font>\n<\/p>\n<p align=\"center\"><font size=\"2\"><\/font><\/p>\n<p><\/b><\/p>\n<p align=\"justify\"><font size=\"2\">ASAJA de Castilla y Le&#243;n participar&#225; hoy en la reuni&#243;n convocada por la Consejer&#237;a de Agricultura y Ganader&#237;a para analizar el \u00abproyecto de Acuerdo de la Junta de Castilla y Le&#243;n por el que se convocan elecciones a C&#225;maras Agrarias Provinciales y se fijan los gastos electorales\u00bb. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">ASAJA pedir&#225; que las elecciones, dado que no pueden celebrarse en mayo por coincidir con las municipales y auton&#243;micas, se retrasen hasta el mes de febrero de 2008 para que sean en una &#233;poca de poco trabajo en el campo y de desahogo en las oficinas de las organizaciones agrarias, con el fin de poder hacer una campa&#241;a electoral que llegue a todos los votantes. Por otra parte, ASAJA pedir&#225; que se defina el futuro papel de las organizaciones profesionales agrarias, ya que no tiene sentido concurrir a un proceso electoral para medir la representatividad si despu&#233;s participan en la interlocuci&#243;n con el Gobierno regional otros entes agrarios en iguales o mejores condiciones. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Por &#250;ltimo ASAJA pedir&#225; a la Junta una financiaci&#243;n p&#250;blica de la campa&#241;a electoral que evite la sangr&#237;a econ&#243;mica que viene siendo este proceso para las organizaciones agrarias. ASAJA estima que el gasto real de la campa&#241;a para las OPA que concurrieron al &#250;ltimo proceso electoral se aproxim&#243; a los dos millones de euros, por lo que muchas organizaciones provinciales est&#225;n pagando todav&#237;a aquellos excesos. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">ASAJA lamenta el clima de divisi&#243;n del sector ante este nuevo proceso electoral, a pesar de que pueda ser beneficioso para los resultados que espera conseguir como principal organizaci&#243;n agraria de la regi&#243;n. ASAJA no duda que los electores valorar&#225;n el clima de unidad y absoluta cohesi&#243;n que se vive en el seno de la organizaci&#243;n, as&#237; como la postura de profesionalidad e independencia que se ha mantenido con firmeza en los &#250;ltimos cinco a&#241;os. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">&#160; <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">&#160; <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">&#160; <\/font>\n<\/p>\n<p align=\"right\"><font size=\"2\">Le&#243;n a 06 de Marzo de 2007 <\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ASAJA de Castilla y Le&#243;n participar&#225; hoy en la reuni&#243;n convocada por la Consejer&#237;a de Agricultura y Ganader&#237;a para analizar el \u00abproyecto de Acuerdo de la Junta de Castilla y Le&#243;n por el que se convocan elecciones a C&#225;maras Agrarias Provinciales y se fijan los gastos electorales\u00bb.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ASAJA SE PRONUNCIAR&#193; HOY EN LA JUNTA SOBRE LAS ELECCIONES A C&#193;MARAS AGRARIAS - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"ASAJA de Castilla y Le&#243;n participar&#225; hoy en la reuni&#243;n convocada por la Consejer&#237;a de Agricultura y Ganader&#237;a para analizar el &quot;proyecto de Acuerdo de la Junta de Castilla y Le&#243;n por el que se convocan elecciones a C&#225;maras Agrarias Provinciales y se fijan los gastos electorales&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASAJA SE PRONUNCIAR&#193; HOY EN LA JUNTA SOBRE LAS ELECCIONES A C&#193;MARAS AGRARIAS - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"ASAJA de Castilla y Le&#243;n participar&#225; hoy en la reuni&#243;n convocada por la Consejer&#237;a de Agricultura y Ganader&#237;a para analizar el &quot;proyecto de Acuerdo de la Junta de Castilla y Le&#243;n por el que se convocan elecciones a C&#225;maras Agrarias Provinciales y se fijan los gastos electorales&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2007-03-05T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias\",\"name\":\"ASAJA SE PRONUNCIAR&#193; HOY EN LA JUNTA SOBRE LAS ELECCIONES A C&#193;MARAS AGRARIAS - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2007-03-05T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"ASAJA de Castilla y Le&#243;n participar&#225; hoy en la reuni&#243;n convocada por la Consejer&#237;a de Agricultura y Ganader&#237;a para analizar el \\\"proyecto de Acuerdo de la Junta de Castilla y Le&#243;n por el que se convocan elecciones a C&#225;maras Agrarias Provinciales y se fijan los gastos electorales\\\".\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASAJA SE PRONUNCIAR&#193; HOY EN LA JUNTA SOBRE LAS ELECCIONES A C&#193;MARAS AGRARIAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASAJA SE PRONUNCIAR&#193; HOY EN LA JUNTA SOBRE LAS ELECCIONES A C&#193;MARAS AGRARIAS - ASAJA Le\u00f3n","description":"ASAJA de Castilla y Le&#243;n participar&#225; hoy en la reuni&#243;n convocada por la Consejer&#237;a de Agricultura y Ganader&#237;a para analizar el \"proyecto de Acuerdo de la Junta de Castilla y Le&#243;n por el que se convocan elecciones a C&#225;maras Agrarias Provinciales y se fijan los gastos electorales\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias","og_locale":"es_ES","og_type":"article","og_title":"ASAJA SE PRONUNCIAR&#193; HOY EN LA JUNTA SOBRE LAS ELECCIONES A C&#193;MARAS AGRARIAS - ASAJA Le\u00f3n","og_description":"ASAJA de Castilla y Le&#243;n participar&#225; hoy en la reuni&#243;n convocada por la Consejer&#237;a de Agricultura y Ganader&#237;a para analizar el \"proyecto de Acuerdo de la Junta de Castilla y Le&#243;n por el que se convocan elecciones a C&#225;maras Agrarias Provinciales y se fijan los gastos electorales\".","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2007-03-05T23:00:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias","name":"ASAJA SE PRONUNCIAR&#193; HOY EN LA JUNTA SOBRE LAS ELECCIONES A C&#193;MARAS AGRARIAS - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2007-03-05T23:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"ASAJA de Castilla y Le&#243;n participar&#225; hoy en la reuni&#243;n convocada por la Consejer&#237;a de Agricultura y Ganader&#237;a para analizar el \"proyecto de Acuerdo de la Junta de Castilla y Le&#243;n por el que se convocan elecciones a C&#225;maras Agrarias Provinciales y se fijan los gastos electorales\".","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/asaja-se-pronunciar-hoy-en-la-junta-sobre-las-elecciones-a-cmaras-agrarias#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"ASAJA SE PRONUNCIAR&#193; HOY EN LA JUNTA SOBRE LAS ELECCIONES A C&#193;MARAS AGRARIAS"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/7646"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=7646"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/7646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=7646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=7646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=7646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}