{"id":77,"date":"2017-10-13T00:00:00","date_gmt":"2017-10-12T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2017\/10\/13\/las-seis-noticias-agrarias-de-la-semana-13102017\/"},"modified":"2017-11-14T18:21:19","modified_gmt":"2017-11-14T17:21:19","slug":"las-seis-noticias-agrarias-de-la-semana-13102017","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017","title":{"rendered":"Las seis noticias agrarias de la semana &#8211; 13\/10\/2017"},"content":{"rendered":"<h2>Comunidad de regantes del canal del P&#225;ramo, concentraci&#243;n parcelaria P&#225;ramo bajo, consejos reguladores, productos fitosanitarios, convenci&#243;n de j&#243;venes  y zona regable Payuelos<\/h2>\n<p style=\"text-align: center;\">\n<span style=\"color:#006400;\"><strong>LAS SEIS NOTICIAS AGRARIAS DE LA SEMANA<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">\n1.&#160;&#160;&#160; &#160;La <strong>Comunidad de Regantes del Canal del P&#225;ramo<\/strong> ha convocado para el domingo d&#237;a 15 de octubre a sus compromisarios para elegir un nuevo presidente de la Comunidad General en sustituci&#243;n del dimitido Ram&#243;n Ferrero. El acto ser&#225; a las 12 del mediod&#237;a en el Centro C&#237;vico de Santa Mar&#237;a del P&#225;ramo. Es previsible que se presente m&#225;s de un candidato y que las votaciones est&#233;n re&#241;idas.<\/p>\n<p style=\"text-align: justify;\">\n2.&#160;&#160;&#160; El Bolet&#237;n Oficial de la Provincia de Le&#243;n ha publicado el acuerdo del Consejo de Gobierno no de la Junta de Castilla y Le&#243;n por el que se declara de utilidad p&#250;blica y urgente ejecuci&#243;n la <strong>concentraci&#243;n parcelaria de la zona P&#225;ramo Bajo cultivos de secano.<\/strong> Esta concentraci&#243;n afecta a los ayuntamientos de&#160; Laguna de Negrillos, Villamandos, La Antigua, Pozuelo del P&#225;ramo y San Adri&#225;n del Valle. A partir de este momento comienzan los trabajos de investigaci&#243;n de la propiedad.<\/p>\n<p style=\"text-align: justify;\">\n3.&#160;&#160;&#160; El Bolet&#237;n Oficial de Castilla y Le&#243;n ha publicado una resoluci&#243;n del Instituto Tecnol&#243;gico Agrario por la que se convoca la aportaci&#243;n econ&#243;mica a las actividades promovidas por los consejos reguladores y dem&#225;s asociaciones sectoriales agroalimentarias, para el desarrollo de <strong>programas voluntarios de fomento y divulgaci&#243;n de la calidad alimentaria<\/strong> en el a&#241;o 2017. El plazo de solicitudes finaliza el 27 de octubre.<\/p>\n<p style=\"text-align: justify;\">\n4.&#160;&#160;&#160; La Uni&#243;n Europea ha prohibido el uso de <strong>productos fitosanitarios<\/strong> en fincas destinadas a cumplir con la obligaci&#243;n de dejar un 5 por ciento de la superficie para fines de inter&#233;s ecol&#243;gico. Esta superficie, obligatoria para quienes cultivan m&#225;s de 15 hect&#225;reas, puede ser de barbecho o de cultivos fijadores de nitr&#243;geno. El no poder utilizar fitosanitarios limita mucho su utilizaci&#243;n para el cultivo de alubias, alfalfa, garbanzos u otras proteaginosas.<\/p>\n<p style=\"text-align: justify;\">\n5.&#160;&#160;&#160; El pr&#243;ximo viernes se celebra en la Finca Valdemora de La Ba&#241;eza una <strong>convenci&#243;n de los j&#243;venes<\/strong> que se han incorporado al campo en los &#250;ltimos a&#241;os, organizada por ASAJA de Le&#243;n. En este acto se aprobar&#225; un documento que recoja las principales reivindicaciones de los j&#243;venes agricultores y ganaderos de la provincia de Le&#243;n. La asistencia, previa inscripci&#243;n, est&#225; limitada a los socios de ASAJA o familiares directos de socios, con menos de cuarenta a&#241;os de edad. La jornada la clausurar&#225; el presiente regional de ASAJA, Donaciano Dujo.<\/p>\n<p style=\"text-align: justify;\">\n6.&#160;&#160;&#160; La Junta de Castilla y Le&#243;n ha comunicado la licitaci&#243;n de las obras de nuevos regad&#237;os del <strong>sector XXIV de la zona regable de Payuelos<\/strong>, dependiente del embalse de Ria&#241;o. Se trata de una superficie de 3.953 hect&#225;reas, de las cuales 1.986 son de regad&#237;o. Las obras incluyen 128 kil&#243;metros de caminos, 57 de desag&#252;es y distintas actuaciones medioambientales. Esta licitaci&#243;n llega de nuevo con retraso, pues el acuerdo ya lo adopt&#243; el Consejo de Gobierno el 20 de julio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunidad de regantes del canal del P&#225;ramo, concentraci&#243;n parcelaria P&#225;ramo bajo, consejos reguladores, productos fitosanitarios, convenci&#243;n de j&#243;venes  y zona regable Payuelos<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las seis noticias agrarias de la semana - 13\/10\/2017 - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Comunidad de regantes del canal del P&#225;ramo, concentraci&#243;n parcelaria P&#225;ramo bajo, consejos reguladores, productos fitosanitarios, convenci&#243;n de j&#243;venes y zona regable Payuelos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las seis noticias agrarias de la semana - 13\/10\/2017 - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Comunidad de regantes del canal del P&#225;ramo, concentraci&#243;n parcelaria P&#225;ramo bajo, consejos reguladores, productos fitosanitarios, convenci&#243;n de j&#243;venes y zona regable Payuelos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-12T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T17:21:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017\",\"name\":\"Las seis noticias agrarias de la semana - 13\/10\/2017 - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2017-10-12T22:00:00+00:00\",\"dateModified\":\"2017-11-14T17:21:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Comunidad de regantes del canal del P&#225;ramo, concentraci&#243;n parcelaria P&#225;ramo bajo, consejos reguladores, productos fitosanitarios, convenci&#243;n de j&#243;venes y zona regable Payuelos\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las seis noticias agrarias de la semana &#8211; 13\/10\/2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las seis noticias agrarias de la semana - 13\/10\/2017 - ASAJA Le\u00f3n","description":"Comunidad de regantes del canal del P&#225;ramo, concentraci&#243;n parcelaria P&#225;ramo bajo, consejos reguladores, productos fitosanitarios, convenci&#243;n de j&#243;venes y zona regable Payuelos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017","og_locale":"es_ES","og_type":"article","og_title":"Las seis noticias agrarias de la semana - 13\/10\/2017 - ASAJA Le\u00f3n","og_description":"Comunidad de regantes del canal del P&#225;ramo, concentraci&#243;n parcelaria P&#225;ramo bajo, consejos reguladores, productos fitosanitarios, convenci&#243;n de j&#243;venes y zona regable Payuelos","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2017-10-12T22:00:00+00:00","article_modified_time":"2017-11-14T17:21:19+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017","name":"Las seis noticias agrarias de la semana - 13\/10\/2017 - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2017-10-12T22:00:00+00:00","dateModified":"2017-11-14T17:21:19+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Comunidad de regantes del canal del P&#225;ramo, concentraci&#243;n parcelaria P&#225;ramo bajo, consejos reguladores, productos fitosanitarios, convenci&#243;n de j&#243;venes y zona regable Payuelos","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-seis-noticias-agrarias-de-la-semana-13102017#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"Las seis noticias agrarias de la semana &#8211; 13\/10\/2017"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/77"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=77"}],"version-history":[{"count":2,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/77\/revisions"}],"predecessor-version":[{"id":3642,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/77\/revisions\/3642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=77"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=77"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=77"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}