{"id":802,"date":"2013-06-28T00:00:00","date_gmt":"2013-06-27T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2013\/06\/28\/la-batalla-de-la-pac-comienza-hoy\/"},"modified":"2017-11-15T10:01:56","modified_gmt":"2017-11-15T09:01:56","slug":"la-batalla-de-la-pac-comienza-hoy","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy","title":{"rendered":"LA BATALLA DE LA PAC COMIENZA HOY"},"content":{"rendered":"<h2>El acuerdo del Consejo sobre la reforma de la PAC despeja dudas sobre el futuro del campo de la provincia para los pr&#243;ximos seis a&#241;os<\/h2>\n<div align=\"center\"><b><font color=\"#003300\">LA BATALLA DE LA PAC COMIENZA HOY<\/font><\/b><\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">El acuerdo del Consejo sobre la reforma de la PAC despeja dudas sobre el futuro del campo de la provincia para los pr&#243;ximos seis a&#241;os. Que haya una pol&#237;tica agraria con unas reglas determinadas y con un presupuesto m&#225;s o menos cierto, da estabilidad a un sector&#160; econ&#243;mico que est&#225; siendo fundamental en un momento de crisis como el actual al ser generador de riqueza y empleo en el medio rural. La nueva pol&#237;tica agr&#237;cola com&#250;n es algo m&#225;s que ayudas econ&#243;micas al campo, pues es tambi&#233;n legislaci&#243;n de obligado cumplimiento, es restricciones a determinadas pr&#225;cticas agron&#243;micas, es aperturismo a los mercados internacionales, es una apuesta por las pr&#225;cticas respetuosas con el medio ambiente y una apuesta por el desarrollo del medio rural. Esta nueva PAC no es la que quer&#237;an unos agricultores y ganaderos profesionales deseosos de producir alimentos y vivir con la remuneraci&#243;n del mercado cobrando por los productos lo que cuesta producirlos. Porque esta nueva PAC no est&#225; pensada para fomentar la productividad de las explotaciones, ni est&#225; pensada para que se produzca un verdadero relevo generacional en el campo, ni fomenta la igualdad de obligaciones para los productores de pa&#237;ses terceros de los que importamos alimentos. La nueva regulaci&#243;n de la agricultura es despiadada para con los intereses de los ganaderos, amenaza con desestabilizar el negocio remolachero azucarero en territorios como el nuestro, no prima al verdadero profesional que se esfuerza en hacer bien las cosas, est&#225; cargada de burocracia, y sus mentores han estado m&#225;s ocupados de vender bien el producto cara a la opini&#243;n p&#250;blica que &#160;de buscar el bienestar de los agricultores y ganaderos.<\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">Pero esta es la PAC que tenemos a partir de ahora &#160;cuando toca la delicada tarea de elaborar los reglamentos. Una PAC que deja mucho margen de maniobra, m&#225;s que en otras ocasiones, para que el Estado y las comunidades aut&#243;nomas tomen decisiones, y de ello depender&#225; que las cosas vayan a mejor o que vayan a peor, que la aplicaci&#243;n sea justa o por el contrario cree agravios y desequilibrios territoriales. Y es que hoy no hay noticia porque esto se ve&#237;a venir, era previsible, la noticia llegar&#225; cuando comience a negociar nuestro ministro Arias Ca&#241;ete con la consejera Silvia Clemente en un clima de malas o muy malas relaciones entre ambos. La verdadera batalla de la reforma de la PAC ha empezado hoy.<\/div>\n<div align=\"justify\">&#160;<\/div>\n<div align=\"justify\">Art&#237;culo de opini&#243;n de Jos&#233; Antonio Turrado publicado en La Cr&#243;nica del viernes 28 de junio de 2013.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El acuerdo del Consejo sobre la reforma de la PAC despeja dudas sobre el futuro del campo de la provincia para los pr&#243;ximos seis a&#241;os<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LA BATALLA DE LA PAC COMIENZA HOY - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"El acuerdo del Consejo sobre la reforma de la PAC despeja dudas sobre el futuro del campo de la provincia para los pr&#243;ximos seis a&#241;os\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA BATALLA DE LA PAC COMIENZA HOY - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El acuerdo del Consejo sobre la reforma de la PAC despeja dudas sobre el futuro del campo de la provincia para los pr&#243;ximos seis a&#241;os\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-27T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T09:01:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy\",\"name\":\"LA BATALLA DE LA PAC COMIENZA HOY - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2013-06-27T22:00:00+00:00\",\"dateModified\":\"2017-11-15T09:01:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"El acuerdo del Consejo sobre la reforma de la PAC despeja dudas sobre el futuro del campo de la provincia para los pr&#243;ximos seis a&#241;os\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA BATALLA DE LA PAC COMIENZA HOY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA BATALLA DE LA PAC COMIENZA HOY - ASAJA Le\u00f3n","description":"El acuerdo del Consejo sobre la reforma de la PAC despeja dudas sobre el futuro del campo de la provincia para los pr&#243;ximos seis a&#241;os","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy","og_locale":"es_ES","og_type":"article","og_title":"LA BATALLA DE LA PAC COMIENZA HOY - ASAJA Le\u00f3n","og_description":"El acuerdo del Consejo sobre la reforma de la PAC despeja dudas sobre el futuro del campo de la provincia para los pr&#243;ximos seis a&#241;os","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2013-06-27T22:00:00+00:00","article_modified_time":"2017-11-15T09:01:56+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy","name":"LA BATALLA DE LA PAC COMIENZA HOY - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2013-06-27T22:00:00+00:00","dateModified":"2017-11-15T09:01:56+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"El acuerdo del Consejo sobre la reforma de la PAC despeja dudas sobre el futuro del campo de la provincia para los pr&#243;ximos seis a&#241;os","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-batalla-de-la-pac-comienza-hoy#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"LA BATALLA DE LA PAC COMIENZA HOY"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/802"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=802"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/802\/revisions"}],"predecessor-version":[{"id":1167,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/802\/revisions\/1167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}