{"id":8040,"date":"2004-03-23T00:00:00","date_gmt":"2004-03-22T23:00:00","guid":{"rendered":"http:\/\/www.asajacyl.com\/leon\/sin-categoria\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len"},"modified":"2004-03-23T00:00:00","modified_gmt":"2004-03-22T23:00:00","slug":"la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len","title":{"rendered":"LA REFORMA DE LA OCM DEL AZ&#218;CAR HAR&#205;A INVIABLE EL CULTIVO EN CASTILLA Y LE&#211;N"},"content":{"rendered":"<h2>Una explotaci&#243;n remolachera media perder&#237;a cada a&#241;o <\/p>\n<p>m&#225;s de 5.000 euros por la bajada de precios<\/h2>\n<p><b><\/p>\n<p align=\"center\"><font size=\"2\"><font color=\"#009900\">LA REFORMA DE LA OCM DEL AZ&#218;CAR HAR&#205;A INVIABLE EL CULTIVO EN CASTILLA Y LE&#211;N<\/font> <\/font>\n<\/p>\n<p align=\"center\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"center\"><font color=\"#0099ff\" size=\"2\">Una explotaci&#243;n remolachera media perder&#237;a cada a&#241;o <\/font>\n<\/p>\n<p align=\"center\"><font color=\"#0099ff\" size=\"2\">m&#225;s de 5.000 euros por la bajada de precios<\/font><\/p>\n<p><\/b><font size=\"2\"> <\/font><\/p>\n<p><font size=\"2\">ASAJA de Castilla y Le&#243;n advierte de la amenaza que para la continuidad del cultivo de la remolacha en la regi&#243;n supondr&#237;a la aprobaci&#243;n de la propuesta de la Comisi&#243;n Europea para reformar la Organizaci&#243;n Com&#250;n del Mercado del Az&#250;car, reforma que supondr&#237;a recortar en un 40 por ciento los precios percibidos por esta producci&#243;n. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">En concreto, eliminar el actual sistema de cuotas y de garant&#237;a de precios supondr&#237;a para Castilla y Le&#243;n una p&#233;rdida por campa&#241;a de unos 77 millones de euros. Teniendo en cuenta que existen cerca de 15.000 cultivadores en la Comunidad Aut&#243;noma, que se reparten 4 millones de toneladas en una superficie aproximada de 50.000 hect&#225;reas, una explotaci&#243;n media (unas 266 toneladas) tendr&#237;a cada a&#241;o p&#233;rdidas de 5.123 euros (m&#225;s de 850.000 pesetas). \u00abEs decir, el productor percibir&#237;a casi 20 euros menos por tonelada, cantidad que no s&#243;lo recortar&#237;a los beneficios, es que pondr&#237;a seriamente en peligro la viabilidad del cultivo, ya que dejar&#237;a de ser rentable producir remolacha con los costes actuales\u00bb, subraya ASAJA. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">La postura que en estos momentos defiende el presidente de ASAJA de Castilla y Le&#243;n, en la reuni&#243;n convocada por el consejero de Agricultura, Jos&#233; Val&#237;n, es que se mantenga el actual sistema de cuotas por pa&#237;ses y garant&#237;a de precios, y no s&#243;lo durante el periodo de vigencia de la OCM actual, hasta 2006. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">A la organizaci&#243;n agraria no le convencen los argumentos de Franz Fischler, respecto a los excedentes de az&#250;car que existen en la Uni&#243;n. Primero, porque esos excedentes no obedecen a la producci&#243;n europea, sino a la importaci&#243;n de az&#250;car de fuera, obligada por acuerdos internacionales. En segundo lugar, precisamente Espa&#241;a es deficitaria en producci&#243;n de az&#250;car: en todo caso, les tocar&#237;a \u00abmover ficha\u00bb a esos pa&#237;ses de la UE que producen por encima de su consumo, y que cuentan con cuotas de exportaci&#243;n. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">De cualquier forma, ASAJA considera que Espa&#241;a y la UE deben negociar con m&#225;s cautela que en ocasiones anteriores, para que no se repita lo ocurrido en Canc&#250;n, cuando Bruselas se esforz&#243; por reformar la Agenda 2000 para que Europa fuera con los deberes hechos, antes de tener garant&#237;as de que el resto de pa&#237;ses hiciera lo mismo. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Por &#250;ltimo, no puede ignorarse que el sistema actual de cuotas y precios es neutro para el presupuesto comunitario, y que una modificaci&#243;n supondr&#237;a que hab&#237;a que compensar a los agricultores por la consiguiente reducci&#243;n de precios, lo que implicar&#237;a un retoque financiero que afectar&#237;a al presupuesto agrario global. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">ASAJA pide que la Consejer&#237;a, con el respaldo de la Junta de Castilla y Le&#243;n, asuma un compromiso total con el sector remolachero, y ponga en marcha sus resortes de presi&#243;n pol&#237;ticos, sociales y econ&#243;micos para que el Estado espa&#241;ol defienda las tesis de nuestra regi&#243;n ante la Uni&#243;n Europea, sin olvidar que, hoy por hoy, no existen alternativas de cultivo que ofrezcan una rentabilidad similar a la remolacha. Para la OPA, es lo menos que se merece este sector, tras los enormes esfuerzos realizados para alcanzar niveles &#243;ptimos de producci&#243;n y calidad y de asumir una cruda reestructuraci&#243;n industrial.<\/font><b><u><font size=\"2\"> <\/font><\/p>\n<p align=\"justify\"><font size=\"2\"><\/font><\/p>\n<p><\/u><\/b><\/p>\n<p><font face=\"Arial\"><\/p>\n<p align=\"right\"><font size=\"2\">Le&#243;n a 22 de Marzo de 2004<\/font><\/p>\n<p><\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una explotaci&#243;n remolachera media perder&#237;a cada a&#241;o <\/p>\n<p>m&#225;s de 5.000 euros por la bajada de precios<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LA REFORMA DE LA OCM DEL AZ&#218;CAR HAR&#205;A INVIABLE EL CULTIVO EN CASTILLA Y LE&#211;N - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Una explotaci&#243;n remolachera media perder&#237;a cada a&#241;o   m&#225;s de 5.000 euros por la bajada de precios\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA REFORMA DE LA OCM DEL AZ&#218;CAR HAR&#205;A INVIABLE EL CULTIVO EN CASTILLA Y LE&#211;N - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Una explotaci&#243;n remolachera media perder&#237;a cada a&#241;o   m&#225;s de 5.000 euros por la bajada de precios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2004-03-22T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len\",\"name\":\"LA REFORMA DE LA OCM DEL AZ&#218;CAR HAR&#205;A INVIABLE EL CULTIVO EN CASTILLA Y LE&#211;N - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2004-03-22T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Una explotaci&#243;n remolachera media perder&#237;a cada a&#241;o m&#225;s de 5.000 euros por la bajada de precios\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA REFORMA DE LA OCM DEL AZ&#218;CAR HAR&#205;A INVIABLE EL CULTIVO EN CASTILLA Y LE&#211;N\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA REFORMA DE LA OCM DEL AZ&#218;CAR HAR&#205;A INVIABLE EL CULTIVO EN CASTILLA Y LE&#211;N - ASAJA Le\u00f3n","description":"Una explotaci&#243;n remolachera media perder&#237;a cada a&#241;o   m&#225;s de 5.000 euros por la bajada de precios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len","og_locale":"es_ES","og_type":"article","og_title":"LA REFORMA DE LA OCM DEL AZ&#218;CAR HAR&#205;A INVIABLE EL CULTIVO EN CASTILLA Y LE&#211;N - ASAJA Le\u00f3n","og_description":"Una explotaci&#243;n remolachera media perder&#237;a cada a&#241;o   m&#225;s de 5.000 euros por la bajada de precios","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2004-03-22T23:00:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len","name":"LA REFORMA DE LA OCM DEL AZ&#218;CAR HAR&#205;A INVIABLE EL CULTIVO EN CASTILLA Y LE&#211;N - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2004-03-22T23:00:00+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Una explotaci&#243;n remolachera media perder&#237;a cada a&#241;o m&#225;s de 5.000 euros por la bajada de precios","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/la-reforma-de-la-ocm-del-azcar-hara-inviable-el-cultivo-en-castilla-y-len#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"LA REFORMA DE LA OCM DEL AZ&#218;CAR HAR&#205;A INVIABLE EL CULTIVO EN CASTILLA Y LE&#211;N"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/8040"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=8040"}],"version-history":[{"count":0,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/8040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=8040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=8040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=8040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}