{"id":848,"date":"2006-12-13T00:00:00","date_gmt":"2006-12-12T23:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2006\/12\/13\/al-respecto-de-la-condicionalidad\/"},"modified":"2017-11-15T10:02:39","modified_gmt":"2017-11-15T09:02:39","slug":"al-respecto-de-la-condicionalidad","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad","title":{"rendered":"AL RESPECTO DE LA CONDICIONALIDAD"},"content":{"rendered":"<h2>Como agricultor y miembro de esa asociaci&#243;n agraria quiero manifestar la incidencia que est&#225; teniendo la conjunci&#243;n de dos nuevos acontecimientos, para los agricultores y ganaderos de nuestra Comarca agr&#237;cola<\/h2>\n<p align=\"center\"><font size=\"2\"><strong><font color=\"#009900\">AL RESPECTO DE LA CONDICIONALIDAD<\/font><\/strong>&#160;<\/font>\n<\/p>\n<p align=\"center\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Como agricultor y miembro de esa asociaci&#243;n agraria quiero manifestar la incidencia que est&#225; teniendo la conjunci&#243;n de dos nuevos acontecimientos, para los agricultores y ganaderos de nuestra Comarca agr&#237;cola: Primero, el obligado cumplimiento de la orden AYG\/1642\/2005, de 5 de diciembre (BOCyL del 15 de diciembre), que establece <i>\u00ablos <b>requisitos legales<\/b> de gesti&#243;n y las <b>condiciones agrarias y medioambientales<\/b> que deber&#225;n cumplir los agricultores <\/i>(y ganaderos) <i>que reciban ayudas directas de la pol&#237;tica agraria com&#250;n\u00bb<\/i>. El segundo, la \u00abmoda\u00bb, cada vez m&#225;s extendida, de forestar tierras agrarias en comarcas con bajo &#237;ndice de producci&#243;n. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">El cumplimiento de las normas referidas afecta por igual a todas las comarcas, al margen del &#237;ndice de producci&#243;n de las mismas, lo que hace que el coste relativo del cumplimiento de dichas normas sea mayor para las zonas de m&#225;s baja producci&#243;n que para las restantes; por lo que econ&#243;micamente vuelven a salir m&#225;s perjudicadas las de baja producci&#243;n. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Pero adem&#225;s, en nuestra comarca, la de Astorga, y las colindantes de secano (Cabrera, La Ba&#241;eza, etc), todas con &#237;ndice de producci&#243;n inferior a 2, se est&#225; extendiendo la pr&#225;ctica de forestar cualquier superficie rural, principalmente entre propietarios jubilados y entre, cada vez m&#225;s frecuentes, especuladores que buscan subvenciones. Este hecho conlleva directas consecuencias graves para las maltrechas econom&#237;as de los pobladores y profesionales del campo de estas zonas, principalmente ganaderos de ovino y agricultores de secano. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Las superficies que se van forestando antes se aprovechaban para el pastoreo, ahora no; pero adem&#225;s, impiden el paso de los reba&#241;os a superficies no forestadas. Son superficies que tampoco se pueden cazar, con lo que se pone en peligro el &#250;nico o principal recurso econ&#243;mico de algunas corporaciones locales. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Las superficies que quedan libres de forestaci&#243;n, en su mayor parte las que trabajan los agricultores, tambi&#233;n est&#225;n afectadas por normas y pr&#225;cticas que perjudican a todos, particularmente a los ganaderos: utilizaci&#243;n de herbicidas en parcelas de retiradas y de barbechos, ya que no se permite el que las superficies se mantengan en condiciones agron&#243;micas adecuadas mediante el eficaz y ancestral m&#233;todo del pastoreo, el cual permitir&#237;a un aprovechamiento muy necesario para los ganados, ahorrar&#237;a consumo de combustible y gastos de herbicidas a los agricultores y evitar&#237;a el perjuicio medioambiental que ocasionan dichos productos y su distribuci&#243;n. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Sumado a los anteriores perjuicios, tambi&#233;n en el contexto de las condiciones agrarias y medioambientales, nos encontramos con la obligaci&#243;n de hacer labores de arada a las superficies de cereal reci&#233;n recoleccionado, en franjas perimetrales de al menos 3 metros de ancho, cuando hay una superficie forestal a menos de 400 metros y, si es colindante con ella, la franja debe ser de al menos 20 metros. Esto realizado por los agricultores, en sus tierras, con su trabajo, con su dinero, perjudicando las propias superficies con labores contraindicadas en esas fechas; todo ello para proteger las forestales que le ha colocado al lado otro titular. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">En determinados pueblos de estas comarcas, m&#225;s del 90% de las parcelas de labor de secano tienen a menos de 400 metros alguna superficie reci&#233;n forestada, con lo cual la pr&#225;ctica antes mencionada afecta a casi todas las parcelas sembradas de cereal. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Sin entrar en m&#225;s inconvenientes, que los hay en relaci&#243;n a los acontecimientos referidos, solicito su intervenci&#243;n ante las autoridades competentes, en defensa de los leg&#237;timos intereses de agricultores y ganaderos en un doble sentido: <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">1&#186;: Que los m&#233;todos de protecci&#243;n de superficies forestales, frente a posibles incendios, corran a cargo de los titulares forestales, en sus propias superficies, y no de los colindantes agricultores. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">2&#186;: Que en zonas con &#237;ndice de producci&#243;n comarcal bajo, al menos las inferiores a 2, se permita el pastoreo, en cuanto m&#233;todo especialmente sano desde el punto de vista medioambiental, para mantener superficies agr&#237;colas en adecuadas condiciones agroambientales, evitando la necesidad de recursos m&#225;s caros y agresivos con el medioambiente, como son el laboreo tradicional o el uso de herbicidas. Con ello se contribuir&#225; a que el coste relativo de las medidas agroambientales no sea m&#225;s alto en las zonas m&#225;s pobres. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">3&#186;: Que tanto la primera como la segunda de las peticiones queden reguladas en las leyes que corresponda y que nada quede al arbitrio de determinadas autoridades en funci&#243;n de circunstancias puntuales de cada a&#241;o o de cada regi&#243;n. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font>\n<\/p>\n<p align=\"right\"><font size=\"2\">Gerardo B. Blanco Blas.<\/font>\n<\/p>\n<p align=\"right\">En Astorga, a 1 de diciembre de 2006<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como agricultor y miembro de esa asociaci&#243;n agraria quiero manifestar la incidencia que est&#225; teniendo la conjunci&#243;n de dos nuevos acontecimientos, para los agricultores y ganaderos de nuestra Comarca agr&#237;cola<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AL RESPECTO DE LA CONDICIONALIDAD - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Como agricultor y miembro de esa asociaci&#243;n agraria quiero manifestar la incidencia que est&#225; teniendo la conjunci&#243;n de dos nuevos acontecimientos, para los agricultores y ganaderos de nuestra Comarca agr&#237;cola\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AL RESPECTO DE LA CONDICIONALIDAD - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Como agricultor y miembro de esa asociaci&#243;n agraria quiero manifestar la incidencia que est&#225; teniendo la conjunci&#243;n de dos nuevos acontecimientos, para los agricultores y ganaderos de nuestra Comarca agr&#237;cola\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2006-12-12T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T09:02:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad\",\"name\":\"AL RESPECTO DE LA CONDICIONALIDAD - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2006-12-12T23:00:00+00:00\",\"dateModified\":\"2017-11-15T09:02:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Como agricultor y miembro de esa asociaci&#243;n agraria quiero manifestar la incidencia que est&#225; teniendo la conjunci&#243;n de dos nuevos acontecimientos, para los agricultores y ganaderos de nuestra Comarca agr&#237;cola\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AL RESPECTO DE LA CONDICIONALIDAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AL RESPECTO DE LA CONDICIONALIDAD - ASAJA Le\u00f3n","description":"Como agricultor y miembro de esa asociaci&#243;n agraria quiero manifestar la incidencia que est&#225; teniendo la conjunci&#243;n de dos nuevos acontecimientos, para los agricultores y ganaderos de nuestra Comarca agr&#237;cola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad","og_locale":"es_ES","og_type":"article","og_title":"AL RESPECTO DE LA CONDICIONALIDAD - ASAJA Le\u00f3n","og_description":"Como agricultor y miembro de esa asociaci&#243;n agraria quiero manifestar la incidencia que est&#225; teniendo la conjunci&#243;n de dos nuevos acontecimientos, para los agricultores y ganaderos de nuestra Comarca agr&#237;cola","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2006-12-12T23:00:00+00:00","article_modified_time":"2017-11-15T09:02:39+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad","name":"AL RESPECTO DE LA CONDICIONALIDAD - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2006-12-12T23:00:00+00:00","dateModified":"2017-11-15T09:02:39+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Como agricultor y miembro de esa asociaci&#243;n agraria quiero manifestar la incidencia que est&#225; teniendo la conjunci&#243;n de dos nuevos acontecimientos, para los agricultores y ganaderos de nuestra Comarca agr&#237;cola","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/al-respecto-de-la-condicionalidad#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"AL RESPECTO DE LA CONDICIONALIDAD"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/848"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=848"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/848\/revisions"}],"predecessor-version":[{"id":1213,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/848\/revisions\/1213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}