{"id":888,"date":"2004-09-23T00:00:00","date_gmt":"2004-09-22T22:00:00","guid":{"rendered":"https:\/\/www.asajacyl.com\/leon\/2004\/09\/23\/las-mentiras-de-la-ministra-narbona\/"},"modified":"2017-11-15T10:03:16","modified_gmt":"2017-11-15T09:03:16","slug":"las-mentiras-de-la-ministra-narbona","status":"publish","type":"post","link":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona","title":{"rendered":"LAS MENTIRAS DE LA MINISTRA NARBONA"},"content":{"rendered":"<h2>Se prodiga la ministra Cristina Narbona por los medios de comunicaci&#243;n haciendo declaraciones sobre su pol&#237;tica hidr&#225;ulica, consistente sobre todo en cuestionar lo hecho por anteriores gobiernos, y en desacreditar el uso de agua para riego como un factor de desarrollo econ&#243;mico y social de amplias zonas de nuestro pa&#237;s.<\/h2>\n<p><b><\/p>\n<p align=\"center\"><font size=\"2\"><\/font><font color=\"#009900\"><font size=\"2\">&#160;L<\/font><font size=\"2\">as mentiras de la ministra Narbona<\/font><\/font><\/p>\n<p><\/b><font color=\"#009900\" size=\"2\"> <\/font><\/p>\n<p align=\"center\"><font size=\"2\">&#160;<\/font><b><font size=\"2\"> <\/font><font size=\"2\">Jos&#233; Antonio Turrado*<\/font><\/b><b><font size=\"2\"> <\/font><\/p>\n<p align=\"justify\"><font size=\"2\">S<\/font><\/p>\n<p><\/b><font size=\"2\">e prodiga la ministra Cristina Narbona por los medios de comunicaci&#243;n haciendo declaraciones sobre su pol&#237;tica hidr&#225;ulica, consistente sobre todo en cuestionar lo hecho por anteriores gobiernos, y en desacreditar el uso de agua para riego como un factor de desarrollo econ&#243;mico y social de amplias zonas de nuestro pa&#237;s. Tiene fijaci&#243;n con los agricultores, a los que acusa de causar incendios, de despilfarrar el agua, y de aprovecharse de los recursos que generosamente le proporciona el Estado de forma gratuita acometiendo costosas y gravosas obras p&#250;blicas. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Defiende la ministra una filosof&#237;a que sustenta una pol&#237;tica contraria a los intereses de los agricultores y ganaderos, una pol&#237;tica contraria a los intereses del medio rural, y contraria al papel del agua como elemento de riqueza y desarrollo integral de zonas desfavorecidas. Porque se olvida la ministra de que en muchas partes de nuestro extenso territorio estamos abandonados a nuestra suerte, no tenemos industrias, no tenemos servicios, y lo &#250;nico que tenemos son algunos recursos naturales que si los explotamos convenientemente nos pueden permitir vivir un poco mejor. En Castilla y Le&#243;n tenemos agua, y el agua tiene muchos destinos, incluido el de regar nuestras tierras, que todos ellos son mejores que mandarla al mar. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Pero en esta ocasi&#243;n no vamos a tratar de convencer a la ministra de que est&#225; equivocada, como equivocado est&#225; todo un Gobierno empe&#241;ado en desaprovechar uno de los recursos m&#225;s importantes que tenemos en Castilla y Le&#243;n. Lo que pretendemos es demostrar a la se&#241;ora Narbona que no es cierto lo que dice sobre la contribuci&#243;n de los usuarios a los costes de las infraestructuras de riego, y que como adem&#225;s ella sabe que lo que dice no es cierto, y lo est&#225; diciendo intencionadamente, pues sencillamente tenemos que llamarle mentirosa. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">La ministra ha sido en sus declaraciones p&#250;blicas clara y contundente en sus afirmaciones, y la &#250;ltima que le conocemos es del martes 21 en la radio p&#250;blica: los usuarios no pagan nada de los costes de las obras hidr&#225;ulicas. Sugerimos a la se&#241;ora ministra que se lea el Real Decreto Legislativo 1\/2001 de 20 de julio por el que se aprueba el texto refundido de la Ley de Aguas. En el art&#237;culo 114 se establece el \u00abcanon de regulaci&#243;n\u00bb y las \u00abtarifas de riego\u00bb, dos conceptos por los que los usuarios del agua, sobre todo los agricultores, pagan al Estado el 50 por ciento del coste de las obras de regulaci&#243;n (pantanos), y de las obras de canalizaci&#243;n del agua, lo que se hace mediante aportaciones del 4 por ciento anual del valor de las inversiones realizadas, debidamente actualizado teniendo en cuenta la amortizaci&#243;n t&#233;cnica de las obras e instalaciones y la depreciaci&#243;n de la moneda. Adem&#225;s, se repercute en su totalidad en los usuarios los costes de explotaci&#243;n y conservaci&#243;n de las obras y los de administraci&#243;n del organismo gestor, -y aqu&#237; se incluye incluso la parte proporcional del salario que cobra el presidente\/a de la Confederaci&#243;n Hidrogr&#225;fica de la cuenca-. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">Est&#225; dentro de las competencias del Gobierno dar una vuelta de tuerca m&#225;s a los agricultores y ganaderos cobrando las infraestructuras hidr&#225;ulicas incluso en su totalidad, y para ello no necesitan tan siquiera escudarse en los principios de la Directiva Marco del Agua publicada en el Bolet&#237;n Oficial de las Comunidades Europeas el 22 de diciembre de 2000. Es competencia de quien gobierna poner impuestos, y lo que pretende la se&#241;ora Narbona no es otra cosa que castigar a los regantes con m&#225;s impuestos. Pero para hacer esta pol&#237;tica de desprecio a los intereses de los agricultores, no es necesario ir de escenario en escenario mintiendo sobre el coste actual del agua de riego. No es elegante medrar en pol&#237;tica a base de desacreditar con mentiras, ya no a la oposici&#243;n pol&#237;tica, que podr&#237;amos entenderlo, sino a todo un colectivo de administrados. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\">El futuro de la agricultura y ganader&#237;a de Castilla y Le&#243;n est&#225; en gran parte en manos del Gobierno socialista. Nos condicionan sus leyes y la defensa que hagan o dejen de hacer de nuestros intereses en el seno de la Uni&#243;n Europea. Y una buena parte de ese futuro se decide en la pol&#237;tica hidr&#225;ulica. Hasta ahora, lo que sabemos es que nos quieren cobrar no el 50 por ciento sino el 100 por 100 de los costes de las infraestructuras, nos quieren suprimir obras previstas en el Plan Hidrol&#243;gico, nos quieren criminalizar como devastadores del medio ambiente, y han empezado por convertir el pantano de Castrovido en un charco de ranas con el argumento de que el tama&#241;o no importa. <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font><i><\/p>\n<p align=\"right\"><font size=\"2\">Le&#243;n, 23 de septiembre de 2004<\/font><\/p>\n<p><\/i><font size=\"2\"> <\/font>\n<\/p>\n<p align=\"justify\"><font size=\"2\"><\/font><b><i><\/p>\n<p><font size=\"2\">&#160; <\/font>\n<\/p>\n<p align=\"right\"><font size=\"2\">*Jos&#233; Antonio Turrado es secretario general de ASAJA de Castilla y Le&#243;n<\/font><\/p>\n<p><\/i><\/b><\/p>\n<p><i><font size=\"2\"> <\/font><\/p>\n<p align=\"right\"><font size=\"2\"><\/font><\/p>\n<p><\/i>&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se prodiga la ministra Cristina Narbona por los medios de comunicaci&#243;n haciendo declaraciones sobre su pol&#237;tica hidr&#225;ulica, consistente sobre todo en cuestionar lo hecho por anteriores gobiernos, y en desacreditar el uso de agua para riego como un factor de desarrollo econ&#243;mico y social de amplias zonas de nuestro pa&#237;s.<\/p>\n","protected":false},"author":3,"featured_media":8174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LAS MENTIRAS DE LA MINISTRA NARBONA - ASAJA Le\u00f3n<\/title>\n<meta name=\"description\" content=\"Se prodiga la ministra Cristina Narbona por los medios de comunicaci&#243;n haciendo declaraciones sobre su pol&#237;tica hidr&#225;ulica, consistente sobre todo en cuestionar lo hecho por anteriores gobiernos, y en desacreditar el uso de agua para riego como un factor de desarrollo econ&#243;mico y social de amplias zonas de nuestro pa&#237;s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LAS MENTIRAS DE LA MINISTRA NARBONA - ASAJA Le\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Se prodiga la ministra Cristina Narbona por los medios de comunicaci&#243;n haciendo declaraciones sobre su pol&#237;tica hidr&#225;ulica, consistente sobre todo en cuestionar lo hecho por anteriores gobiernos, y en desacreditar el uso de agua para riego como un factor de desarrollo econ&#243;mico y social de amplias zonas de nuestro pa&#237;s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona\" \/>\n<meta property=\"og:site_name\" content=\"ASAJA Le\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2004-09-22T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-15T09:03:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona\",\"name\":\"LAS MENTIRAS DE LA MINISTRA NARBONA - ASAJA Le\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"datePublished\":\"2004-09-22T22:00:00+00:00\",\"dateModified\":\"2017-11-15T09:03:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\"},\"description\":\"Se prodiga la ministra Cristina Narbona por los medios de comunicaci&#243;n haciendo declaraciones sobre su pol&#237;tica hidr&#225;ulica, consistente sobre todo en cuestionar lo hecho por anteriores gobiernos, y en desacreditar el uso de agua para riego como un factor de desarrollo econ&#243;mico y social de amplias zonas de nuestro pa&#237;s.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona#primaryimage\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"contentUrl\":\"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Logotipo ASAJA Le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.asajacyl.com\/leon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LAS MENTIRAS DE LA MINISTRA NARBONA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#website\",\"url\":\"https:\/\/www.asajacyl.com\/leon\/\",\"name\":\"ASAJA Le\u00f3n\",\"description\":\"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g\",\"caption\":\"Editor\"},\"url\":\"https:\/\/www.asajacyl.com\/leon\/author\/oscargg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LAS MENTIRAS DE LA MINISTRA NARBONA - ASAJA Le\u00f3n","description":"Se prodiga la ministra Cristina Narbona por los medios de comunicaci&#243;n haciendo declaraciones sobre su pol&#237;tica hidr&#225;ulica, consistente sobre todo en cuestionar lo hecho por anteriores gobiernos, y en desacreditar el uso de agua para riego como un factor de desarrollo econ&#243;mico y social de amplias zonas de nuestro pa&#237;s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona","og_locale":"es_ES","og_type":"article","og_title":"LAS MENTIRAS DE LA MINISTRA NARBONA - ASAJA Le\u00f3n","og_description":"Se prodiga la ministra Cristina Narbona por los medios de comunicaci&#243;n haciendo declaraciones sobre su pol&#237;tica hidr&#225;ulica, consistente sobre todo en cuestionar lo hecho por anteriores gobiernos, y en desacreditar el uso de agua para riego como un factor de desarrollo econ&#243;mico y social de amplias zonas de nuestro pa&#237;s.","og_url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona","og_site_name":"ASAJA Le\u00f3n","article_published_time":"2004-09-22T22:00:00+00:00","article_modified_time":"2017-11-15T09:03:16+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","type":"image\/jpeg"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editor","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona","url":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona","name":"LAS MENTIRAS DE LA MINISTRA NARBONA - ASAJA Le\u00f3n","isPartOf":{"@id":"https:\/\/www.asajacyl.com\/leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona#primaryimage"},"image":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona#primaryimage"},"thumbnailUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","datePublished":"2004-09-22T22:00:00+00:00","dateModified":"2017-11-15T09:03:16+00:00","author":{"@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c"},"description":"Se prodiga la ministra Cristina Narbona por los medios de comunicaci&#243;n haciendo declaraciones sobre su pol&#237;tica hidr&#225;ulica, consistente sobre todo en cuestionar lo hecho por anteriores gobiernos, y en desacreditar el uso de agua para riego como un factor de desarrollo econ&#243;mico y social de amplias zonas de nuestro pa&#237;s.","breadcrumb":{"@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona#primaryimage","url":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","contentUrl":"https:\/\/www.asajacyl.com\/leon\/wp-content\/uploads\/sites\/6\/2017\/11\/im_predefinida_1920x1080.jpg","width":1920,"height":1080,"caption":"Logotipo ASAJA Le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.asajacyl.com\/leon\/asaja-leon-informa\/las-mentiras-de-la-ministra-narbona#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.asajacyl.com\/leon\/"},{"@type":"ListItem","position":2,"name":"LAS MENTIRAS DE LA MINISTRA NARBONA"}]},{"@type":"WebSite","@id":"https:\/\/www.asajacyl.com\/leon\/#website","url":"https:\/\/www.asajacyl.com\/leon\/","name":"ASAJA Le\u00f3n","description":"Otro sitio m\u00e1s de Provincias ASAJA Castilla y Le\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asajacyl.com\/leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/7e884476cee132331142e8ac9689f20c","name":"Editor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.asajacyl.com\/leon\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2ef43c165669686cfcfb0e1ffa59869?s=96&d=mm&r=g","caption":"Editor"},"url":"https:\/\/www.asajacyl.com\/leon\/author\/oscargg"}]}},"_links":{"self":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/888"}],"collection":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/comments?post=888"}],"version-history":[{"count":1,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/888\/revisions"}],"predecessor-version":[{"id":1253,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/posts\/888\/revisions\/1253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media\/8174"}],"wp:attachment":[{"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/media?parent=888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/categories?post=888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asajacyl.com\/leon\/wp-json\/wp\/v2\/tags?post=888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}